{"id":49044,"date":"2023-02-20T03:03:37","date_gmt":"2023-02-20T06:03:37","guid":{"rendered":"https:\/\/www.mundoacuicola.cl\/new\/?p=49044"},"modified":"2023-02-20T11:52:23","modified_gmt":"2023-02-20T14:52:23","slug":"espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada","status":"publish","type":"post","link":"https:\/\/www.mundoacuicola.cl\/new\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\/","title":{"rendered":"Espa\u00f1a: IU-ECOAQUA culmina proyecto para reducir anomal\u00edas esquel\u00e9ticas durante el cultivo de dorada"},"content":{"rendered":"<p>El\u00a0<a href=\"http:\/\/ecoaqua.ulpgc.es\/\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=http:\/\/ecoaqua.ulpgc.es\/&amp;source=gmail&amp;ust=1676939893950000&amp;usg=AOvVaw31UeT3sXc9Euyrl4iADd-C\">Instituto Universitario de Investigaci\u00f3n en Acuicultura Sostenible y Ecosistemas Marinos (IU-ECOAQUA)<\/a>\u00a0de la Universidad de Las Palmas de Gran Canaria (ULPGC), ha presentado los resultados m\u00e1s relevantes de cuatro j\u00f3venes investigadores que han cursado sus estudios de doctorado en el marco de un ambicioso proyecto europeo denominado\u00a0<a href=\"https:\/\/www.gigabiomedaqu.uliege.be\/cms\/c_4430156\/en\/gigabiomedaqu\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.gigabiomedaqu.uliege.be\/cms\/c_4430156\/en\/gigabiomedaqu&amp;source=gmail&amp;ust=1676939893950000&amp;usg=AOvVaw2C1V3rl1rLeIG6hmM7PeOJ\">BiomedAqu<\/a>, que ha culminado a finales de enero tras tres a\u00f1os de investigaciones en todo el mundo combinando la biolog\u00eda esquel\u00e9tica de especies acu\u00edcolas con modelos biom\u00e9dicos y humanos.<\/p>\n<p>En las investigaciones de los alumnos de la ULPGC se han determinado las preferencias del consumidor en los productos acu\u00edcolas, as\u00ed como los impactos econ\u00f3micos de anomal\u00edas esquel\u00e9ticas severas en granjas mediterr\u00e1neas de dorada y lubina, que podr\u00edan llegar a casi 90 millones de euros anuales, y las condiciones \u00f3ptimas de cultivo de la dorada para reducir la prevalencia de tales anomal\u00edas determinando que la densidad y el volumen del citado cultivo son fundamentales en el desarrollo de deformidades en esta especie.<\/p>\n<p>Entre los hallazgos de estos cient\u00edficos, que se han integrado en el Grupo de Investigaci\u00f3n en Acuicultura (GIA) de ECOAQUA, destaca la demostraci\u00f3n de los niveles seguros para la suplementaci\u00f3n de vitamina D y de los niveles \u00f3ptimos para la vitamina K, para la suplementaci\u00f3n de minerales como el selenio, el cobre, el zinc o el manganeso en los piensos utilizados en las dietas de las larvas de dorada (Sparus aurata) y, en el caso de los juveniles, del zinc y las vitaminas K y D.<\/p>\n<p>Las alteraciones de la expresi\u00f3n de biomarcadores \u00f3seos y reguladores del calcio causados por desajustes de las vitaminas D y K o los riesgos percibidos y las pr\u00e1cticas de gesti\u00f3n de riesgos de las empresas acu\u00edcolas europeas son otros de los resultados obtenidos por los cuatro investigadores que han cursado sus t\u00edtulos de doctorado en Acuicultura Sostenible y Ecosistemas Marinos (ACUISEMAR) en la ULPGC en el marco del proyecto BiomedAqu: Javier Castillo, originario de Colombia; Zachary Dellacqua, estadounidense; Yiyen Tseng, de Taiwan, y Sivagurunathan Ulaganathan, nacido en la India.<\/p>\n<p>Los j\u00f3venes investigadores han trabajado bajo la direcci\u00f3n de Mar\u00eda Soledad Izquierdo, Daniel Montero V\u00edtores y David Dom\u00ednguez Montesdeoca, del Grupo de Investigaci\u00f3n en Acuicultura (GIA) del IU-ECOAQUA, as\u00ed como del catedr\u00e1tico de An\u00e1lisis Econ\u00f3mico Aplicado de la ULPGC, Juan Carlos Mart\u00edn Hern\u00e1ndez, integrado en el comit\u00e9 cient\u00edfico de BiomedAqu.<\/p>\n<h2><strong>Un proyecto que ha implicado a 15 investigadores durante 3 a\u00f1os<\/strong><\/h2>\n<p>En BiomedAqu se han implicado investigadores de todo el mundo durante 36 meses, algo que ha servido para construir una experiencia innovadora al combinar la investigaci\u00f3n en biolog\u00eda esquel\u00e9tica de especies de peces acu\u00edcolas con modelos biom\u00e9dicos y humanos. Y es que\u00a0estos avances sobre las anomal\u00edas esquel\u00e9ticas en peces como la dorada pueden ser trasladables en un futuro al estudio de las anomal\u00edas esquel\u00e9ticas en humanos, utilizando peces como modelos de experimentaci\u00f3n.<\/p>\n<p>Estas investigaciones podr\u00edan tener relaci\u00f3n con avances en patolog\u00edas como la osteoporosis y la osteoartritis, enfermedades cr\u00f3nicas, degenerativas, que cursan con dolor y limitaci\u00f3n funcional progresiva.<\/p>\n<p>Aunque no es muy conocido, el progreso en muchas \u00e1reas de investigaci\u00f3n biom\u00e9dica se basa en el uso de varias especies de peces como modelo, por la alta similitud entre su genoma y el del ser humano. Las caracter\u00edsticas biol\u00f3gicas de estos peces, que no envejecen, los convierten en modelos id\u00f3neos para estudiar enfermedades como Alzheimer, Parkinson, c\u00e1ncer o deficiencias card\u00edacas; as\u00ed como de coballas en el campo de la medicina regenerativa.<\/p>\n<p>Con un presupuesto de casi 665.000 euros, el proyecto BiomedAqu cuenta con financiaci\u00f3n de la Uni\u00f3n Europea (UE) y se enmarca en las acciones Marie Sklodowska-Curie Innovative Training Network (MCSA-ITN), un programa de contratos predoctorales de gran prestigio internacional cuya llegada a la ULPGC y al IU-ECOAQUA suponen todo un hito en el campo de la cooperaci\u00f3n universitaria.<\/p>\n<p>El\u00a0IU-ECOAQUA de la ULPGC\u00a0ha formado parte del total de 18 instituciones, entre universidades, centros de investigaci\u00f3n, asociaciones de granjas de acuicultura y productores de piensos, adem\u00e1s de hospitales y empresas de biotecnolog\u00eda, que han conformado el consorcio internacional a cargo del proyecto.<\/p>\n<p>Se trata de una iniciativa a trav\u00e9s de la cual se han formado 15 j\u00f3venes investigadores (siete mujeres y ocho hombres) de 10 nacionalidades distintas, que han obtenido sus t\u00edtulos de doctores en las universidades asociadas al proyecto, tras tener la oportunidad de completar estancias de investigaci\u00f3n en diferentes instituciones del consorcio.<\/p>\n<p>Los resultados generados en la ULPGC en el transcurso del proyecto BiomedAqu, han sido compartidos no solo entre las instituciones participantes a trav\u00e9s de talleres y encuentros, sino se ha trasladado a un p\u00fablico m\u00e1s amplio, que incluye miembros de la industria, investigadores y estudiantes.<\/p>\n<p>La jornada final, en la que participaron en formato online m\u00e1s de 30 investigadores internacionales de todos los sectores de la acuicultura, cont\u00f3 con la participaci\u00f3n de David Dom\u00ednguez, Sivagurunathan Ulaganathan, Javier Cantillo, Yiyen Tseng y Zachary Dellacqua, que dieron cuenta de los resultados m\u00e1s relevantes, anteriormente relatados, logrados a lo largo de las investigaciones fruto de sus doctorados cursados en el marco de la iniciativa europea.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El\u00a0Instituto Universitario de Investigaci\u00f3n en Acuicultura Sostenible y Ecosistemas Marinos (IU-ECOAQUA)\u00a0de la Universidad de Las&#8230;<\/p>\n","protected":false},"author":8,"featured_media":49045,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"class_list":["post-49044","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acuicultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Espa\u00f1a: IU-ECOAQUA culmina proyecto para reducir anomal\u00edas esquel\u00e9ticas durante el cultivo de dorada - Mundoacuicola<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoacuicola.cl\/new\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Espa\u00f1a: IU-ECOAQUA culmina proyecto para reducir anomal\u00edas esquel\u00e9ticas durante el cultivo de dorada - Mundoacuicola\" \/>\n<meta property=\"og:description\" content=\"El\u00a0Instituto Universitario de Investigaci\u00f3n en Acuicultura Sostenible y Ecosistemas Marinos (IU-ECOAQUA)\u00a0de la Universidad de Las...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoacuicola.cl\/new\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoacuicola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.acuicola\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-20T06:03:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-20T14:52:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/02\/ProyectoBiomedAqu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ricardo Alvarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:site\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Alvarez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\\\/\"},\"author\":{\"name\":\"Ricardo Alvarez\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\"},\"headline\":\"Espa\u00f1a: IU-ECOAQUA culmina proyecto para reducir anomal\u00edas esquel\u00e9ticas durante el cultivo de dorada\",\"datePublished\":\"2023-02-20T06:03:37+00:00\",\"dateModified\":\"2023-02-20T14:52:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\\\/\"},\"wordCount\":916,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/ProyectoBiomedAqu.jpg\",\"articleSection\":[\"Acuicultura\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\\\/\",\"name\":\"Espa\u00f1a: IU-ECOAQUA culmina proyecto para reducir anomal\u00edas esquel\u00e9ticas durante el cultivo de dorada - Mundoacuicola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/ProyectoBiomedAqu.jpg\",\"datePublished\":\"2023-02-20T06:03:37+00:00\",\"dateModified\":\"2023-02-20T14:52:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/ProyectoBiomedAqu.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/ProyectoBiomedAqu.jpg\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Espa\u00f1a: IU-ECOAQUA culmina proyecto para reducir anomal\u00edas esquel\u00e9ticas durante el cultivo de dorada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"name\":\"Mundoacuicola\",\"description\":\"Revista de Acuicultura.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\",\"name\":\"Mundoacuicola\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"width\":1252,\"height\":296,\"caption\":\"Mundoacuicola\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.acuicola\\\/\",\"https:\\\/\\\/x.com\\\/mundoacuicola\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-acuicola\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\",\"name\":\"Ricardo Alvarez\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/author\\\/ricardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Espa\u00f1a: IU-ECOAQUA culmina proyecto para reducir anomal\u00edas esquel\u00e9ticas durante el cultivo de dorada - Mundoacuicola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoacuicola.cl\/new\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\/","og_locale":"es_ES","og_type":"article","og_title":"Espa\u00f1a: IU-ECOAQUA culmina proyecto para reducir anomal\u00edas esquel\u00e9ticas durante el cultivo de dorada - Mundoacuicola","og_description":"El\u00a0Instituto Universitario de Investigaci\u00f3n en Acuicultura Sostenible y Ecosistemas Marinos (IU-ECOAQUA)\u00a0de la Universidad de Las...","og_url":"https:\/\/www.mundoacuicola.cl\/new\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\/","og_site_name":"Mundoacuicola","article_publisher":"https:\/\/www.facebook.com\/mundo.acuicola\/","article_published_time":"2023-02-20T06:03:37+00:00","article_modified_time":"2023-02-20T14:52:23+00:00","og_image":[{"width":750,"height":400,"url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/02\/ProyectoBiomedAqu.jpg","type":"image\/jpeg"}],"author":"Ricardo Alvarez","twitter_card":"summary_large_image","twitter_creator":"@mundoacuicola","twitter_site":"@mundoacuicola","twitter_misc":{"Escrito por":"Ricardo Alvarez","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoacuicola.cl\/new\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\/#article","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\/"},"author":{"name":"Ricardo Alvarez","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd"},"headline":"Espa\u00f1a: IU-ECOAQUA culmina proyecto para reducir anomal\u00edas esquel\u00e9ticas durante el cultivo de dorada","datePublished":"2023-02-20T06:03:37+00:00","dateModified":"2023-02-20T14:52:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\/"},"wordCount":916,"publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/02\/ProyectoBiomedAqu.jpg","articleSection":["Acuicultura"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoacuicola.cl\/new\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\/","url":"https:\/\/www.mundoacuicola.cl\/new\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\/","name":"Espa\u00f1a: IU-ECOAQUA culmina proyecto para reducir anomal\u00edas esquel\u00e9ticas durante el cultivo de dorada - Mundoacuicola","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/02\/ProyectoBiomedAqu.jpg","datePublished":"2023-02-20T06:03:37+00:00","dateModified":"2023-02-20T14:52:23+00:00","breadcrumb":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoacuicola.cl\/new\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\/#primaryimage","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/02\/ProyectoBiomedAqu.jpg","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/02\/ProyectoBiomedAqu.jpg","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoacuicola.cl\/new\/espana-iu-ecoaqua-culmina-proyecto-para-reducir-anomalias-esqueleticas-durante-el-cultivo-de-dorada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoacuicola.cl\/new\/"},{"@type":"ListItem","position":2,"name":"Espa\u00f1a: IU-ECOAQUA culmina proyecto para reducir anomal\u00edas esquel\u00e9ticas durante el cultivo de dorada"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoacuicola.cl\/new\/#website","url":"https:\/\/www.mundoacuicola.cl\/new\/","name":"Mundoacuicola","description":"Revista de Acuicultura.","publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoacuicola.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization","name":"Mundoacuicola","url":"https:\/\/www.mundoacuicola.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","width":1252,"height":296,"caption":"Mundoacuicola"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.acuicola\/","https:\/\/x.com\/mundoacuicola","https:\/\/www.linkedin.com\/in\/mundo-acuicola"]},{"@type":"Person","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd","name":"Ricardo Alvarez","url":"https:\/\/www.mundoacuicola.cl\/new\/author\/ricardo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/49044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/comments?post=49044"}],"version-history":[{"count":0,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/49044\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media\/49045"}],"wp:attachment":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media?parent=49044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/categories?post=49044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/tags?post=49044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}