{"id":50488,"date":"2023-04-06T09:00:06","date_gmt":"2023-04-06T12:00:06","guid":{"rendered":"https:\/\/www.mundoacuicola.cl\/new\/?p=50488"},"modified":"2023-04-07T11:50:10","modified_gmt":"2023-04-07T14:50:10","slug":"deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales","status":"publish","type":"post","link":"https:\/\/www.mundoacuicola.cl\/new\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\/","title":{"rendered":"Deloitte expuso al cl\u00faster salmonero los desaf\u00edos en ESG, ciberseguridad y nuevos acuerdos comerciales"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.mundoacuicola.cl\/medios\/?url_camp=192\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.mundoacuicola.cl\/medios\/?camp=192\" alt=\"\" width=\"300\" height=\"250\" \/><\/a><\/span>La tarde del jueves 05 de abril, en el Hotel Caba\u00f1a del Lago de Puerto Varas, tuvo lugar el seminario \u00abNadando contra la corriente, retos para la industria salmonera\u00bb, instancia organizada por Deloitte y que cont\u00f3 con el apoyo de SalmonChile y del Consejo del Salm\u00f3n.<\/p>\n<p>\u00abCuando pensamos en este seminario, contactamos tanto a SalmonChile como al Consejo del Salm\u00f3n, y les consultamos a estos gremios salmonicultores qu\u00e9 temas les parec\u00edan importantes que les presentemos, trabajando de forma colaborativa. Y es que Deloitte, tal como las empresas del sector salmonero, somos actores de inter\u00e9s p\u00fablico. Cada intervenci\u00f3n e inversi\u00f3n que hacemos tienen un impacto en materia de sostenibilidad. Por lo tanto, queremos que la industria salmonera vea a Deloitte como un equipo con el cual trabajar diversos temas, de manera de generar valor para las empresas y el pa\u00eds\u00bb, coment\u00f3 durante la apertura del seminario Jackie Plass, Chief Purpose Officer Partner de Deloitte.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-50501 alignleft\" src=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/04\/DeloitteSalmonera-1-533x400.jpg\" alt=\"\" width=\"407\" height=\"332\" \/><\/p>\n<p>\u00abDesde hace un tiempo hemos tomado la decisi\u00f3n de focalizarnos en la salmonicultura, estructurado nuestra compa\u00f1\u00eda de tal manera que podamos prestar atenci\u00f3n a esta industria de manera particular. Es as\u00ed como hemos elaborado un equipo de alrededor de 8 socios que, dentro de su quehacer, tienen la misi\u00f3n de actualizarse en temas importantes para la industria salmonera: impuestos, temas de franquicias de investigaci\u00f3n y desarrollo, I+D, entre otros\u00bb, coment\u00f3 Rolf Lagos, L\u00edder del sector salmonero Partner de Deloitte.<\/p>\n<p>\u00abEste a\u00f1o nos queda avanzar en m\u00e1s temas, raz\u00f3n por la cual tenemos a dos gerentes radicados en la zona: un socio dedicado a temas de impuestos, servicios de outsourcing, auditoria y otro a consultor\u00eda\u00bb, agreg\u00f3.<\/p>\n<p>\u00abCon todo, estamos mirando a industria salmonera con la real importancia que esta tiene. Dentro de este foco estamos armando una mesa de trabajo que ya lleva alrededor de dos meses, colaborando con socios de Deloitte Noruega, de manera de poder traer aquellas pr\u00e1cticas que sean novedosas en temas de innovaci\u00f3n y servicios. La idea es repetir este tipo de seminarios, trayendo novedades y temas de relevancia para poder trabajar y crecer en conjunto\u00bb, enfatiz\u00f3 Lagos.<\/p>\n<h2>Tendencias en ESG, Ciberseguridad y acuerdos comerciales<\/h2>\n<p><img decoding=\"async\" class=\"wp-image-50506 alignleft\" src=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/04\/DeloitteSalmonera4-533x400.jpg\" alt=\"\" width=\"403\" height=\"322\" \/>La exposici\u00f3n del primer t\u00f3pico del seminario estuvo a cargo de Alejandra Bernal y Germ\u00e1n Zapata, expertos de Deloitte en ESG y SAP respectivamente, quienes abordaron la conexi\u00f3n entre ambos conceptos.<\/p>\n<p>As\u00ed, Bernal comenz\u00f3 aclarando que\u00a0\u00abel concepto ESG es un concepto din\u00e1mico, que abarca los grandes factores ambientales, sociales y de gobernanza, que no solamente viene a establecer criterios en los que hay que basar las estrategias de sostenibilidad, sino tambi\u00e9n viene a ser un lenguaje de las finanzas sostenibles, es decir, de c\u00f3mo las empresas vinculan sus estrategias de sostenibilidad hacia su estrategia de negocio\u00bb, para luego abordar los principales desaf\u00edos en ESG.<\/p>\n<p>\u00abAbordar el cambio clim\u00e1tico es un desaf\u00edo hoy en d\u00eda porque no solamente es un tema de medici\u00f3n, sino tambi\u00e9n de seguimiento, y muchas empresas no tienen los medios para hacer seguimientos o, seg\u00fan las regulaciones, tiene que ser de manera externa. Otro de los desaf\u00edos en ESG es el aumento de la presi\u00f3n p\u00fablica y pol\u00edtica, la tecnolog\u00eda y los datos aceleran el dialogo. En el fondo, sabemos que este gran volumen de datos que tienen que ver con lo ambiental, social y la gobernanza muchas se maneja en una hoja de c\u00e1lculo. Luego podemos hablar de la estandarizaci\u00f3n, que busca no solo la regulaci\u00f3n correcta de estos criterios, sino tambi\u00e9n la interpretaci\u00f3n de los datos. La idea que estos datos se traduzcan en beneficios para las empresas\u00bb, detall\u00f3 Bernal.<\/p>\n<p>En el tercer \u00edtem del seminario, Mar\u00eda Luisa Acu\u00f1a, Experta en ciberseguridad, quien expuso sobre las tendencias y estrategias de ciberseguridad.<\/p>\n<p>\u00abHoy nos convoca este seminario que trabajamos en conjunto con la industria salmonera principalmente para transmitir uno de los conceptos que nos importa que es la ciberseguridad porque es un sector en general Industrial, y observamos que el a\u00f1o pasado el sector industrial fue uno de los sectores que tuvo m\u00e1s ataques, por lo que es una preocupaci\u00f3n que debe llamar la atenci\u00f3n de la salmonicultura\u00bb, coment\u00f3 Acu\u00f1a.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-50505 alignleft\" src=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/04\/DeloitteSalmonera3-533x400.jpg\" alt=\"\" width=\"451\" height=\"339\" srcset=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/04\/DeloitteSalmonera3-533x400.jpg 533w, https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/04\/DeloitteSalmonera3-500x375.jpg 500w, https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/04\/DeloitteSalmonera3-177x133.jpg 177w, https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/04\/DeloitteSalmonera3-768x576.jpg 768w, https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/04\/DeloitteSalmonera3-1536x1152.jpg 1536w, https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/04\/DeloitteSalmonera3.jpg 2048w\" sizes=\"(max-width: 451px) 100vw, 451px\" \/>\u00abLos niveles de madurez son variados en la industria salmonera, algunas han dado pasos m\u00e1s bien t\u00edmidos en t\u00e9rminos de c\u00f3mo subirse a la tendencia de la ciberseguridad, y ah\u00ed la recomendaci\u00f3n es que lo consideren dentro sus definiciones estrat\u00e9gicas para que le den la importancia que merece, pues no queremos que la industria se vea afectada por alg\u00fan ataque de ciberseguridad, por qu\u00e9 principalmente su afectaci\u00f3n va a tener impacto en la disponibilidad de los servicios y la paralizaci\u00f3n de faenas\u00bb, a\u00f1adi\u00f3.<\/p>\n<p>Finalmente, el cierre de la actividad estuvo a cargo de Rodrigo Y\u00e1\u00f1ez, L\u00edder de Comercio Exterior e Inversiones de Deloitte, quien realiz\u00f3 un an\u00e1lisis sobre las rebajas arancelarias; procedimientos aduaneros; y regulaciones contenidas en los acuerdos comerciales\u00a0 CPTPP11 -recientemente entrado en vigencia-, y la Modernizaci\u00f3n del Acuerdo con la Uni\u00f3n Europea que actualmente se encuentra en desarrollo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-50504 \" src=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/04\/DeloitteSalmonera1-533x400.jpg\" alt=\"\" width=\"409\" height=\"278\" \/>\u00abEn estos \u00faltimos 30 a\u00f1os, con 32 acuerdos en vigor, es importante no perder la visi\u00f3n sobre la realidad del comercio internacional. Con el CPTPP y la Modernizaci\u00f3n del Acuerdo con la Uni\u00f3n Europea, en t\u00e9rminos de oportunidades arancelarias, regulaciones y de facilitaci\u00f3n de comercio, lo que buscamos es que estos acuerdos sean tambi\u00e9n catalizador de la industria, pero al mismo tiempo, generar una mayor conciencia de los instrumentos que tiene la industria para mitigar riesgos, que puedan afectar\u00a0 su desempe\u00f1o, como son los desaf\u00edos de la sostenibilidad y el cambio clim\u00e1tico\u00bb, resalt\u00f3 Y\u00e1\u00f1ez.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Compa\u00f1\u00eda present\u00f3 el seminario \u00abNadando contra la corriente, retos para la industria salmonera\u00bb, con el apoyo de SalmonChile y del Consejo del Salm\u00f3n.<\/p>\n","protected":false},"author":8,"featured_media":50489,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[16867,143,16869,5625,3138,10256,2907,16868,6834,3964],"class_list":["post-50488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salmonicultura","tag-acuerdos-comerciales","tag-acuicultura","tag-ciberseguridad","tag-consejo-del-salmon","tag-deloitte","tag-esg","tag-industria-salmonera","tag-modernizacion-del-acuerdo-con-la-ue","tag-salmon-chile","tag-tpp11"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Deloitte expuso al cl\u00faster salmonero los desaf\u00edos en ESG, ciberseguridad y nuevos acuerdos comerciales - Mundoacuicola<\/title>\n<meta name=\"description\" content=\"Present\u00f3 el seminario &quot;Nadando contra la corriente, retos para la industria salmonera&quot;, con el apoyo de SalmonChile y del Consejo del Salm\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoacuicola.cl\/new\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deloitte expuso al cl\u00faster salmonero los desaf\u00edos en ESG, ciberseguridad y nuevos acuerdos comerciales - Mundoacuicola\" \/>\n<meta property=\"og:description\" content=\"Present\u00f3 el seminario &quot;Nadando contra la corriente, retos para la industria salmonera&quot;, con el apoyo de SalmonChile y del Consejo del Salm\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoacuicola.cl\/new\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoacuicola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.acuicola\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-06T12:00:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-07T14:50:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/04\/DeloitteSalmonera.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ricardo Alvarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:site\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Alvarez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\\\/\"},\"author\":{\"name\":\"Ricardo Alvarez\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\"},\"headline\":\"Deloitte expuso al cl\u00faster salmonero los desaf\u00edos en ESG, ciberseguridad y nuevos acuerdos comerciales\",\"datePublished\":\"2023-04-06T12:00:06+00:00\",\"dateModified\":\"2023-04-07T14:50:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\\\/\"},\"wordCount\":1004,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/DeloitteSalmonera.jpg\",\"keywords\":[\"Acuerdos comerciales\",\"Acuicultura\",\"Ciberseguridad\",\"Consejo del Salm\u00f3n\",\"Deloitte\",\"ESG\",\"Industria salmonera\",\"Modernizaci\u00f3n del Acuerdo con la UE\",\"Salmon Chile\",\"TPP11\"],\"articleSection\":[\"Salmonicultura\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\\\/\",\"name\":\"Deloitte expuso al cl\u00faster salmonero los desaf\u00edos en ESG, ciberseguridad y nuevos acuerdos comerciales - Mundoacuicola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/DeloitteSalmonera.jpg\",\"datePublished\":\"2023-04-06T12:00:06+00:00\",\"dateModified\":\"2023-04-07T14:50:10+00:00\",\"description\":\"Present\u00f3 el seminario \\\"Nadando contra la corriente, retos para la industria salmonera\\\", con el apoyo de SalmonChile y del Consejo del Salm\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/DeloitteSalmonera.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/DeloitteSalmonera.jpg\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deloitte expuso al cl\u00faster salmonero los desaf\u00edos en ESG, ciberseguridad y nuevos acuerdos comerciales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"name\":\"Mundoacuicola\",\"description\":\"Revista de Acuicultura.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\",\"name\":\"Mundoacuicola\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"width\":1252,\"height\":296,\"caption\":\"Mundoacuicola\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.acuicola\\\/\",\"https:\\\/\\\/x.com\\\/mundoacuicola\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-acuicola\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\",\"name\":\"Ricardo Alvarez\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/author\\\/ricardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deloitte expuso al cl\u00faster salmonero los desaf\u00edos en ESG, ciberseguridad y nuevos acuerdos comerciales - Mundoacuicola","description":"Present\u00f3 el seminario \"Nadando contra la corriente, retos para la industria salmonera\", con el apoyo de SalmonChile y del Consejo del Salm\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoacuicola.cl\/new\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\/","og_locale":"es_ES","og_type":"article","og_title":"Deloitte expuso al cl\u00faster salmonero los desaf\u00edos en ESG, ciberseguridad y nuevos acuerdos comerciales - Mundoacuicola","og_description":"Present\u00f3 el seminario \"Nadando contra la corriente, retos para la industria salmonera\", con el apoyo de SalmonChile y del Consejo del Salm\u00f3n.","og_url":"https:\/\/www.mundoacuicola.cl\/new\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\/","og_site_name":"Mundoacuicola","article_publisher":"https:\/\/www.facebook.com\/mundo.acuicola\/","article_published_time":"2023-04-06T12:00:06+00:00","article_modified_time":"2023-04-07T14:50:10+00:00","og_image":[{"width":750,"height":400,"url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/04\/DeloitteSalmonera.jpg","type":"image\/jpeg"}],"author":"Ricardo Alvarez","twitter_card":"summary_large_image","twitter_creator":"@mundoacuicola","twitter_site":"@mundoacuicola","twitter_misc":{"Escrito por":"Ricardo Alvarez","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoacuicola.cl\/new\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\/#article","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\/"},"author":{"name":"Ricardo Alvarez","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd"},"headline":"Deloitte expuso al cl\u00faster salmonero los desaf\u00edos en ESG, ciberseguridad y nuevos acuerdos comerciales","datePublished":"2023-04-06T12:00:06+00:00","dateModified":"2023-04-07T14:50:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\/"},"wordCount":1004,"publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/04\/DeloitteSalmonera.jpg","keywords":["Acuerdos comerciales","Acuicultura","Ciberseguridad","Consejo del Salm\u00f3n","Deloitte","ESG","Industria salmonera","Modernizaci\u00f3n del Acuerdo con la UE","Salmon Chile","TPP11"],"articleSection":["Salmonicultura"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoacuicola.cl\/new\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\/","url":"https:\/\/www.mundoacuicola.cl\/new\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\/","name":"Deloitte expuso al cl\u00faster salmonero los desaf\u00edos en ESG, ciberseguridad y nuevos acuerdos comerciales - Mundoacuicola","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/04\/DeloitteSalmonera.jpg","datePublished":"2023-04-06T12:00:06+00:00","dateModified":"2023-04-07T14:50:10+00:00","description":"Present\u00f3 el seminario \"Nadando contra la corriente, retos para la industria salmonera\", con el apoyo de SalmonChile y del Consejo del Salm\u00f3n.","breadcrumb":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoacuicola.cl\/new\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\/#primaryimage","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/04\/DeloitteSalmonera.jpg","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/04\/DeloitteSalmonera.jpg","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoacuicola.cl\/new\/deloitte-presento-al-cluster-salmonero-los-desafios-en-esg-ciberseguridad-y-nuevos-acuerdos-comerciales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoacuicola.cl\/new\/"},{"@type":"ListItem","position":2,"name":"Deloitte expuso al cl\u00faster salmonero los desaf\u00edos en ESG, ciberseguridad y nuevos acuerdos comerciales"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoacuicola.cl\/new\/#website","url":"https:\/\/www.mundoacuicola.cl\/new\/","name":"Mundoacuicola","description":"Revista de Acuicultura.","publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoacuicola.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization","name":"Mundoacuicola","url":"https:\/\/www.mundoacuicola.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","width":1252,"height":296,"caption":"Mundoacuicola"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.acuicola\/","https:\/\/x.com\/mundoacuicola","https:\/\/www.linkedin.com\/in\/mundo-acuicola"]},{"@type":"Person","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd","name":"Ricardo Alvarez","url":"https:\/\/www.mundoacuicola.cl\/new\/author\/ricardo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/50488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/comments?post=50488"}],"version-history":[{"count":0,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/50488\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media\/50489"}],"wp:attachment":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media?parent=50488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/categories?post=50488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/tags?post=50488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}