{"id":51634,"date":"2023-05-11T05:08:28","date_gmt":"2023-05-11T08:08:28","guid":{"rendered":"https:\/\/www.mundoacuicola.cl\/new\/?p=51634"},"modified":"2023-05-12T09:18:24","modified_gmt":"2023-05-12T12:18:24","slug":"con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen","status":"publish","type":"post","link":"https:\/\/www.mundoacuicola.cl\/new\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\/","title":{"rendered":"Con \u00e9xito AquaChile organiz\u00f3 feria de emprendedores y proveedores en Ays\u00e9n"},"content":{"rendered":"<p style=\"font-weight: 400;\"><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.mundoacuicola.cl\/medios\/?url_camp=26\" target=\"_blank\" rel=\"https:\/\/www.mundoacuicola.cl\/medios\/?url_camp=26 noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.mundoacuicola.cl\/medios\/?camp=26\" alt=\"\" width=\"300\" height=\"250\" \/><\/a><\/span>Oportunidades, reuniones, y m\u00e1s de doscientas conversaciones uno a uno, hubo este martes en el polideportivo de Puerto Ays\u00e9n durante\u00a0la feria para proveedores y emprendedores que organiz\u00f3 AquaChile. El objetivo era generar puntos de encuentro, que nacieran nuevos proveedores para la empresa y ponerle rostro y cari\u00f1o a algunos de los m\u00e1s de 2.900 proveedores que tiene la compa\u00f1\u00eda en el pa\u00eds, y as\u00ed contribuir al desarrollo de m\u00e1s prestadores de servicios locales.<\/p>\n<p>En la ma\u00f1ana, los m\u00e1s de 600 asistentes estuvieron conversando con ejecutivos de la compa\u00f1\u00eda en los distintos stands de \u00e1reas como producci\u00f3n, administraci\u00f3n, industrial, servicios a la producci\u00f3n y asesor\u00edas legales, entre otros. Ah\u00ed, emprendedores locales pudieron conocer de la mano de los ejecutivos de la compa\u00f1\u00eda las necesidades locales de AquaChile y conversar sobre el futuro y oportunidades de cooperaci\u00f3n. Tambi\u00e9n asistieron estudiantes de la zona, tanto del liceo t\u00e9cnico como de universidades, quienes pudieron conocer sobre las oportunidades laborales que brinda la empresa.<\/p>\n<p>Durante la tarde la actividad estuvo abierta a toda la comunidad de Ays\u00e9n, quienes oyeron con gran atenci\u00f3n la charla motivacional de Amaro G\u00f3mez-Pablos. Luego hubo una entretenida conversaci\u00f3n entre Mauricio Pinilla y Harold Mayne-Nicholls, quienes lanzaron balones de f\u00fatbol hacia el p\u00fablico. A eso de las 4 de la tarde, el polideportivo tuvo su momento de lleno, con risas y carcajadas con el show del artista y humorista chileno Stefan Kramer.<\/p>\n<p>\u201cTenemos un gran compromiso con Ays\u00e9n, con una trayectoria de m\u00e1s de treinta a\u00f1os en esta regi\u00f3n y hoy estamos muy contentos con la gran participaci\u00f3n de asistentes que tuvo nuestra feria. El balance es muy positivo, ya que pudimos conversar y orientar a muchas personas que quieren sacar adelante sus negocios. Estamos convencidos que juntos podemos lograr m\u00e1s oportunidades y avanzar en pos del desarrollo de la zona\u201d, afirm\u00f3 Sady Delgado, gerente general de AquaChile.<\/p>\n<p>Katia Inostroza, presidenta de Acuiprov y presidenta del PTI entre Fiordos y canales de Ays\u00e9n, coment\u00f3: \u201cLa instancia me pareci\u00f3 absolutamente destacable y recomendada. Es tan bueno ver que existe una comunidad acu\u00edcola presente en Ays\u00e9n, que somos los proveedores y la comunidad en general la que se vincula. Nada m\u00e1s que felicitar a AquaChile, que estas instancias se repitan. Fue todo un \u00e9xito\u201d<\/p>\n<p>El delegado presidencial de la provincia de Ays\u00e9n, Jorge D\u00edaz, afirm\u00f3: \u201cCreo que es un gran aporte (la feria) sobre todo para la gente joven que quiere emprender y buscar independencia econ\u00f3mica en una provincia y una ciudad donde m\u00e1s de un tercio de la econom\u00eda regional sale de este territorio, donde el sector acu\u00edcola y pesquero es muy importante para el desarrollo de esta regi\u00f3n. Por lo tanto, el hecho de que ustedes incentiven el desarrollo de las personas que est\u00e1n vinculadas con esta industria es bueno para el desarrollo de la gente de Ays\u00e9n\u201d.<\/p>\n<p>A juicio del Seremi de Econom\u00eda, Felipe Rojas, \u201cla regi\u00f3n de Ays\u00e9n hist\u00f3ricamente ha funcionado y se ha vinculado al sector alimentos, primero la ganader\u00eda, actualmente la fruticultura, pero particularmente en los \u00faltimos a\u00f1os con la acuicultura y la producci\u00f3n de salm\u00f3n. Es una tremenda oportunidad para la regi\u00f3n seguir fortaleciendo la industria, particularmente con el v\u00ednculo con los proveedores. Nosotros necesitamos que la regi\u00f3n complejice su tejido empresarial y es muy relevante que las empresas relevantes que est\u00e1n participando -o tengan potencial- se vinculen con el sector para el crecimiento de largo plazo de la regi\u00f3n\u201d.<\/p>\n<p>Julio Uribe, alcalde de Puerto Ays\u00e9n, agradeci\u00f3 a AquaChile por esta instancia. \u201cQue una empresa haga este tipo de actividad que, para nuestra comuna, que es una comuna peque\u00f1a, y que vengan expositores de todo el pa\u00eds, dinamiza la econom\u00eda local, a trav\u00e9s de los restaurantes, hoteles.\u00a0 Con este tipo de actividad, se motiva a que las dem\u00e1s empresas tambi\u00e9n hagan este tipo de encuentros, y se motiva a nuestros empresarios locales para que puedan participar en la industria con m\u00e1s posibilidades. Por eso, como municipio estamos muy contentos de que sigan haciendo este tipo de cosas e invitar a AquaChile a acercarse m\u00e1s a nuestras comunidades, a poder colaborar en todos los aspectos, en la parte social que igual es muy importante. Agradecido de que puedan estar ac\u00e1 mostrando lo que hacen, ya que nosotros como comuna nos hemos sentido alejados de las actividades de la salmonicultura, porque no ha habido ese arraigo que pudi\u00e9ramos haber tenido. Por eso invitamos a las empresas a que hagan este tipo de actividades\u201d.<\/p>\n<p>Actualmente AquaChile trabaja con m\u00e1s de 2.900 proveedores, de los cuales el 96% son locales. Uno de los asistentes a la feria, Marcos Rubilar, representante legal de JM Servicios Acu\u00edcolas, destac\u00f3 la realizaci\u00f3n de esta feria: \u201cEstuve conversando con otros proveedores que asistieron hoy d\u00eda, y todos est\u00e1n todos muy agradecidos que AquaChile haya abierto sus puertas para que la gente se sienta m\u00e1s cercana a esta compa\u00f1\u00eda que es tan importante para el desarrollo de la regi\u00f3n de Ays\u00e9n. La gente ve\u00eda muy de lejos la posibilidad de acercarse al equipo de AquaChile y hoy lo tienen al lado. As\u00ed es que todos estamos muy contentos y agradecidos\u201d.<\/p>\n<p>En tanto, Juan Carlos Gonz\u00e1lez, gerente general de Transandino Transportes, resalt\u00f3 la relevancia de ser proveedor de AquaChile: \u201cNos da prestigio. AquaChile es la principal empresa de exportaci\u00f3n de salm\u00f3n de Chile y ellos tienen un est\u00e1ndar muy alto, que nos hace exigirnos cada vez m\u00e1s como proveedor y mantener ese est\u00e1ndar es complicado. Nosotros este a\u00f1o invertimos en camiones nuevos con nueva tecnolog\u00eda, seguridad, capacitaci\u00f3n a los conductores, etc. Estamos muy felices de ser proveedores de AquaChile\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es importante destacar que actualmente AquaChile trabaja con m\u00e1s de 2.900 proveedores, de los cuales el 96% de ellas son locales. <\/p>\n","protected":false},"author":8,"featured_media":51635,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[112],"tags":[6775,423,2958,17103,1654,17104,7304,907],"class_list":["post-51634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","tag-acuiprov","tag-aquachile","tag-aysen","tag-feria-de-emprendedores-aysen","tag-harold-mayne-nicholls","tag-mauricio-pinilla","tag-proveedores-salmonicultura","tag-sady-delgado"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Con \u00e9xito AquaChile organiz\u00f3 feria de emprendedores y proveedores en Ays\u00e9n - Mundoacuicola<\/title>\n<meta name=\"description\" content=\"Es importante destacar que actualmente AquaChile trabaja con m\u00e1s de 2.900 proveedores, de los cuales el 96% de ellas son locales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoacuicola.cl\/new\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Con \u00e9xito AquaChile organiz\u00f3 feria de emprendedores y proveedores en Ays\u00e9n - Mundoacuicola\" \/>\n<meta property=\"og:description\" content=\"Es importante destacar que actualmente AquaChile trabaja con m\u00e1s de 2.900 proveedores, de los cuales el 96% de ellas son locales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoacuicola.cl\/new\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoacuicola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.acuicola\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-11T08:08:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-12T12:18:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/05\/FeriaEmprendedoresAquaChile2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ricardo Alvarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:site\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Alvarez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\\\/\"},\"author\":{\"name\":\"Ricardo Alvarez\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\"},\"headline\":\"Con \u00e9xito AquaChile organiz\u00f3 feria de emprendedores y proveedores en Ays\u00e9n\",\"datePublished\":\"2023-05-11T08:08:28+00:00\",\"dateModified\":\"2023-05-12T12:18:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\\\/\"},\"wordCount\":1015,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/FeriaEmprendedoresAquaChile2.jpg\",\"keywords\":[\"Acuiprov\",\"AquaChile\",\"Ays\u00e9n\",\"Feria de emprendedores Ays\u00e9n\",\"Harold Mayne Nicholls\",\"Mauricio Pinilla\",\"Proveedores salmonicultura\",\"Sady Delgado\"],\"articleSection\":[\"Eventos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\\\/\",\"name\":\"Con \u00e9xito AquaChile organiz\u00f3 feria de emprendedores y proveedores en Ays\u00e9n - Mundoacuicola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/FeriaEmprendedoresAquaChile2.jpg\",\"datePublished\":\"2023-05-11T08:08:28+00:00\",\"dateModified\":\"2023-05-12T12:18:24+00:00\",\"description\":\"Es importante destacar que actualmente AquaChile trabaja con m\u00e1s de 2.900 proveedores, de los cuales el 96% de ellas son locales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/FeriaEmprendedoresAquaChile2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/FeriaEmprendedoresAquaChile2.jpg\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Con \u00e9xito AquaChile organiz\u00f3 feria de emprendedores y proveedores en Ays\u00e9n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"name\":\"Mundoacuicola\",\"description\":\"Revista de Acuicultura.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\",\"name\":\"Mundoacuicola\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"width\":1252,\"height\":296,\"caption\":\"Mundoacuicola\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.acuicola\\\/\",\"https:\\\/\\\/x.com\\\/mundoacuicola\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-acuicola\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\",\"name\":\"Ricardo Alvarez\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/author\\\/ricardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Con \u00e9xito AquaChile organiz\u00f3 feria de emprendedores y proveedores en Ays\u00e9n - Mundoacuicola","description":"Es importante destacar que actualmente AquaChile trabaja con m\u00e1s de 2.900 proveedores, de los cuales el 96% de ellas son locales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoacuicola.cl\/new\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\/","og_locale":"es_ES","og_type":"article","og_title":"Con \u00e9xito AquaChile organiz\u00f3 feria de emprendedores y proveedores en Ays\u00e9n - Mundoacuicola","og_description":"Es importante destacar que actualmente AquaChile trabaja con m\u00e1s de 2.900 proveedores, de los cuales el 96% de ellas son locales.","og_url":"https:\/\/www.mundoacuicola.cl\/new\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\/","og_site_name":"Mundoacuicola","article_publisher":"https:\/\/www.facebook.com\/mundo.acuicola\/","article_published_time":"2023-05-11T08:08:28+00:00","article_modified_time":"2023-05-12T12:18:24+00:00","og_image":[{"width":750,"height":400,"url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/05\/FeriaEmprendedoresAquaChile2.jpg","type":"image\/jpeg"}],"author":"Ricardo Alvarez","twitter_card":"summary_large_image","twitter_creator":"@mundoacuicola","twitter_site":"@mundoacuicola","twitter_misc":{"Escrito por":"Ricardo Alvarez","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoacuicola.cl\/new\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\/#article","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\/"},"author":{"name":"Ricardo Alvarez","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd"},"headline":"Con \u00e9xito AquaChile organiz\u00f3 feria de emprendedores y proveedores en Ays\u00e9n","datePublished":"2023-05-11T08:08:28+00:00","dateModified":"2023-05-12T12:18:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\/"},"wordCount":1015,"publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/05\/FeriaEmprendedoresAquaChile2.jpg","keywords":["Acuiprov","AquaChile","Ays\u00e9n","Feria de emprendedores Ays\u00e9n","Harold Mayne Nicholls","Mauricio Pinilla","Proveedores salmonicultura","Sady Delgado"],"articleSection":["Eventos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoacuicola.cl\/new\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\/","url":"https:\/\/www.mundoacuicola.cl\/new\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\/","name":"Con \u00e9xito AquaChile organiz\u00f3 feria de emprendedores y proveedores en Ays\u00e9n - Mundoacuicola","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/05\/FeriaEmprendedoresAquaChile2.jpg","datePublished":"2023-05-11T08:08:28+00:00","dateModified":"2023-05-12T12:18:24+00:00","description":"Es importante destacar que actualmente AquaChile trabaja con m\u00e1s de 2.900 proveedores, de los cuales el 96% de ellas son locales.","breadcrumb":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoacuicola.cl\/new\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\/#primaryimage","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/05\/FeriaEmprendedoresAquaChile2.jpg","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/05\/FeriaEmprendedoresAquaChile2.jpg","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoacuicola.cl\/new\/con-exito-aquachile-organizo-feria-de-emprendedores-y-proveedores-en-aysen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoacuicola.cl\/new\/"},{"@type":"ListItem","position":2,"name":"Con \u00e9xito AquaChile organiz\u00f3 feria de emprendedores y proveedores en Ays\u00e9n"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoacuicola.cl\/new\/#website","url":"https:\/\/www.mundoacuicola.cl\/new\/","name":"Mundoacuicola","description":"Revista de Acuicultura.","publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoacuicola.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization","name":"Mundoacuicola","url":"https:\/\/www.mundoacuicola.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","width":1252,"height":296,"caption":"Mundoacuicola"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.acuicola\/","https:\/\/x.com\/mundoacuicola","https:\/\/www.linkedin.com\/in\/mundo-acuicola"]},{"@type":"Person","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd","name":"Ricardo Alvarez","url":"https:\/\/www.mundoacuicola.cl\/new\/author\/ricardo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/51634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/comments?post=51634"}],"version-history":[{"count":0,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/51634\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media\/51635"}],"wp:attachment":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media?parent=51634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/categories?post=51634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/tags?post=51634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}