{"id":53266,"date":"2023-06-30T03:46:11","date_gmt":"2023-06-30T06:46:11","guid":{"rendered":"https:\/\/www.mundoacuicola.cl\/new\/?p=53266"},"modified":"2023-07-04T10:50:37","modified_gmt":"2023-07-04T13:50:37","slug":"en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure","status":"publish","type":"post","link":"https:\/\/www.mundoacuicola.cl\/new\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\/","title":{"rendered":"En Coquimbo: Pescadores(as) de Caleta Buena se capacitan en cultivo de piure"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.mundoacuicola.cl\/medios\/?url_camp=26\" target=\"_blank\" rel=\"https:\/\/www.mundoacuicola.cl\/medios\/?url_camp=26 noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.mundoacuicola.cl\/medios\/?camp=26\" alt=\"\" width=\"300\" height=\"250\" \/><\/a><\/span>Una delegaci\u00f3n de 6 pescadores y 7 pescadoras de Caleta Buena, de la comuna de Tocopilla, particip\u00f3 durante una semana en una capacitaci\u00f3n sobre el cultivo de piure, en el marco del Proyecto \u201cRecurso Piure como Estrategia de Diversificaci\u00f3n Productiva de la Pesca Artesanal\u201d, el que es financiado por el Fondo de Innovaci\u00f3n para la Competitividad Regional FIC-R del <a href=\"https:\/\/www.goreantofagasta.cl\/\">Gobierno Regional de Antofagasta<\/a> y ejecutado por el <a href=\"https:\/\/www.ucn.cl\/facultad-de-ciencias-del-mar\/departamento-de-acuicultura\/\">Departamento de Acuicultura de Facultad de Ciencias del Mar de la Universidad Cat\u00f3lica del Norte (UCN).<\/a><\/p>\n<p>El proyecto liderado por el Dr. Rodrigo Rojas Araya, consiste en el desarrollo y aplicaci\u00f3n de un sistema de cultivo para el recurso piure de bajo costo, para las \u00c1reas de Manejo y Explotaci\u00f3n de Recursos Bent\u00f3nicos (AMERB). El foco productivo considera\u00a0 producci\u00f3n de cuelgas de piure (en tierra) y el cultivo en mar mediante la estrategia de Acuicultura a Peque\u00f1a Escala. De manera adicional, se trabaja en la agregaci\u00f3n de valor a los productos del mar que hoy comercializan en Caleta Buena, as\u00ed como el desarrollo de nuevos productos y mercados para aquellos que surgir\u00e1n como resultado de la acuicultura.<\/p>\n<p>El proyecto ejecutado por el Departamento de Acuicultura, explic\u00f3 el Dr. Rodrigo Rojas, \u201cpromueve la acuicultura en la pesca artesanal en el territorio nacional, y en especial en la zona norte del pa\u00eds, que presenta condiciones ambientales favorables para el cultivo de piure. Est\u00e1s se ven potenciadas por el trabajo comunitario sistem\u00e1tico que viene desarrollando Caleta Buena de Tocopilla, en pos de mejorar la calidad de vida de sus integrantes, mediante la diversificaci\u00f3n de su actividad extractiva tradicional, la incorporaci\u00f3n de acuicultura, la agregaci\u00f3n de valor a sus productos actuales, y especialmente a trav\u00e9s del trabajo protag\u00f3nico de mujeres y pescadores artesanales j\u00f3venes y adultos mayores\u201d.<\/p>\n<p>En tanto, el director alterno del proyecto y coordinador de la Unidad Productiva de la Facultad de Ciencias del Mar, Mag. Germ\u00e1n Lira Godoy, explic\u00f3 que el proyecto se inici\u00f3 con la habilitaci\u00f3n de un hatchery que funciona con energ\u00eda fotovoltaica que cuenta con las condiciones para la producci\u00f3n de semillas de piure en los vol\u00famenes requeridos. Junto con ello explic\u00f3, que la selecci\u00f3n del recurso piure obedece a la sencillez de su producci\u00f3n y su corto ciclo de vida, lo que favorece los procesos de aprendizaje y adopci\u00f3n de la acuicultura por parte de pescadores y pescadoras de Caleta Buena.<\/p>\n<p>Para desarrollar el proyecto se seleccionaron caletas en la comuna de Tocopilla, que contaran con las condiciones para implementar este sistema y el Sindicato Caleta Buena, cumpli\u00f3 con las condiciones requeridas. Adem\u00e1s conoc\u00edan el trabajo de la Facultad de Ciencias del Mar y se proyectaban en la acuicultura en peque\u00f1a escala. \u201cComo universidad les estamos entregando todo el conocimiento de ingenier\u00eda, sobre el cultivo en tierra y mar, adem\u00e1s temas comerciales y sociol\u00f3gicos que permitan asegurar el \u00e9xito de la\u00a0 transferencia tecnol\u00f3gica\u201d, destac\u00f3 Germ\u00e1n Lira.<\/p>\n<h2><strong>Desarrollo para Caleta Buena<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">El Sindicato de Caleta Buena est\u00e1 integrado por 26 personas entre buzos, pescadores, recolectores de orilla y asistentes de buzos. Hace unos a\u00f1os realizaron una primera pasant\u00eda a la regi\u00f3n de Coquimbo, con el foco en acuicultura, gastronom\u00eda y turismo, fue entonces que aprendieron de la acuicultura en la UCN, y ahora son parte del FIC que desarrolla el Departamento de Acuicultura, \u201cestamos muy agradecidos de participar y queremos desarrollar lo que hemos aprendido\u201d, destac\u00f3 Francisco Ossand\u00f3n Ossand\u00f3n, presidente del Sindicato de Caleta Buena.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al referirse a la capacitaci\u00f3n recibida, el dirigente resalt\u00f3 que ha sido una experiencia muy buena, \u201chemos aprendido todo lo relacionado con la acuicultura, lo que ha sido novedoso, es bueno aprender, para despu\u00e9s desarrollarlo en la caleta y luego difundirlo\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En tanto Maril\u00fa Geraldo Geraldo, recolectora de orilla y socia del sindicato desde hace cerca de 16 a\u00f1os, enfatiz\u00f3 que el trabajo desarrollado con la Universidad es buen\u00edsimo, un trabajo muy enriquecedor que les ha permitido aprender muchas cosas e ir motivadas para replicar la informaci\u00f3n en la caleta.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cEstamos focalizados en que, si bien hasta ahora hemos sido m\u00e1s depredadores de la costa, ahora queremos sembrar para producir los mariscos, lo que nos abre m\u00e1s esperanzas de tener m\u00e1s mariscos de manera regular, generar trabajo entre nuestros compa\u00f1eros e insertar m\u00e1s a la mujer en el trabajo, ya que con todo lo que hemos aprendido queremos hacernos cargo del hatchery, ser\u00e1 muy bueno para nosotros\u201d, dijo Maril\u00fa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esto tambi\u00e9n da la posibilidad de entregar trabajo a mujeres de Caleta Buena, porque si empezamos a producir, con el tiempo podemos generar trabajo para m\u00e1s personas, no importa que no sean del sindicato, es trabajo para la comunidad, enfatiz\u00f3 Maril\u00fa Geraldo.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El trabajo se desarroll\u00f3 en el marco de proyecto FIC-R financiado por el Gobierno Regional de Antofagasta.<\/p>\n","protected":false},"author":8,"featured_media":53267,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[143,17336,380,5931,2390,9182,6482,441,1492,1379,144],"class_list":["post-53266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acuicultura","tag-acuicultura","tag-agregacion-de-valor","tag-capacitacion","tag-cultivo-de-piure","tag-diversificacion-productiva","tag-financiamiento","tag-fondo-de-innovacion","tag-pesca-artesanal","tag-productos-del-mar","tag-recursos-bentonicos","tag-ucn"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En Coquimbo: Pescadores(as) de Caleta Buena se capacitan en cultivo de piure - Mundoacuicola<\/title>\n<meta name=\"description\" content=\"El trabajo se desarroll\u00f3 en el marco de proyecto FIC-R financiado por el Gobierno Regional de Antofagasta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoacuicola.cl\/new\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En Coquimbo: Pescadores(as) de Caleta Buena se capacitan en cultivo de piure - Mundoacuicola\" \/>\n<meta property=\"og:description\" content=\"El trabajo se desarroll\u00f3 en el marco de proyecto FIC-R financiado por el Gobierno Regional de Antofagasta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoacuicola.cl\/new\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoacuicola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.acuicola\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-30T06:46:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-04T13:50:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/06\/PiureCultivoCaletaBuena.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ricardo Alvarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:site\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Alvarez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\\\/\"},\"author\":{\"name\":\"Ricardo Alvarez\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\"},\"headline\":\"En Coquimbo: Pescadores(as) de Caleta Buena se capacitan en cultivo de piure\",\"datePublished\":\"2023-06-30T06:46:11+00:00\",\"dateModified\":\"2023-07-04T13:50:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\\\/\"},\"wordCount\":829,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/PiureCultivoCaletaBuena.jpg\",\"keywords\":[\"Acuicultura\",\"agregaci\u00f3n de valor\",\"capacitaci\u00f3n\",\"cultivo de piure\",\"Diversificaci\u00f3n productiva\",\"financiamiento\",\"Fondo de innovaci\u00f3n\",\"Pesca artesanal\",\"Productos del mar\",\"Recursos bent\u00f3nicos\",\"UCN\"],\"articleSection\":[\"Acuicultura\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\\\/\",\"name\":\"En Coquimbo: Pescadores(as) de Caleta Buena se capacitan en cultivo de piure - Mundoacuicola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/PiureCultivoCaletaBuena.jpg\",\"datePublished\":\"2023-06-30T06:46:11+00:00\",\"dateModified\":\"2023-07-04T13:50:37+00:00\",\"description\":\"El trabajo se desarroll\u00f3 en el marco de proyecto FIC-R financiado por el Gobierno Regional de Antofagasta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/PiureCultivoCaletaBuena.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/PiureCultivoCaletaBuena.jpg\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En Coquimbo: Pescadores(as) de Caleta Buena se capacitan en cultivo de piure\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"name\":\"Mundoacuicola\",\"description\":\"Revista de Acuicultura.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\",\"name\":\"Mundoacuicola\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"width\":1252,\"height\":296,\"caption\":\"Mundoacuicola\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.acuicola\\\/\",\"https:\\\/\\\/x.com\\\/mundoacuicola\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-acuicola\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\",\"name\":\"Ricardo Alvarez\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/author\\\/ricardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En Coquimbo: Pescadores(as) de Caleta Buena se capacitan en cultivo de piure - Mundoacuicola","description":"El trabajo se desarroll\u00f3 en el marco de proyecto FIC-R financiado por el Gobierno Regional de Antofagasta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoacuicola.cl\/new\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\/","og_locale":"es_ES","og_type":"article","og_title":"En Coquimbo: Pescadores(as) de Caleta Buena se capacitan en cultivo de piure - Mundoacuicola","og_description":"El trabajo se desarroll\u00f3 en el marco de proyecto FIC-R financiado por el Gobierno Regional de Antofagasta.","og_url":"https:\/\/www.mundoacuicola.cl\/new\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\/","og_site_name":"Mundoacuicola","article_publisher":"https:\/\/www.facebook.com\/mundo.acuicola\/","article_published_time":"2023-06-30T06:46:11+00:00","article_modified_time":"2023-07-04T13:50:37+00:00","og_image":[{"width":750,"height":400,"url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/06\/PiureCultivoCaletaBuena.jpg","type":"image\/jpeg"}],"author":"Ricardo Alvarez","twitter_card":"summary_large_image","twitter_creator":"@mundoacuicola","twitter_site":"@mundoacuicola","twitter_misc":{"Escrito por":"Ricardo Alvarez","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoacuicola.cl\/new\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\/#article","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\/"},"author":{"name":"Ricardo Alvarez","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd"},"headline":"En Coquimbo: Pescadores(as) de Caleta Buena se capacitan en cultivo de piure","datePublished":"2023-06-30T06:46:11+00:00","dateModified":"2023-07-04T13:50:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\/"},"wordCount":829,"publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/06\/PiureCultivoCaletaBuena.jpg","keywords":["Acuicultura","agregaci\u00f3n de valor","capacitaci\u00f3n","cultivo de piure","Diversificaci\u00f3n productiva","financiamiento","Fondo de innovaci\u00f3n","Pesca artesanal","Productos del mar","Recursos bent\u00f3nicos","UCN"],"articleSection":["Acuicultura"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoacuicola.cl\/new\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\/","url":"https:\/\/www.mundoacuicola.cl\/new\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\/","name":"En Coquimbo: Pescadores(as) de Caleta Buena se capacitan en cultivo de piure - Mundoacuicola","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/06\/PiureCultivoCaletaBuena.jpg","datePublished":"2023-06-30T06:46:11+00:00","dateModified":"2023-07-04T13:50:37+00:00","description":"El trabajo se desarroll\u00f3 en el marco de proyecto FIC-R financiado por el Gobierno Regional de Antofagasta.","breadcrumb":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoacuicola.cl\/new\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\/#primaryimage","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/06\/PiureCultivoCaletaBuena.jpg","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/06\/PiureCultivoCaletaBuena.jpg","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoacuicola.cl\/new\/en-coquimbo-pescadoresas-de-caleta-buena-se-capacitan-en-cultivo-de-piure\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoacuicola.cl\/new\/"},{"@type":"ListItem","position":2,"name":"En Coquimbo: Pescadores(as) de Caleta Buena se capacitan en cultivo de piure"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoacuicola.cl\/new\/#website","url":"https:\/\/www.mundoacuicola.cl\/new\/","name":"Mundoacuicola","description":"Revista de Acuicultura.","publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoacuicola.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization","name":"Mundoacuicola","url":"https:\/\/www.mundoacuicola.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","width":1252,"height":296,"caption":"Mundoacuicola"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.acuicola\/","https:\/\/x.com\/mundoacuicola","https:\/\/www.linkedin.com\/in\/mundo-acuicola"]},{"@type":"Person","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd","name":"Ricardo Alvarez","url":"https:\/\/www.mundoacuicola.cl\/new\/author\/ricardo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/53266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/comments?post=53266"}],"version-history":[{"count":0,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/53266\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media\/53267"}],"wp:attachment":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media?parent=53266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/categories?post=53266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/tags?post=53266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}