{"id":57313,"date":"2023-10-26T06:30:10","date_gmt":"2023-10-26T09:30:10","guid":{"rendered":"https:\/\/www.mundoacuicola.cl\/new\/?p=57313"},"modified":"2023-10-29T18:32:45","modified_gmt":"2023-10-29T21:32:45","slug":"piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades","status":"publish","type":"post","link":"https:\/\/www.mundoacuicola.cl\/new\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\/","title":{"rendered":"Piscicultores de La Araucan\u00eda participan en taller de cumplimiento medioambiental"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.alloyingenieria.com\/\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-55815 size-full alignright\" src=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/09\/Gif-Alloy.gif\" alt=\"\" width=\"300\" height=\"300\" \/><\/a><\/span>Los piscicultores de La Araucan\u00eda asociados a SalmonChile se reunieron para participar en un taller de cumplimiento medioambiental por parte de representantes de la Superintendencia de Medio Ambiente (SMA); el Servicio Nacional de Pesca (Sernapesca); el Servicio de Evaluaci\u00f3n Ambiental (SEA) y la Direcci\u00f3n General de Aguas (DGA), en el cual profundizaron en los cambios regulatorios sanitarios y medioambientales que rigen a la actividad, adem\u00e1s de los avances y desaf\u00edos para el futuro de la salmonicultura.<\/p>\n<p>En la iniciativa, a la que asistieron m\u00e1s de cincuenta personas, expusieron el jefe de la Oficina Regional del SMA de La Araucan\u00eda, Luis Mu\u00f1oz; el encargado de la Unidad de Acuicultura Sernapesca de la regi\u00f3n, Cristian Acu\u00f1a; el director regional del SEA, Marco Pichunman; y las profesionales de la DGA Araucan\u00eda, Kely Lagos y Albenia Padilla.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-56705 alignleft\" src=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/10\/CuracalcoBenchmark.jpg\" alt=\"\" width=\"435\" height=\"232\" srcset=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/10\/CuracalcoBenchmark.jpg 750w, https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/10\/CuracalcoBenchmark-500x267.jpg 500w, https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/10\/CuracalcoBenchmark-250x133.jpg 250w, https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/10\/CuracalcoBenchmark-167x89.jpg 167w, https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/10\/CuracalcoBenchmark-564x301.jpg 564w\" sizes=\"(max-width: 435px) 100vw, 435px\" \/>\u201cLa actividad desarrollada se enmarca dentro de la asistencia al cumplimiento, que es una atribuci\u00f3n que la ley establece a la SMA, que consiste en orientar e informar al regulado respecto de las obligaciones que le son propias de los instrumentos ambientales que son fiscalizados. Es por ello que la actividad permiti\u00f3 realizar una actualizaci\u00f3n de la normativa y procesos de fiscalizaci\u00f3n con el objetivo de intensificar un rol preventivo y proactivo del rubro dentro de la regi\u00f3n\u201d, indic\u00f3 el jefe de la Oficina Regional SMA de La Araucan\u00eda, Luis Mu\u00f1oz.<\/p>\n<p>Por su parte, el gerente general del Instituto Tecnol\u00f3gico del Salm\u00f3n, Esteban Ram\u00edrez, se\u00f1al\u00f3 que \u201ccumplir la normativa, requisito b\u00e1sico de una operaci\u00f3n que tiene como foco la excelencia y la sustentabilidad,\u00a0 requiere un lenguaje compartido entre regulador y regulado. Los Talleres de Cumplimiento son instancias no s\u00f3lo para actualizaci\u00f3n, sino que espacios de conversaci\u00f3n que permiten fijar los criterios que asegure el cumplimiento, por eso la importancia de su realizaci\u00f3n y la raz\u00f3n de que SalmonChile e Intesal los promuevan y organicen <span style=\"font-weight: 400;\"><strong><b><a href=\"https:\/\/www.mundoacuicola.cl\/medios\/?url_camp=26\" target=\"_blank\" rel=\"https:\/\/www.mundoacuicola.cl\/medios\/?url_camp=26 noopener\"><img decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.mundoacuicola.cl\/medios\/?camp=26\" alt=\"\" width=\"300\" height=\"250\" \/><\/a><\/b><\/strong><\/span>peri\u00f3dicamente\u00bb.<\/p>\n<p>\u201cLa salmonicultura, representada a trav\u00e9s de SalmonChile, busca permanentemente el disminuir las brechas innovando y mejorando operacionalmente en pos de la sustentabilidad medioambiental. Agradecemos a los servicios p\u00fablicos por la disposici\u00f3n y a las empresas por el gran inter\u00e9s mostrado en la actividad organizada conjuntamente entre las instituciones fiscalizadoras y SalmonChile\u201d puntualiz\u00f3 el representante territorial de SalmonChile en La Araucan\u00eda, Ricardo L\u00f3pez.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Superintendencia de Medio Ambiente y Sernapesca brindaron informaci\u00f3n sobre la normativa ambiental y los procesos de fiscalizaci\u00f3n. <\/p>\n","protected":false},"author":8,"featured_media":57314,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[19384,7926,435,6654,1735,1126,170,125,718,3477,9485],"class_list":["post-57313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salmonicultura","tag-cumplimiento-medioambiental","tag-direccion-general-de-aguas","tag-fiscalizacion","tag-instituto-tecnologico-del-salmon","tag-la-araucania","tag-normativa-ambiental","tag-salmonchile","tag-sernapesca","tag-servicio-de-evaluacion-ambiental","tag-sostenibilidad","tag-superintendencia-de-medio-ambiente"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Piscicultores de La Araucan\u00eda participan en taller de cumplimiento medioambiental - Mundoacuicola<\/title>\n<meta name=\"description\" content=\"Superintendencia de Medio Ambiente y Sernapesca brindaron informaci\u00f3n sobre la normativa ambiental y los procesos de fiscalizaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoacuicola.cl\/new\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Piscicultores de La Araucan\u00eda participan en taller de cumplimiento medioambiental - Mundoacuicola\" \/>\n<meta property=\"og:description\" content=\"Superintendencia de Medio Ambiente y Sernapesca brindaron informaci\u00f3n sobre la normativa ambiental y los procesos de fiscalizaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoacuicola.cl\/new\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoacuicola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.acuicola\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-26T09:30:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-29T21:32:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/10\/SalmonChileAraucania.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ricardo Alvarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:site\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Alvarez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\\\/\"},\"author\":{\"name\":\"Ricardo Alvarez\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\"},\"headline\":\"Piscicultores de La Araucan\u00eda participan en taller de cumplimiento medioambiental\",\"datePublished\":\"2023-10-26T09:30:10+00:00\",\"dateModified\":\"2023-10-29T21:32:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\\\/\"},\"wordCount\":417,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/SalmonChileAraucania.jpg\",\"keywords\":[\"cumplimiento medioambiental\",\"Direcci\u00f3n General de Aguas\",\"Fiscalizaci\u00f3n\",\"Instituto Tecnol\u00f3gico del Salm\u00f3n\",\"La Araucan\u00eda\",\"Normativa ambiental\",\"Salmonchile\",\"Sernapesca\",\"Servicio de Evaluaci\u00f3n Ambiental\",\"sostenibilidad\",\"Superintendencia de Medio Ambiente\"],\"articleSection\":[\"Salmonicultura\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\\\/\",\"name\":\"Piscicultores de La Araucan\u00eda participan en taller de cumplimiento medioambiental - Mundoacuicola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/SalmonChileAraucania.jpg\",\"datePublished\":\"2023-10-26T09:30:10+00:00\",\"dateModified\":\"2023-10-29T21:32:45+00:00\",\"description\":\"Superintendencia de Medio Ambiente y Sernapesca brindaron informaci\u00f3n sobre la normativa ambiental y los procesos de fiscalizaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/SalmonChileAraucania.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/SalmonChileAraucania.jpg\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Piscicultores de La Araucan\u00eda participan en taller de cumplimiento medioambiental\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"name\":\"Mundoacuicola\",\"description\":\"Revista de Acuicultura.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\",\"name\":\"Mundoacuicola\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"width\":1252,\"height\":296,\"caption\":\"Mundoacuicola\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.acuicola\\\/\",\"https:\\\/\\\/x.com\\\/mundoacuicola\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-acuicola\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\",\"name\":\"Ricardo Alvarez\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/author\\\/ricardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Piscicultores de La Araucan\u00eda participan en taller de cumplimiento medioambiental - Mundoacuicola","description":"Superintendencia de Medio Ambiente y Sernapesca brindaron informaci\u00f3n sobre la normativa ambiental y los procesos de fiscalizaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoacuicola.cl\/new\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\/","og_locale":"es_ES","og_type":"article","og_title":"Piscicultores de La Araucan\u00eda participan en taller de cumplimiento medioambiental - Mundoacuicola","og_description":"Superintendencia de Medio Ambiente y Sernapesca brindaron informaci\u00f3n sobre la normativa ambiental y los procesos de fiscalizaci\u00f3n.","og_url":"https:\/\/www.mundoacuicola.cl\/new\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\/","og_site_name":"Mundoacuicola","article_publisher":"https:\/\/www.facebook.com\/mundo.acuicola\/","article_published_time":"2023-10-26T09:30:10+00:00","article_modified_time":"2023-10-29T21:32:45+00:00","og_image":[{"width":750,"height":400,"url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/10\/SalmonChileAraucania.jpg","type":"image\/jpeg"}],"author":"Ricardo Alvarez","twitter_card":"summary_large_image","twitter_creator":"@mundoacuicola","twitter_site":"@mundoacuicola","twitter_misc":{"Escrito por":"Ricardo Alvarez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoacuicola.cl\/new\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\/#article","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\/"},"author":{"name":"Ricardo Alvarez","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd"},"headline":"Piscicultores de La Araucan\u00eda participan en taller de cumplimiento medioambiental","datePublished":"2023-10-26T09:30:10+00:00","dateModified":"2023-10-29T21:32:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\/"},"wordCount":417,"publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/10\/SalmonChileAraucania.jpg","keywords":["cumplimiento medioambiental","Direcci\u00f3n General de Aguas","Fiscalizaci\u00f3n","Instituto Tecnol\u00f3gico del Salm\u00f3n","La Araucan\u00eda","Normativa ambiental","Salmonchile","Sernapesca","Servicio de Evaluaci\u00f3n Ambiental","sostenibilidad","Superintendencia de Medio Ambiente"],"articleSection":["Salmonicultura"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoacuicola.cl\/new\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\/","url":"https:\/\/www.mundoacuicola.cl\/new\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\/","name":"Piscicultores de La Araucan\u00eda participan en taller de cumplimiento medioambiental - Mundoacuicola","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/10\/SalmonChileAraucania.jpg","datePublished":"2023-10-26T09:30:10+00:00","dateModified":"2023-10-29T21:32:45+00:00","description":"Superintendencia de Medio Ambiente y Sernapesca brindaron informaci\u00f3n sobre la normativa ambiental y los procesos de fiscalizaci\u00f3n.","breadcrumb":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoacuicola.cl\/new\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\/#primaryimage","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/10\/SalmonChileAraucania.jpg","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/10\/SalmonChileAraucania.jpg","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoacuicola.cl\/new\/piscicultores-de-la-araucania-participan-en-taller-de-cumplimiento-medioambiental-realizado-por-autoridades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoacuicola.cl\/new\/"},{"@type":"ListItem","position":2,"name":"Piscicultores de La Araucan\u00eda participan en taller de cumplimiento medioambiental"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoacuicola.cl\/new\/#website","url":"https:\/\/www.mundoacuicola.cl\/new\/","name":"Mundoacuicola","description":"Revista de Acuicultura.","publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoacuicola.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization","name":"Mundoacuicola","url":"https:\/\/www.mundoacuicola.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","width":1252,"height":296,"caption":"Mundoacuicola"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.acuicola\/","https:\/\/x.com\/mundoacuicola","https:\/\/www.linkedin.com\/in\/mundo-acuicola"]},{"@type":"Person","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd","name":"Ricardo Alvarez","url":"https:\/\/www.mundoacuicola.cl\/new\/author\/ricardo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/57313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/comments?post=57313"}],"version-history":[{"count":0,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/57313\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media\/57314"}],"wp:attachment":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media?parent=57313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/categories?post=57313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/tags?post=57313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}