{"id":59119,"date":"2023-12-18T10:37:13","date_gmt":"2023-12-18T13:37:13","guid":{"rendered":"https:\/\/www.mundoacuicola.cl\/new\/?p=59119"},"modified":"2023-12-20T09:24:05","modified_gmt":"2023-12-20T12:24:05","slug":"aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas","status":"publish","type":"post","link":"https:\/\/www.mundoacuicola.cl\/new\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\/","title":{"rendered":"AquaShip  e Intership se fusionan para liderar la flota mundial de servicios acu\u00edcolas"},"content":{"rendered":"<p><b><span style=\"font-weight: 400;\"><a href=\"https:\/\/www.alloyingenieria.com\/\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-55815 size-full alignright\" src=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/09\/Gif-Alloy.gif\" alt=\"\" width=\"300\" height=\"300\" \/><\/a><\/span><\/b>American Industrial Partners Capital Fund VII, LP, un fondo de inversi\u00f3n gestionado por American Industrial Partners (AIP) se convierte en el accionista mayoritario de AquaShip AS (\u00abAquaShip\u00bb) e Intership AS (\u00abIntership\u00bb) para formar uno de los mayores y m\u00e1s diversificados operadores de buques de servicios acu\u00edcolas a nivel mundial. La integraci\u00f3n combina dos negocios complementarios con liderazgo en experiencia operativa, activos diferenciados y de alta calidad e innovaci\u00f3n tecnol\u00f3gica.<\/p>\n<p>La empresa combinada ser\u00e1 dirigida por Sverre Taknes, Consejero Delegado desde Kristiansund, y Ole-Peter Brandal, Presidente Ejecutivo desde Hareid. La nueva empresa se beneficiar\u00e1 de un acceso significativo a capital, lo que permitir\u00e1 la ejecuci\u00f3n de ambiciosos planes de crecimiento sobre la base de la creciente demanda de servicios acu\u00edcolas diversificados de clientes nuevos y establecidos a nivel mundial.<\/p>\n<p>La empresa de inversiones Alchemy, con sede en Londres, era el mayor accionista de Intership hasta que vendi\u00f3 toda su participaci\u00f3n en la operaci\u00f3n. AILP, propiedad mayoritaria de AMERRA, que ha sido anteriormente el mayor accionista de AquaShip, seguir\u00e1 siendo un accionista importante de la empresa combinada y estar\u00e1 representada en el Consejo por el CIO de AMERRA, Craig Tashjian. Los directivos de ambas empresas tambi\u00e9n seguir\u00e1n siendo accionistas significativos.<\/p>\n<p>AquaShip es la \u00fanica empresa que posee y opera buques en las cuatro \u00e1reas principales de los servicios acu\u00edcolas. Intership ha construido una de las flotas de wellboats o barcos de transporte de peces vivos m\u00e1s modernas del mundo y ha demostrado ser una empresa innovadora al introducir en el mercado un nuevo tratamiento de agua dulce para los piojos de mar y las enfermedades de las branquias que no da\u00f1a a la vida marina. En conjunto, la empresa contar\u00e1 con una flota de 39 buques y cerca de 700 empleados que operan en Chile, Reino Unido, Irlanda, Canad\u00e1 y Noruega.<\/p>\n<p><img decoding=\"async\" class=\"wp-image-59121 alignleft\" src=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/12\/Grip-Marine-533x400.jpg\" alt=\"\" width=\"520\" height=\"390\" srcset=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/12\/Grip-Marine-533x400.jpg 533w, https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/12\/Grip-Marine-500x375.jpg 500w, https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/12\/Grip-Marine-177x133.jpg 177w, https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/12\/Grip-Marine-768x576.jpg 768w, https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/12\/Grip-Marine.jpg 1024w\" sizes=\"(max-width: 520px) 100vw, 520px\" \/>\u00abNos complace incorporar a AIP como socio estrat\u00e9gico y propietario mayoritario de la nueva empresa combinada. Creemos que tenemos una plataforma \u00fanica, que combina las competencias reconocidas de AquaShip en m\u00faltiples tipos de buques y la experiencia pr\u00e1ctica local en varias regiones con la reconocida experiencia de Intership en buques de transporte de peces vivos. Juntos, aspiramos a crear nuevas e impactantes alianzas en todas las regiones y a mejorar a\u00fan m\u00e1s el excelente servicio que ya prestamos a nuestros clientes. Al aprovechar las capacidades de AIP, combinadas con el enfoque innovador y la plataforma diversificada tanto de AquaShip como de Intership, estamos seguros de que la compa\u00f1\u00eda combinada est\u00e1 bien posicionada para el camino de crecimiento que tenemos por delante\u00bb, dijo Sverre Taknes, CEO de AquaShip y CEO de la compa\u00f1\u00eda combinada.<\/p>\n<p>Ole Peter Brandal, Consejero Delegado de Intership y Presidente Ejecutivo de la empresa combinada, ha declarado: \u00abEstamos ansiosos por emprender un nuevo viaje con AIP y AquaShip y continuar nuestra misi\u00f3n de ofrecer y mejorar a\u00fan m\u00e1s el servicio de m\u00e1xima calidad a nuestros clientes. Estamos convencidos de que nuestras relaciones con los clientes, presencia mundial, tecnolog\u00eda pionera y dedicaci\u00f3n al servicio de nuestros clientes constituir\u00e1n una valiosa plataforma para el camino que tenemos por delante. La uni\u00f3n de fuerzas con AIP y AquaShip marca un cap\u00edtulo emocionante para todos en Intership\u00bb.<\/p>\n<p>\u00abEstamos entusiasmados de asociarnos con los equipos de AquaShip e Intership y de apoyar la siguiente fase de crecimiento, creando una plataforma global verdaderamente diferenciada en esta industria en r\u00e1pida evoluci\u00f3n\u00bb, dijo Alex Schukin, socio de <span style=\"font-weight: 400;\"><strong><b><a href=\"https:\/\/www.mundoacuicola.cl\/medios\/?url_camp=26\" target=\"_blank\" rel=\"https:\/\/www.mundoacuicola.cl\/medios\/?url_camp=26 noopener\"><img decoding=\"async\" class=\"alignright\" src=\"https:\/\/www.mundoacuicola.cl\/medios\/?camp=26\" alt=\"\" width=\"300\" height=\"250\" \/><\/a><\/b><\/strong><\/span>AIP. Invertimos en empresas que ya son l\u00edderes mundiales en sus sectores, pero que a\u00fan tienen un importante potencial sin explotar. Existe una oportunidad significativa de desbloquear nuevas capacidades para la empresa combinada, sus clientes, sus empleados y la industria. Esperamos permitir a DNB Confidential, la empresa combinada, impulsar un mayor crecimiento y desarrollo tecnol\u00f3gico tanto org\u00e1nica como adquisitivamente.\u00bb<\/p>\n<p>Craig Tashjian, CIO de AMERRA coment\u00f3 \u00abEstamos entusiasmados de asociarnos con AIP y la reciente transacci\u00f3n con Intership. En AILP estamos muy satisfechos y entusiasmados con el futuro de AquaShip y el \u00e9xito a largo plazo de la empresa fusionada.\u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el objetivo de convertirse en uno de los principales operadores mundiales de buques de servicios acu\u00edcolas, ambas empresas buscan seguir potenciando la industria en Chile y el resto del mundo. <\/p>\n","protected":false},"author":8,"featured_media":59120,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[20222,20223,4706,11725,19353,11726,8807,11841,2100,12100,3929,9783,18018,2021,346],"class_list":["post-59119","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salmonicultura","tag-american-industrial-partners","tag-aquaship","tag-buques","tag-clientes","tag-competencias","tag-empresa","tag-experiencia","tag-flota","tag-innovacion","tag-integracion","tag-intership","tag-inversion","tag-operadores","tag-servicios-acuicolas","tag-tecnologia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AquaShip e Intership se fusionan para liderar la flota mundial de servicios acu\u00edcolas - Mundoacuicola<\/title>\n<meta name=\"description\" content=\"Con esta fusi\u00f3n, Intership y AquaShip\u00a0buscan\u00a0seguir\u00a0potenciando\u00a0la\u00a0industria\u00a0en\u00a0Chile y\u00a0el\u00a0resto del\u00a0mundo.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoacuicola.cl\/new\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AquaShip e Intership se fusionan para liderar la flota mundial de servicios acu\u00edcolas - Mundoacuicola\" \/>\n<meta property=\"og:description\" content=\"Con esta fusi\u00f3n, Intership y AquaShip\u00a0buscan\u00a0seguir\u00a0potenciando\u00a0la\u00a0industria\u00a0en\u00a0Chile y\u00a0el\u00a0resto del\u00a0mundo.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoacuicola.cl\/new\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoacuicola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.acuicola\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-18T13:37:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-20T12:24:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/12\/IntershipAquaShip.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ricardo Alvarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:site\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Alvarez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\\\/\"},\"author\":{\"name\":\"Ricardo Alvarez\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\"},\"headline\":\"AquaShip e Intership se fusionan para liderar la flota mundial de servicios acu\u00edcolas\",\"datePublished\":\"2023-12-18T13:37:13+00:00\",\"dateModified\":\"2023-12-20T12:24:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\\\/\"},\"wordCount\":709,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/IntershipAquaShip.jpg\",\"keywords\":[\"American Industrial Partners\",\"AquaShip\",\"buques\",\"clientes\",\"competencias\",\"empresa\",\"experiencia\",\"flota\",\"Innovaci\u00f3n\",\"integraci\u00f3n\",\"Intership\",\"inversi\u00f3n\",\"operadores\",\"Servicios acu\u00edcolas\",\"Tecnolog\u00eda\"],\"articleSection\":[\"Salmonicultura\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\\\/\",\"name\":\"AquaShip e Intership se fusionan para liderar la flota mundial de servicios acu\u00edcolas - Mundoacuicola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/IntershipAquaShip.jpg\",\"datePublished\":\"2023-12-18T13:37:13+00:00\",\"dateModified\":\"2023-12-20T12:24:05+00:00\",\"description\":\"Con esta fusi\u00f3n, Intership y AquaShip\u00a0buscan\u00a0seguir\u00a0potenciando\u00a0la\u00a0industria\u00a0en\u00a0Chile y\u00a0el\u00a0resto del\u00a0mundo.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/IntershipAquaShip.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/IntershipAquaShip.jpg\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AquaShip e Intership se fusionan para liderar la flota mundial de servicios acu\u00edcolas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"name\":\"Mundoacuicola\",\"description\":\"Revista de Acuicultura.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\",\"name\":\"Mundoacuicola\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"width\":1252,\"height\":296,\"caption\":\"Mundoacuicola\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.acuicola\\\/\",\"https:\\\/\\\/x.com\\\/mundoacuicola\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-acuicola\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\",\"name\":\"Ricardo Alvarez\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/author\\\/ricardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AquaShip e Intership se fusionan para liderar la flota mundial de servicios acu\u00edcolas - Mundoacuicola","description":"Con esta fusi\u00f3n, Intership y AquaShip\u00a0buscan\u00a0seguir\u00a0potenciando\u00a0la\u00a0industria\u00a0en\u00a0Chile y\u00a0el\u00a0resto del\u00a0mundo.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoacuicola.cl\/new\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\/","og_locale":"es_ES","og_type":"article","og_title":"AquaShip e Intership se fusionan para liderar la flota mundial de servicios acu\u00edcolas - Mundoacuicola","og_description":"Con esta fusi\u00f3n, Intership y AquaShip\u00a0buscan\u00a0seguir\u00a0potenciando\u00a0la\u00a0industria\u00a0en\u00a0Chile y\u00a0el\u00a0resto del\u00a0mundo.\u00a0","og_url":"https:\/\/www.mundoacuicola.cl\/new\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\/","og_site_name":"Mundoacuicola","article_publisher":"https:\/\/www.facebook.com\/mundo.acuicola\/","article_published_time":"2023-12-18T13:37:13+00:00","article_modified_time":"2023-12-20T12:24:05+00:00","og_image":[{"width":750,"height":400,"url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/12\/IntershipAquaShip.jpg","type":"image\/jpeg"}],"author":"Ricardo Alvarez","twitter_card":"summary_large_image","twitter_creator":"@mundoacuicola","twitter_site":"@mundoacuicola","twitter_misc":{"Escrito por":"Ricardo Alvarez","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoacuicola.cl\/new\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\/#article","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\/"},"author":{"name":"Ricardo Alvarez","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd"},"headline":"AquaShip e Intership se fusionan para liderar la flota mundial de servicios acu\u00edcolas","datePublished":"2023-12-18T13:37:13+00:00","dateModified":"2023-12-20T12:24:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\/"},"wordCount":709,"publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/12\/IntershipAquaShip.jpg","keywords":["American Industrial Partners","AquaShip","buques","clientes","competencias","empresa","experiencia","flota","Innovaci\u00f3n","integraci\u00f3n","Intership","inversi\u00f3n","operadores","Servicios acu\u00edcolas","Tecnolog\u00eda"],"articleSection":["Salmonicultura"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoacuicola.cl\/new\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\/","url":"https:\/\/www.mundoacuicola.cl\/new\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\/","name":"AquaShip e Intership se fusionan para liderar la flota mundial de servicios acu\u00edcolas - Mundoacuicola","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/12\/IntershipAquaShip.jpg","datePublished":"2023-12-18T13:37:13+00:00","dateModified":"2023-12-20T12:24:05+00:00","description":"Con esta fusi\u00f3n, Intership y AquaShip\u00a0buscan\u00a0seguir\u00a0potenciando\u00a0la\u00a0industria\u00a0en\u00a0Chile y\u00a0el\u00a0resto del\u00a0mundo.\u00a0","breadcrumb":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoacuicola.cl\/new\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\/#primaryimage","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/12\/IntershipAquaShip.jpg","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/12\/IntershipAquaShip.jpg","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoacuicola.cl\/new\/aquaship-as-e-intership-as-se-fusionan-para-liderar-la-flota-mundial-de-servicios-acuicolas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoacuicola.cl\/new\/"},{"@type":"ListItem","position":2,"name":"AquaShip e Intership se fusionan para liderar la flota mundial de servicios acu\u00edcolas"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoacuicola.cl\/new\/#website","url":"https:\/\/www.mundoacuicola.cl\/new\/","name":"Mundoacuicola","description":"Revista de Acuicultura.","publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoacuicola.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization","name":"Mundoacuicola","url":"https:\/\/www.mundoacuicola.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","width":1252,"height":296,"caption":"Mundoacuicola"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.acuicola\/","https:\/\/x.com\/mundoacuicola","https:\/\/www.linkedin.com\/in\/mundo-acuicola"]},{"@type":"Person","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd","name":"Ricardo Alvarez","url":"https:\/\/www.mundoacuicola.cl\/new\/author\/ricardo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/59119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/comments?post=59119"}],"version-history":[{"count":0,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/59119\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media\/59120"}],"wp:attachment":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media?parent=59119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/categories?post=59119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/tags?post=59119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}