{"id":63127,"date":"2024-05-02T06:10:53","date_gmt":"2024-05-02T09:10:53","guid":{"rendered":"https:\/\/www.mundoacuicola.cl\/new\/?p=63127"},"modified":"2024-05-03T10:04:45","modified_gmt":"2024-05-03T13:04:45","slug":"equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras","status":"publish","type":"post","link":"https:\/\/www.mundoacuicola.cl\/new\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\/","title":{"rendered":"Equipo de Sernapesca llega hasta Puerto Gala para realizar atenci\u00f3n en terreno a pescadores y pescadoras"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><b><span lang=\"ES-TRAD\"><a href=\"https:\/\/www.alloyingenieria.com\/\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-55815 size-full alignright\" src=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/09\/Gif-Alloy.gif\" alt=\"\" width=\"300\" height=\"300\" \/><\/a><\/span><\/b><\/span>En el marco del programa Caleta + Cerca del Servicio Nacional de Pesca y Acuicultura (Sernapesca), cuyo objetivo es la facilitaci\u00f3n del cumplimiento normativo en terreno y acercamiento con el sector pesquero artesanal, funcionarios de la Direcci\u00f3n Regional ubicada en Puerto Ays\u00e9n se desplazaron hasta la localidad de Puerto Gala para realizar atenci\u00f3n en localidades aisladas de la regi\u00f3n.<\/p>\n<p>Tras recorrer aproximadamente tres horas en veh\u00edculo y otras cinco a bordo de una barcaza de conectividad regional, llegaron a Puerto Gala donde permanecieron un d\u00eda y medio para atender a un total de 22 pescadores artesanales (6 mujeres y 16 hombres), realizar actividades de difusi\u00f3n, capacitaci\u00f3n y de tr\u00e1mites.<\/p>\n<p>\u201cPara nosotros es sumamente relevante poder asistir con nuestros funcionarios a realizar estas actividades de acompa\u00f1amiento, sobre todo considerando la lejan\u00eda y dificultades para acceder de manera presencial a nuestra Direcci\u00f3n Regional ubicada en Puerto Ays\u00e9n, como tambi\u00e9n por la importancia que reviste el disponer de informaci\u00f3n, formularios y medios de atenci\u00f3n en la misma caleta, dada la brecha digital con la que se cuenta en estos territorios aislados\u201d, expres\u00f3 Jorge Padilla, Director Regional <span style=\"font-weight: 400;\"><b><span lang=\"ES-TRAD\"><strong><a href=\"https:\/\/www.mundoacuicola.cl\/medios\/?url_camp=26\" target=\"_blank\" rel=\"https:\/\/www.mundoacuicola.cl\/medios\/?url_camp=26 noopener\"><img decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.mundoacuicola.cl\/medios\/?camp=26\" alt=\"\" width=\"300\" height=\"250\" \/><\/a><\/strong><\/span><\/b><\/span>(s) de Sernapesca Ays\u00e9n.<\/p>\n<p>Dentro de las tem\u00e1ticas abordadas en la visita est\u00e1 la difusi\u00f3n de cuotas, vedas y periodos de extracci\u00f3n de los principales recursos de la zona; la inscripci\u00f3n y actualizaci\u00f3n de antecedentes del Registro Pesquero Artesanal; consultas por cambio de regi\u00f3n, sustituciones y reemplazos en el RPA; capacitaci\u00f3n en el uso de la plataforma online de Trazabilidad de Sernapesca y gesti\u00f3n de contrase\u00f1as; recepci\u00f3n de declaraciones de desembarque artesanal y entrega de saldos de cuota de merluza del sur en el marco del r\u00e9gimen artesanal de extracci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>funcionarios de Sernapesca se desplazaron hasta la localidad de Puerto Gala para realizar atenci\u00f3n en localidades aisladas de la regi\u00f3n.<\/p>\n","protected":false},"author":8,"featured_media":63128,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[89],"tags":[7675,15366,125,13854,9385],"class_list":["post-63127","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-instituciones","tag-pescadores-y-pescadoras","tag-puerto-gala","tag-sernapesca","tag-sernapesca-aysen","tag-servicio-nacional-de-pesca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Equipo de Sernapesca llega hasta Puerto Gala para realizar atenci\u00f3n en terreno a pescadores y pescadoras - Mundoacuicola<\/title>\n<meta name=\"description\" content=\"funcionarios de Sernapesca se desplazaron hasta la localidad de Puerto Gala para realizar atenci\u00f3n en localidades aisladas de la regi\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoacuicola.cl\/new\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Equipo de Sernapesca llega hasta Puerto Gala para realizar atenci\u00f3n en terreno a pescadores y pescadoras - Mundoacuicola\" \/>\n<meta property=\"og:description\" content=\"funcionarios de Sernapesca se desplazaron hasta la localidad de Puerto Gala para realizar atenci\u00f3n en localidades aisladas de la regi\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoacuicola.cl\/new\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoacuicola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.acuicola\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-02T09:10:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-03T13:04:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/05\/CaletaMasCerca.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ricardo Alvarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:site\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Alvarez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\\\/\"},\"author\":{\"name\":\"Ricardo Alvarez\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\"},\"headline\":\"Equipo de Sernapesca llega hasta Puerto Gala para realizar atenci\u00f3n en terreno a pescadores y pescadoras\",\"datePublished\":\"2024-05-02T09:10:53+00:00\",\"dateModified\":\"2024-05-03T13:04:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\\\/\"},\"wordCount\":316,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/CaletaMasCerca.jpeg\",\"keywords\":[\"pescadores y pescadoras\",\"Puerto Gala\",\"Sernapesca\",\"Sernapesca Ays\u00e9n\",\"Servicio Nacional de Pesca\"],\"articleSection\":[\"Instituciones\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\\\/\",\"name\":\"Equipo de Sernapesca llega hasta Puerto Gala para realizar atenci\u00f3n en terreno a pescadores y pescadoras - Mundoacuicola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/CaletaMasCerca.jpeg\",\"datePublished\":\"2024-05-02T09:10:53+00:00\",\"dateModified\":\"2024-05-03T13:04:45+00:00\",\"description\":\"funcionarios de Sernapesca se desplazaron hasta la localidad de Puerto Gala para realizar atenci\u00f3n en localidades aisladas de la regi\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/CaletaMasCerca.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/CaletaMasCerca.jpeg\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Equipo de Sernapesca llega hasta Puerto Gala para realizar atenci\u00f3n en terreno a pescadores y pescadoras\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"name\":\"Mundoacuicola\",\"description\":\"Revista de Acuicultura.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\",\"name\":\"Mundoacuicola\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"width\":1252,\"height\":296,\"caption\":\"Mundoacuicola\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.acuicola\\\/\",\"https:\\\/\\\/x.com\\\/mundoacuicola\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-acuicola\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\",\"name\":\"Ricardo Alvarez\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/author\\\/ricardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Equipo de Sernapesca llega hasta Puerto Gala para realizar atenci\u00f3n en terreno a pescadores y pescadoras - Mundoacuicola","description":"funcionarios de Sernapesca se desplazaron hasta la localidad de Puerto Gala para realizar atenci\u00f3n en localidades aisladas de la regi\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoacuicola.cl\/new\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\/","og_locale":"es_ES","og_type":"article","og_title":"Equipo de Sernapesca llega hasta Puerto Gala para realizar atenci\u00f3n en terreno a pescadores y pescadoras - Mundoacuicola","og_description":"funcionarios de Sernapesca se desplazaron hasta la localidad de Puerto Gala para realizar atenci\u00f3n en localidades aisladas de la regi\u00f3n.","og_url":"https:\/\/www.mundoacuicola.cl\/new\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\/","og_site_name":"Mundoacuicola","article_publisher":"https:\/\/www.facebook.com\/mundo.acuicola\/","article_published_time":"2024-05-02T09:10:53+00:00","article_modified_time":"2024-05-03T13:04:45+00:00","og_image":[{"width":750,"height":400,"url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/05\/CaletaMasCerca.jpeg","type":"image\/jpeg"}],"author":"Ricardo Alvarez","twitter_card":"summary_large_image","twitter_creator":"@mundoacuicola","twitter_site":"@mundoacuicola","twitter_misc":{"Escrito por":"Ricardo Alvarez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoacuicola.cl\/new\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\/#article","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\/"},"author":{"name":"Ricardo Alvarez","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd"},"headline":"Equipo de Sernapesca llega hasta Puerto Gala para realizar atenci\u00f3n en terreno a pescadores y pescadoras","datePublished":"2024-05-02T09:10:53+00:00","dateModified":"2024-05-03T13:04:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\/"},"wordCount":316,"publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/05\/CaletaMasCerca.jpeg","keywords":["pescadores y pescadoras","Puerto Gala","Sernapesca","Sernapesca Ays\u00e9n","Servicio Nacional de Pesca"],"articleSection":["Instituciones"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoacuicola.cl\/new\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\/","url":"https:\/\/www.mundoacuicola.cl\/new\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\/","name":"Equipo de Sernapesca llega hasta Puerto Gala para realizar atenci\u00f3n en terreno a pescadores y pescadoras - Mundoacuicola","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/05\/CaletaMasCerca.jpeg","datePublished":"2024-05-02T09:10:53+00:00","dateModified":"2024-05-03T13:04:45+00:00","description":"funcionarios de Sernapesca se desplazaron hasta la localidad de Puerto Gala para realizar atenci\u00f3n en localidades aisladas de la regi\u00f3n.","breadcrumb":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoacuicola.cl\/new\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\/#primaryimage","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/05\/CaletaMasCerca.jpeg","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/05\/CaletaMasCerca.jpeg","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoacuicola.cl\/new\/equipo-de-sernapesca-llega-hasta-puerto-gala-para-realizar-atencion-en-terreno-a-pescadores-y-pescadoras\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoacuicola.cl\/new\/"},{"@type":"ListItem","position":2,"name":"Equipo de Sernapesca llega hasta Puerto Gala para realizar atenci\u00f3n en terreno a pescadores y pescadoras"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoacuicola.cl\/new\/#website","url":"https:\/\/www.mundoacuicola.cl\/new\/","name":"Mundoacuicola","description":"Revista de Acuicultura.","publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoacuicola.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization","name":"Mundoacuicola","url":"https:\/\/www.mundoacuicola.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","width":1252,"height":296,"caption":"Mundoacuicola"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.acuicola\/","https:\/\/x.com\/mundoacuicola","https:\/\/www.linkedin.com\/in\/mundo-acuicola"]},{"@type":"Person","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd","name":"Ricardo Alvarez","url":"https:\/\/www.mundoacuicola.cl\/new\/author\/ricardo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/63127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/comments?post=63127"}],"version-history":[{"count":0,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/63127\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media\/63128"}],"wp:attachment":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media?parent=63127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/categories?post=63127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/tags?post=63127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}