{"id":65296,"date":"2024-07-09T13:49:10","date_gmt":"2024-07-09T16:49:10","guid":{"rendered":"https:\/\/www.mundoacuicola.cl\/new\/?p=65296"},"modified":"2024-07-11T08:42:39","modified_gmt":"2024-07-11T11:42:39","slug":"msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco","status":"publish","type":"post","link":"https:\/\/www.mundoacuicola.cl\/new\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\/","title":{"rendered":"MSD\u00a0Salud Animal completa la adquisici\u00f3n del negocio Aqua de Elanco"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><span lang=\"ES-PE\"><b><span lang=\"es-CL\"><span lang=\"ES-TRAD\"><a href=\"https:\/\/www.alloyingenieria.com\/\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-55815 size-full alignright\" src=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2023\/09\/Gif-Alloy.gif\" alt=\"\" width=\"300\" height=\"300\" \/><\/a><\/span><\/span><\/b><\/span>Como parte de su compromiso con la preservaci\u00f3n y mejora de la salud, el bienestar y el rendimiento de los animales y de las personas que los cuidan, MSD Salud Animal, una divisi\u00f3n de Merck &amp; Co., Inc., anunci\u00f3 hoy a nivel global, la finalizaci\u00f3n de la adquisici\u00f3n del negocio acu\u00edcola de Elanco Animal Health Incorporated.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esta integraci\u00f3n refuerza la posici\u00f3n de liderazgo de MSD Salud Animal en la industria acu\u00edcola. Con presencia en m\u00e1s de 50 pa\u00edses y productos disponibles en alrededor de 150 mercados, MSD Salud Animal invierte en recursos de I+D din\u00e1micos e integrales y cuenta con una cadena de suministro global y moderna.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cCon la finalizaci\u00f3n de esta adquisici\u00f3n, estamos bien posicionados para transformar la industria de la acuicultura con una cartera s\u00f3lida y completa que abarca agua tibia, agua fr\u00eda, vacunas, tratamientos antiparasitarios, suplementos de agua y nutrici\u00f3n\u201d, dijo Rick DeLuca, presidente de MSD Salud Animal. A su vez, DeLuca mencion\u00f3 que \u201cnos entusiasma dar la bienvenida a nuestros nuevos colegas a MSD Salud Animal y esperamos trabajar juntos, impulsados por nuestro prop\u00f3sito com\u00fan de la Ciencia de los Animales m\u00e1s Sanos\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El uso creciente de medicamentos y vacunas, nutrientes y suplementos para la industria acu\u00edcola, se ha visto impulsado por la alta demanda de prote\u00ednas y la seguridad alimentaria, lo que garantiza un suministro de alimentos de calidad y protege la salud p\u00fablica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"><strong><b><span lang=\"ES-TRAD\"><a href=\"https:\/\/www.mundoacuicola.cl\/medios\/?url_camp=26\" target=\"_blank\" rel=\"https:\/\/www.mundoacuicola.cl\/medios\/?url_camp=26 noopener\"><img decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.mundoacuicola.cl\/medios\/?camp=26\" alt=\"\" width=\"300\" height=\"250\" \/><\/a><\/span><\/b><\/strong>Como resultado de la fusi\u00f3n, MSD Salud Animal ahora posee productos innovadores como CLYNAV, una vacuna de nueva generaci\u00f3n basada en ADN que protege al salm\u00f3n del Atl\u00e1ntico contra la enfermedad del p\u00e1ncreas, e IMVIXA, un tratamiento antiparasitario contra los piojos de mar. Adem\u00e1s, la cartera de productos incluye tratamientos para el agua destinados a la producci\u00f3n en aguas c\u00e1lidas, completando as\u00ed la oferta de vacunas de MSD Salud Animal.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Con un enfoque claro en la ciencia y la tecnolog\u00eda, MSD Salud Animal se prepara para enfrentar los desaf\u00edos y aprovechar las oportunidades en la acuicultura global, contribuyendo al bienestar de los animales y las comunidades que dependen de ellos.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta integraci\u00f3n refuerza la posici\u00f3n de liderazgo de MSD Salud Animal en la industria acu\u00edcola.<\/p>\n","protected":false},"author":8,"featured_media":65297,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[143,19527,22472,22979,2997,4072,22976,5805,2926,159,22975,122,2907,22974,15402,419,1188,5419,6879,184,1357,2273,22471,137,197,10664,2644,22978,22977,897,1956],"class_list":["post-65296","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-acuicultura","tag-adquisicion","tag-cluster-del-salmon","tag-clynav","tag-coho","tag-cultivo","tag-elanco-animal-health-incorporated","tag-gente-del-salmon","tag-id","tag-imvixa","tag-inc","tag-industria-acuicola","tag-industria-salmonera","tag-merck-co","tag-msd-salud-animal","tag-nutricion","tag-ovas","tag-piojos-de-mar","tag-salar","tag-salmon","tag-salmon-atlantico","tag-salmon-chileno","tag-salmoneras-chilenas","tag-salmones","tag-salmonicultura","tag-sector-salmonero","tag-seguridad-alimentaria","tag-suplementos-de-agua","tag-tratamientos-antiparasitarios","tag-trucha","tag-vacunas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MSD\u00a0Salud Animal completa la adquisici\u00f3n del negocio Aqua de Elanco - Mundoacuicola<\/title>\n<meta name=\"description\" content=\"Esta integraci\u00f3n refuerza la posici\u00f3n de liderazgo de la empresa MSD Salud Animal en la industria acu\u00edcola.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoacuicola.cl\/new\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MSD\u00a0Salud Animal completa la adquisici\u00f3n del negocio Aqua de Elanco - Mundoacuicola\" \/>\n<meta property=\"og:description\" content=\"Esta integraci\u00f3n refuerza la posici\u00f3n de liderazgo de la empresa MSD Salud Animal en la industria acu\u00edcola.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoacuicola.cl\/new\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoacuicola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.acuicola\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-09T16:49:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-11T11:42:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/07\/MSDsaludAnimal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ricardo Alvarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:site\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Alvarez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\\\/\"},\"author\":{\"name\":\"Ricardo Alvarez\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\"},\"headline\":\"MSD\u00a0Salud Animal completa la adquisici\u00f3n del negocio Aqua de Elanco\",\"datePublished\":\"2024-07-09T16:49:10+00:00\",\"dateModified\":\"2024-07-11T11:42:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\\\/\"},\"wordCount\":382,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/MSDsaludAnimal.jpg\",\"keywords\":[\"Acuicultura\",\"adquisici\u00f3n\",\"Cl\u00faster del salm\u00f3n\",\"CLYNAV\",\"coho\",\"cultivo\",\"Elanco Animal Health Incorporated\",\"Gente del Salm\u00f3n\",\"I+D\",\"Imvixa\",\"Inc.\",\"Industria Acu\u00edcola\",\"Industria salmonera\",\"Merck &amp; Co.\",\"MSD Salud Animal\",\"Nutrici\u00f3n\",\"Ovas\",\"piojos de mar\",\"Salar\",\"Salm\u00f3n\",\"Salm\u00f3n Atl\u00e1ntico\",\"Salm\u00f3n chileno\",\"salmoneras chilenas\",\"salmones\",\"salmonicultura\",\"sector salmonero\",\"seguridad alimentaria\",\"suplementos de agua\",\"tratamientos antiparasitarios\",\"trucha\",\"vacunas\"],\"articleSection\":[\"Negocios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\\\/\",\"name\":\"MSD\u00a0Salud Animal completa la adquisici\u00f3n del negocio Aqua de Elanco - Mundoacuicola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/MSDsaludAnimal.jpg\",\"datePublished\":\"2024-07-09T16:49:10+00:00\",\"dateModified\":\"2024-07-11T11:42:39+00:00\",\"description\":\"Esta integraci\u00f3n refuerza la posici\u00f3n de liderazgo de la empresa MSD Salud Animal en la industria acu\u00edcola.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/MSDsaludAnimal.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/MSDsaludAnimal.jpg\",\"width\":750,\"height\":400,\"caption\":\"Aquaculture 13795 300dpi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MSD\u00a0Salud Animal completa la adquisici\u00f3n del negocio Aqua de Elanco\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"name\":\"Mundoacuicola\",\"description\":\"Revista de Acuicultura.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\",\"name\":\"Mundoacuicola\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"width\":1252,\"height\":296,\"caption\":\"Mundoacuicola\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.acuicola\\\/\",\"https:\\\/\\\/x.com\\\/mundoacuicola\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-acuicola\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\",\"name\":\"Ricardo Alvarez\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/author\\\/ricardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MSD\u00a0Salud Animal completa la adquisici\u00f3n del negocio Aqua de Elanco - Mundoacuicola","description":"Esta integraci\u00f3n refuerza la posici\u00f3n de liderazgo de la empresa MSD Salud Animal en la industria acu\u00edcola.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoacuicola.cl\/new\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\/","og_locale":"es_ES","og_type":"article","og_title":"MSD\u00a0Salud Animal completa la adquisici\u00f3n del negocio Aqua de Elanco - Mundoacuicola","og_description":"Esta integraci\u00f3n refuerza la posici\u00f3n de liderazgo de la empresa MSD Salud Animal en la industria acu\u00edcola.","og_url":"https:\/\/www.mundoacuicola.cl\/new\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\/","og_site_name":"Mundoacuicola","article_publisher":"https:\/\/www.facebook.com\/mundo.acuicola\/","article_published_time":"2024-07-09T16:49:10+00:00","article_modified_time":"2024-07-11T11:42:39+00:00","og_image":[{"width":750,"height":400,"url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/07\/MSDsaludAnimal.jpg","type":"image\/jpeg"}],"author":"Ricardo Alvarez","twitter_card":"summary_large_image","twitter_creator":"@mundoacuicola","twitter_site":"@mundoacuicola","twitter_misc":{"Escrito por":"Ricardo Alvarez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoacuicola.cl\/new\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\/#article","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\/"},"author":{"name":"Ricardo Alvarez","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd"},"headline":"MSD\u00a0Salud Animal completa la adquisici\u00f3n del negocio Aqua de Elanco","datePublished":"2024-07-09T16:49:10+00:00","dateModified":"2024-07-11T11:42:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\/"},"wordCount":382,"publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/07\/MSDsaludAnimal.jpg","keywords":["Acuicultura","adquisici\u00f3n","Cl\u00faster del salm\u00f3n","CLYNAV","coho","cultivo","Elanco Animal Health Incorporated","Gente del Salm\u00f3n","I+D","Imvixa","Inc.","Industria Acu\u00edcola","Industria salmonera","Merck &amp; Co.","MSD Salud Animal","Nutrici\u00f3n","Ovas","piojos de mar","Salar","Salm\u00f3n","Salm\u00f3n Atl\u00e1ntico","Salm\u00f3n chileno","salmoneras chilenas","salmones","salmonicultura","sector salmonero","seguridad alimentaria","suplementos de agua","tratamientos antiparasitarios","trucha","vacunas"],"articleSection":["Negocios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoacuicola.cl\/new\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\/","url":"https:\/\/www.mundoacuicola.cl\/new\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\/","name":"MSD\u00a0Salud Animal completa la adquisici\u00f3n del negocio Aqua de Elanco - Mundoacuicola","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/07\/MSDsaludAnimal.jpg","datePublished":"2024-07-09T16:49:10+00:00","dateModified":"2024-07-11T11:42:39+00:00","description":"Esta integraci\u00f3n refuerza la posici\u00f3n de liderazgo de la empresa MSD Salud Animal en la industria acu\u00edcola.","breadcrumb":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoacuicola.cl\/new\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\/#primaryimage","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/07\/MSDsaludAnimal.jpg","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/07\/MSDsaludAnimal.jpg","width":750,"height":400,"caption":"Aquaculture 13795 300dpi"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoacuicola.cl\/new\/msd-salud-animal-completa-la-adquisicion-del-negocio-aqua-de-elanco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoacuicola.cl\/new\/"},{"@type":"ListItem","position":2,"name":"MSD\u00a0Salud Animal completa la adquisici\u00f3n del negocio Aqua de Elanco"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoacuicola.cl\/new\/#website","url":"https:\/\/www.mundoacuicola.cl\/new\/","name":"Mundoacuicola","description":"Revista de Acuicultura.","publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoacuicola.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization","name":"Mundoacuicola","url":"https:\/\/www.mundoacuicola.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","width":1252,"height":296,"caption":"Mundoacuicola"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.acuicola\/","https:\/\/x.com\/mundoacuicola","https:\/\/www.linkedin.com\/in\/mundo-acuicola"]},{"@type":"Person","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd","name":"Ricardo Alvarez","url":"https:\/\/www.mundoacuicola.cl\/new\/author\/ricardo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/65296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/comments?post=65296"}],"version-history":[{"count":0,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/65296\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media\/65297"}],"wp:attachment":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media?parent=65296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/categories?post=65296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/tags?post=65296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}