{"id":66723,"date":"2024-08-21T06:35:08","date_gmt":"2024-08-21T09:35:08","guid":{"rendered":"https:\/\/www.mundoacuicola.cl\/new\/?p=66723"},"modified":"2024-08-22T09:32:52","modified_gmt":"2024-08-22T12:32:52","slug":"mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt","status":"publish","type":"post","link":"https:\/\/www.mundoacuicola.cl\/new\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\/","title":{"rendered":"Mundo Acu\u00edcola estrena nueva oficina en el centro de Puerto Montt"},"content":{"rendered":"<p><span style=\"font-weight: 400;\"><span lang=\"ES-PE\"><b><span lang=\"es-CL\"><span lang=\"ES-TRAD\"><a href=\"https:\/\/www.alloyingenieria.com\/\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignright wp-image-66753 \" src=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/08\/4d9dcfdc-cbd4-4003-98e0-998b7871d693-1-400x400.jpeg\" alt=\"\" width=\"261\" height=\"261\" srcset=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/08\/4d9dcfdc-cbd4-4003-98e0-998b7871d693-1-400x400.jpeg 400w, https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/08\/4d9dcfdc-cbd4-4003-98e0-998b7871d693-1-300x300.jpeg 300w, https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/08\/4d9dcfdc-cbd4-4003-98e0-998b7871d693-1-100x100.jpeg 100w, https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/08\/4d9dcfdc-cbd4-4003-98e0-998b7871d693-1-500x500.jpeg 500w, https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/08\/4d9dcfdc-cbd4-4003-98e0-998b7871d693-1-225x225.jpeg 225w, https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/08\/4d9dcfdc-cbd4-4003-98e0-998b7871d693-1.jpeg 700w\" sizes=\"(max-width: 261px) 100vw, 261px\" \/><\/a><\/span><\/span><\/b><\/span><\/span>Con el objetivo de estar m\u00e1s cerca de los actores clave de la industria y la agenda de actividades vinculadas al sector desarrolladas en Puerto Montt, Mundo Acu\u00edcola ha inaugurado recientemente sus nuevas oficinas en el edificio \u00abDo\u00f1a Encarnaci\u00f3n\u00bb, ubicado en Concepci\u00f3n 120, en pleno centro de la capital regional.<\/p>\n<p>El director de Mundo Acu\u00edcola, Claudio Berkhoff, expres\u00f3 su entusiasmo ante esta nueva etapa para el medio: \u00abEsta inauguraci\u00f3n marca un hito importante en nuestra trayectoria, pues implica la incorporaci\u00f3n de nuevos profesionales al medio. Con ello, potenciaremos nuestra misi\u00f3n de seguir informando sobre las novedades de los<\/p>\n<h2><strong><span style=\"font-weight: 400;\"><b><span lang=\"ES-TRAD\"><a href=\"https:\/\/www.mundoacuicola.cl\/medios\/?url_camp=26\" target=\"_blank\" rel=\"https:\/\/www.mundoacuicola.cl\/medios\/?url_camp=26 noopener\"><img decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.mundoacuicola.cl\/medios\/?camp=26\" alt=\"\" width=\"300\" height=\"250\" \/><\/a><\/span><\/b><\/span><\/strong><\/h2>\n<p>sector de la salmonicultura, mitilicultura, pesca, mar\u00edtimo y medioambiente.\u00bb<\/p>\n<p>Con la apertura de esta oficina, Mundo Acu\u00edcola busca no solo estar presente en la agenda de actividades del sector, entendiendo que Puerto Montt es el epicentro log\u00edstico de la actividad acu\u00edcola, sino tambi\u00e9n establecer un punto de encuentro con colaboradores, empresas y trabajadores del sector.<\/p>\n<p>\u00abInvitamos a todos los actores de la industria, desde las empresas y gremios hasta los trabajadores, a visitar nuestras oficinas. Queremos abrir un espacio para el di\u00e1logo, realizar entrevistas y fomentar la colaboraci\u00f3n que nos permita seguir aportando al desarrollo sostenible de la acuicultura en Chile\u00bb, concluy\u00f3 Berkhoff.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la apertura de esta oficina, Mundo Acu\u00edcola busca no solo estar presente en la agenda de actividades del sector, entendiendo que Puerto Montt es el epicentro log\u00edstico de la actividad acu\u00edcola, sino tambi\u00e9n establecer un punto de encuentro con colaboradores, empresas y trabajadores del sector.<\/p>\n","protected":false},"author":8,"featured_media":66724,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[6165,9606,122,449,353,109,23452,206,197,7306],"class_list":["post-66723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios","tag-colaboracion","tag-desarrollo-sostenible","tag-industria-acuicola","tag-medioambiente","tag-mitilicultura","tag-mundo-acuicola","tag-oficinas-en-puerto-montt","tag-pesca","tag-salmonicultura","tag-sector-acuicola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mundo Acu\u00edcola estrena nueva oficina en el centro de Puerto Montt - Mundoacuicola<\/title>\n<meta name=\"description\" content=\"Con la apertura de esta oficina, Mundo Acu\u00edcola busca establecer un punto de encuentro con colaboradores, empresas y trabajadores del sector.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoacuicola.cl\/new\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mundo Acu\u00edcola estrena nueva oficina en el centro de Puerto Montt - Mundoacuicola\" \/>\n<meta property=\"og:description\" content=\"Con la apertura de esta oficina, Mundo Acu\u00edcola busca establecer un punto de encuentro con colaboradores, empresas y trabajadores del sector.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoacuicola.cl\/new\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoacuicola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.acuicola\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-21T09:35:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-22T12:32:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/08\/NuevasOficinasMundo.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ricardo Alvarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:site\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Alvarez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\\\/\"},\"author\":{\"name\":\"Ricardo Alvarez\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\"},\"headline\":\"Mundo Acu\u00edcola estrena nueva oficina en el centro de Puerto Montt\",\"datePublished\":\"2024-08-21T09:35:08+00:00\",\"dateModified\":\"2024-08-22T12:32:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\\\/\"},\"wordCount\":228,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/NuevasOficinasMundo.jpeg\",\"keywords\":[\"colaboraci\u00f3n\",\"Desarrollo Sostenible\",\"Industria Acu\u00edcola\",\"Medioambiente\",\"mitilicultura\",\"Mundo Acu\u00edcola\",\"oficinas en Puerto Montt\",\"Pesca\",\"salmonicultura\",\"sector acu\u00edcola\"],\"articleSection\":[\"Negocios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\\\/\",\"name\":\"Mundo Acu\u00edcola estrena nueva oficina en el centro de Puerto Montt - Mundoacuicola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/NuevasOficinasMundo.jpeg\",\"datePublished\":\"2024-08-21T09:35:08+00:00\",\"dateModified\":\"2024-08-22T12:32:52+00:00\",\"description\":\"Con la apertura de esta oficina, Mundo Acu\u00edcola busca establecer un punto de encuentro con colaboradores, empresas y trabajadores del sector.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/NuevasOficinasMundo.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/NuevasOficinasMundo.jpeg\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mundo Acu\u00edcola estrena nueva oficina en el centro de Puerto Montt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"name\":\"Mundoacuicola\",\"description\":\"Revista de Acuicultura.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\",\"name\":\"Mundoacuicola\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"width\":1252,\"height\":296,\"caption\":\"Mundoacuicola\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.acuicola\\\/\",\"https:\\\/\\\/x.com\\\/mundoacuicola\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-acuicola\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\",\"name\":\"Ricardo Alvarez\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/author\\\/ricardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mundo Acu\u00edcola estrena nueva oficina en el centro de Puerto Montt - Mundoacuicola","description":"Con la apertura de esta oficina, Mundo Acu\u00edcola busca establecer un punto de encuentro con colaboradores, empresas y trabajadores del sector.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoacuicola.cl\/new\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\/","og_locale":"es_ES","og_type":"article","og_title":"Mundo Acu\u00edcola estrena nueva oficina en el centro de Puerto Montt - Mundoacuicola","og_description":"Con la apertura de esta oficina, Mundo Acu\u00edcola busca establecer un punto de encuentro con colaboradores, empresas y trabajadores del sector.","og_url":"https:\/\/www.mundoacuicola.cl\/new\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\/","og_site_name":"Mundoacuicola","article_publisher":"https:\/\/www.facebook.com\/mundo.acuicola\/","article_published_time":"2024-08-21T09:35:08+00:00","article_modified_time":"2024-08-22T12:32:52+00:00","og_image":[{"width":750,"height":400,"url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/08\/NuevasOficinasMundo.jpeg","type":"image\/jpeg"}],"author":"Ricardo Alvarez","twitter_card":"summary_large_image","twitter_creator":"@mundoacuicola","twitter_site":"@mundoacuicola","twitter_misc":{"Escrito por":"Ricardo Alvarez","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoacuicola.cl\/new\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\/#article","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\/"},"author":{"name":"Ricardo Alvarez","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd"},"headline":"Mundo Acu\u00edcola estrena nueva oficina en el centro de Puerto Montt","datePublished":"2024-08-21T09:35:08+00:00","dateModified":"2024-08-22T12:32:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\/"},"wordCount":228,"publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/08\/NuevasOficinasMundo.jpeg","keywords":["colaboraci\u00f3n","Desarrollo Sostenible","Industria Acu\u00edcola","Medioambiente","mitilicultura","Mundo Acu\u00edcola","oficinas en Puerto Montt","Pesca","salmonicultura","sector acu\u00edcola"],"articleSection":["Negocios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoacuicola.cl\/new\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\/","url":"https:\/\/www.mundoacuicola.cl\/new\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\/","name":"Mundo Acu\u00edcola estrena nueva oficina en el centro de Puerto Montt - Mundoacuicola","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/08\/NuevasOficinasMundo.jpeg","datePublished":"2024-08-21T09:35:08+00:00","dateModified":"2024-08-22T12:32:52+00:00","description":"Con la apertura de esta oficina, Mundo Acu\u00edcola busca establecer un punto de encuentro con colaboradores, empresas y trabajadores del sector.","breadcrumb":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoacuicola.cl\/new\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\/#primaryimage","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/08\/NuevasOficinasMundo.jpeg","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/08\/NuevasOficinasMundo.jpeg","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoacuicola.cl\/new\/mundo-acuicola-estrena-nueva-oficina-en-el-centro-de-puerto-montt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoacuicola.cl\/new\/"},{"@type":"ListItem","position":2,"name":"Mundo Acu\u00edcola estrena nueva oficina en el centro de Puerto Montt"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoacuicola.cl\/new\/#website","url":"https:\/\/www.mundoacuicola.cl\/new\/","name":"Mundoacuicola","description":"Revista de Acuicultura.","publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoacuicola.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization","name":"Mundoacuicola","url":"https:\/\/www.mundoacuicola.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","width":1252,"height":296,"caption":"Mundoacuicola"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.acuicola\/","https:\/\/x.com\/mundoacuicola","https:\/\/www.linkedin.com\/in\/mundo-acuicola"]},{"@type":"Person","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd","name":"Ricardo Alvarez","url":"https:\/\/www.mundoacuicola.cl\/new\/author\/ricardo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/66723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/comments?post=66723"}],"version-history":[{"count":0,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/66723\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media\/66724"}],"wp:attachment":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media?parent=66723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/categories?post=66723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/tags?post=66723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}