{"id":69339,"date":"2024-10-23T10:38:14","date_gmt":"2024-10-23T14:38:14","guid":{"rendered":"https:\/\/www.mundoacuicola.cl\/new\/?p=69339"},"modified":"2024-10-24T12:22:55","modified_gmt":"2024-10-24T16:22:55","slug":"iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca","status":"publish","type":"post","link":"https:\/\/www.mundoacuicola.cl\/new\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\/","title":{"rendered":"Iron Women: Mujeres del Biob\u00edo realizar\u00e1n su pr\u00e1ctica de conductoras profesionales en Camanchaca"},"content":{"rendered":"<div>M\u00e1s de 214 mujeres interesadas en convertirse en conductoras profesionales de camiones y veh\u00edculos de carga pesada se han beneficiado por el programa Iron\u00a0Women, impulsado por Volvo Chile y ChileTransporte AG, iniciativa que busca fomentar la inserci\u00f3n laboral y equidad de g\u00e9nero en el sector del transporte.<\/div>\n<div><\/div>\n<div>\n<h2><strong><span style=\"font-weight: 400;\"><b><span lang=\"ES-TRAD\"><a href=\"https:\/\/www.mundoacuicola.cl\/medios\/?url_camp=26\" target=\"_blank\" rel=\"https:\/\/www.mundoacuicola.cl\/medios\/?url_camp=26 noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignleft\" src=\"https:\/\/www.mundoacuicola.cl\/medios\/?camp=26\" alt=\"\" width=\"300\" height=\"250\" \/><\/a><\/span><\/b><\/span><\/strong><\/h2>\n<p>Las participantes del programa fueron capacitadas con cursos de conducci\u00f3n, de las cuales 12 fueron seleccionadas para realizar su pr\u00e1ctica profesional en empresas asociadas del sector, entre ellas Interpolar de Camanchaca, obteniendo la oportunidad de integrarse a diferentes \u00e1reas de la empresa, incluyendo operaciones de log\u00edstica y conducci\u00f3n de veh\u00edculos de carga pesada.<\/p><\/div>\n<div><\/div>\n<div>\n<p>A trav\u00e9s del programa Iron Women, Camanchaca resalta su compromiso con la diversidad y la inclusi\u00f3n en todos los \u00e1mbitos de su operaci\u00f3n, reconociendo el valor que la equidad de g\u00e9nero aporta al equipo y a la industria.<\/p>\n<p><a href=\"https:\/\/www.canal9.cl\/episodios\/nuestra-casa\/2024\/10\/23\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.canal9.cl\/episodios\/nuestra-casa\/2024\/10\/23\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca&amp;source=gmail&amp;ust=1729818663525000&amp;usg=AOvVaw0MK3d_c09i0FGT605JdigT\"><b>https:\/\/www.canal9.cl\/<wbr \/>episodios\/nuestra-casa\/2024\/<wbr \/>10\/23\/iron-women-mujeres-del-<wbr \/>biobio-realizaran-su-practica-<wbr \/>de-conductoras-profesionales-<wbr \/>en-camanchaca<\/b><\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 214 mujeres interesadas en convertirse en conductoras profesionales de camiones y veh\u00edculos de&#8230;<\/p>\n","protected":false},"author":8,"featured_media":69340,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-69339","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-negocios"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Iron Women: Mujeres del Biob\u00edo realizar\u00e1n su pr\u00e1ctica de conductoras profesionales en Camanchaca - Mundoacuicola<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoacuicola.cl\/new\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Iron Women: Mujeres del Biob\u00edo realizar\u00e1n su pr\u00e1ctica de conductoras profesionales en Camanchaca - Mundoacuicola\" \/>\n<meta property=\"og:description\" content=\"M\u00e1s de 214 mujeres interesadas en convertirse en conductoras profesionales de camiones y veh\u00edculos de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoacuicola.cl\/new\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoacuicola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.acuicola\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-23T14:38:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-24T16:22:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/10\/Mujeres1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ricardo Alvarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:site\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Alvarez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\\\/\"},\"author\":{\"name\":\"Ricardo Alvarez\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\"},\"headline\":\"Iron Women: Mujeres del Biob\u00edo realizar\u00e1n su pr\u00e1ctica de conductoras profesionales en Camanchaca\",\"datePublished\":\"2024-10-23T14:38:14+00:00\",\"dateModified\":\"2024-10-24T16:22:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\\\/\"},\"wordCount\":173,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Mujeres1-1.jpg\",\"articleSection\":[\"Negocios\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\\\/\",\"name\":\"Iron Women: Mujeres del Biob\u00edo realizar\u00e1n su pr\u00e1ctica de conductoras profesionales en Camanchaca - Mundoacuicola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Mujeres1-1.jpg\",\"datePublished\":\"2024-10-23T14:38:14+00:00\",\"dateModified\":\"2024-10-24T16:22:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Mujeres1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Mujeres1-1.jpg\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Iron Women: Mujeres del Biob\u00edo realizar\u00e1n su pr\u00e1ctica de conductoras profesionales en Camanchaca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"name\":\"Mundoacuicola\",\"description\":\"Revista de Acuicultura.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\",\"name\":\"Mundoacuicola\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"width\":1252,\"height\":296,\"caption\":\"Mundoacuicola\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.acuicola\\\/\",\"https:\\\/\\\/x.com\\\/mundoacuicola\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-acuicola\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\",\"name\":\"Ricardo Alvarez\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/author\\\/ricardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Iron Women: Mujeres del Biob\u00edo realizar\u00e1n su pr\u00e1ctica de conductoras profesionales en Camanchaca - Mundoacuicola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoacuicola.cl\/new\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\/","og_locale":"es_ES","og_type":"article","og_title":"Iron Women: Mujeres del Biob\u00edo realizar\u00e1n su pr\u00e1ctica de conductoras profesionales en Camanchaca - Mundoacuicola","og_description":"M\u00e1s de 214 mujeres interesadas en convertirse en conductoras profesionales de camiones y veh\u00edculos de...","og_url":"https:\/\/www.mundoacuicola.cl\/new\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\/","og_site_name":"Mundoacuicola","article_publisher":"https:\/\/www.facebook.com\/mundo.acuicola\/","article_published_time":"2024-10-23T14:38:14+00:00","article_modified_time":"2024-10-24T16:22:55+00:00","og_image":[{"width":750,"height":400,"url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/10\/Mujeres1-1.jpg","type":"image\/jpeg"}],"author":"Ricardo Alvarez","twitter_card":"summary_large_image","twitter_creator":"@mundoacuicola","twitter_site":"@mundoacuicola","twitter_misc":{"Escrito por":"Ricardo Alvarez","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoacuicola.cl\/new\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\/#article","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\/"},"author":{"name":"Ricardo Alvarez","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd"},"headline":"Iron Women: Mujeres del Biob\u00edo realizar\u00e1n su pr\u00e1ctica de conductoras profesionales en Camanchaca","datePublished":"2024-10-23T14:38:14+00:00","dateModified":"2024-10-24T16:22:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\/"},"wordCount":173,"publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/10\/Mujeres1-1.jpg","articleSection":["Negocios"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoacuicola.cl\/new\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\/","url":"https:\/\/www.mundoacuicola.cl\/new\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\/","name":"Iron Women: Mujeres del Biob\u00edo realizar\u00e1n su pr\u00e1ctica de conductoras profesionales en Camanchaca - Mundoacuicola","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/10\/Mujeres1-1.jpg","datePublished":"2024-10-23T14:38:14+00:00","dateModified":"2024-10-24T16:22:55+00:00","breadcrumb":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoacuicola.cl\/new\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\/#primaryimage","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/10\/Mujeres1-1.jpg","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2024\/10\/Mujeres1-1.jpg","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoacuicola.cl\/new\/iron-women-mujeres-del-biobio-realizaran-su-practica-de-conductoras-profesionales-en-camanchaca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoacuicola.cl\/new\/"},{"@type":"ListItem","position":2,"name":"Iron Women: Mujeres del Biob\u00edo realizar\u00e1n su pr\u00e1ctica de conductoras profesionales en Camanchaca"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoacuicola.cl\/new\/#website","url":"https:\/\/www.mundoacuicola.cl\/new\/","name":"Mundoacuicola","description":"Revista de Acuicultura.","publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoacuicola.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization","name":"Mundoacuicola","url":"https:\/\/www.mundoacuicola.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","width":1252,"height":296,"caption":"Mundoacuicola"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.acuicola\/","https:\/\/x.com\/mundoacuicola","https:\/\/www.linkedin.com\/in\/mundo-acuicola"]},{"@type":"Person","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd","name":"Ricardo Alvarez","url":"https:\/\/www.mundoacuicola.cl\/new\/author\/ricardo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/69339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/comments?post=69339"}],"version-history":[{"count":0,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/69339\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media\/69340"}],"wp:attachment":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media?parent=69339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/categories?post=69339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/tags?post=69339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}