{"id":75224,"date":"2025-04-23T04:28:47","date_gmt":"2025-04-23T08:28:47","guid":{"rendered":"https:\/\/www.mundoacuicola.cl\/new\/?p=75224"},"modified":"2025-08-29T12:15:30","modified_gmt":"2025-08-29T16:15:30","slug":"conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump","status":"publish","type":"post","link":"https:\/\/www.mundoacuicola.cl\/new\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\/","title":{"rendered":"Conozca a los expertos que asesorar\u00e1n al Gobierno ante aranceles de Trump"},"content":{"rendered":"<p>El Consejo de Alto Nivel para la Respuesta Estrat\u00e9gica de Pol\u00edtica Econ\u00f3mica y Financiera Internacional (CPEFI), encabezado por el Presidente de la Rep\u00fablica Gabriel Boric, es el organismo que el Gobierno ha conformado para enfrentar la guerra comercial y los desaf\u00edos y oportunidades que se presentan para Chile en el \u00e1mbito econ\u00f3mico internacional.<\/p>\n<p>Las principales tareas de este consejo, que tendr\u00e1 una duraci\u00f3n de seis meses, ser\u00e1n realizar un diagn\u00f3stico de la situaci\u00f3n econ\u00f3mica internacional y buscar nuevas oportunidades de inversi\u00f3n y acciones que mitiguen el impacto de los aranceles.<\/p>\n<p>\u201cEl objetivo es hacer todos los esfuerzos por mitigar el impacto de la actual coyuntura en el sector exportador\u201d, asegur\u00f3 el Jefe de Estado, Gabriel Boric, destacando el car\u00e1cter transversal de esta iniciativa: \u201cEs una se\u00f1al de certidumbre de largo plazo el que seamos capaces de sentarnos en la mesa diferentes personalidades del mundo pol\u00edtico y acad\u00e9mico vinculado a centros de estudios de diferentes ideas pol\u00edticas, porque compartimos una visi\u00f3n de largo plazo respecto a Chile\u201d.<\/p>\n<p>Y agreg\u00f3: \u201cEste espacio es importante porque hay que actuar con unidad nacional, con visi\u00f3n de futuro con el objetivo de proteger los intereses de Chile en el mundo\u201d.<\/p>\n<h3 dir=\"&quot;&quot;&quot;ltr&quot;&quot;&quot;\"><span id=\"&quot;&quot;&quot;docs-internal-guid-5969fbbc-7fff-c851-5863-4e196f0fe426&quot;&quot;&quot;\">Reducir la incertidumbre<\/span><\/h3>\n<p dir=\"&quot;&quot;&quot;ltr&quot;&quot;&quot;\"><span id=\"&quot;&quot;&quot;docs-internal-guid-5969fbbc-7fff-c851-5863-4e196f0fe426&quot;&quot;&quot;\">El ministro de Hacienda, Mario Marcel, afirm\u00f3 que \u201ccontar con una estrategia es un paso fundamental para poder reducir la incertidumbre, acortar los escenarios y ordenar las decisiones del Gobierno. El escenario de guerra comercial de proteccionismo en el mundo es una amenaza muy importante a la econom\u00eda global y particularmente a las perspectivas para Chile. No es una amenaza inminente, pero s\u00ed implica un riesgo para nuestro crecimiento futuro, para la estabilidad de los mercados internacionales. En esta reuni\u00f3n hemos convocado un grupo de 18 personas, todos con amplia experiencia en temas comerciales, econ\u00f3micos y financieros, con quienes iremos consultando las acciones dentro de la estrategia para enfrentar este escenario internacional\u201d.<\/span><\/p>\n<h3 dir=\"&quot;&quot;&quot;ltr&quot;&quot;&quot;\">Integrantes<\/h3>\n<h4 data-start=\"170\" data-end=\"460\"><strong data-start=\"170\" data-end=\"189\">Roberto \u00c1lvarez<\/strong><\/h4>\n<p data-start=\"170\" data-end=\"460\">Acad\u00e9mico de la Universidad de Chile, ha liderado el Departamento de Econom\u00eda y la Escuela de Econom\u00eda y Administraci\u00f3n de la misma casa de estudios. Su trabajo se centra en la productividad, el comercio y la innovaci\u00f3n tecnol\u00f3gica, con \u00e9nfasis en el contexto chileno.<\/p>\n<h4 data-start=\"462\" data-end=\"745\"><strong>Alejandro Jara<\/strong><\/h4>\n<p class=\"\" data-start=\"462\" data-end=\"745\">Con una destacada trayectoria internacional, fue director general adjunto de la Organizaci\u00f3n Mundial del Comercio (OMC) y represent\u00f3 a Chile ante dicho organismo. Adem\u00e1s, lider\u00f3 DIRECON y ha participado en negociaciones comerciales durante m\u00e1s de cuatro d\u00e9cadas.<\/p>\n<h4 data-start=\"747\" data-end=\"1013\"><strong data-start=\"747\" data-end=\"766\">Ignacio Briones<\/strong><\/h4>\n<p class=\"\" data-start=\"747\" data-end=\"1013\">Fue ministro de Hacienda y tambi\u00e9n embajador ante la OCDE. Actualmente dirige la Escuela de Gobierno de la Universidad Adolfo Ib\u00e1\u00f1ez y preside el centro Horizontal. Compagina su rol acad\u00e9mico con funciones como consultor y director de empresas.<\/p>\n<h4 data-start=\"1015\" data-end=\"1304\">Dorothea L\u00f3pez<\/h4>\n<p class=\"\" data-start=\"1015\" data-end=\"1304\">Profesora y directora del Instituto de Estudios Internacionales de la Universidad de Chile, investiga temas vinculados al comercio internacional, g\u00e9nero y servicios. Tambi\u00e9n ha analizado la percepci\u00f3n ciudadana sobre tratados de libre comercio y la relaci\u00f3n con China.<\/p>\n<h4 data-start=\"1306\" data-end=\"1601\">Jos\u00e9 De Gregorio<\/h4>\n<p class=\"\" data-start=\"1306\" data-end=\"1601\">Economista de perfil internacional, ha sido asesor del Banco Mundial y del FMI, y presidi\u00f3 el Banco Central de Chile. Tambi\u00e9n se desempe\u00f1\u00f3 como ministro de Econom\u00eda, Miner\u00eda y Energ\u00eda. Actualmente es decano de la Facultad de Econom\u00eda y Negocios de la Universidad de Chile.<\/p>\n<h4 data-start=\"1603\" data-end=\"1872\"><strong data-start=\"1603\" data-end=\"1622\">Osvaldo Rosales<\/strong><\/h4>\n<p class=\"\" data-start=\"1603\" data-end=\"1872\">Exdirector de Comercio Internacional de la CEPAL y exdirector general de DIRECON. Fue negociador principal de los tratados de libre comercio con Estados Unidos, la Uni\u00f3n Europea, Corea del Sur y EFTA, as\u00ed como de los inicios del acuerdo con China.<\/p>\n<h4 data-start=\"1874\" data-end=\"2160\"><strong data-start=\"1874\" data-end=\"1892\">Antonio Walker<\/strong><\/h4>\n<p class=\"\" data-start=\"1874\" data-end=\"2160\">Preside la Sociedad Nacional de Agricultura y ha estado estrechamente ligado al sector frut\u00edcola como cofundador de Frus\u00e9ptima y Frumanova. Fue ministro de Agricultura y tambi\u00e9n lider\u00f3 Fedefruta, consolidando su experiencia en pol\u00edtica y producci\u00f3n agroalimentaria.<\/p>\n<h4 data-start=\"2162\" data-end=\"2464\"><strong data-start=\"2162\" data-end=\"2180\">Patricio Rojas<\/strong><\/h4>\n<p class=\"\" data-start=\"2162\" data-end=\"2464\">Economista y consultor, ha sido gerente del Banco Central e integrante de la Comisi\u00f3n Resolutiva Antimonopolios y la Comisi\u00f3n de Distorsiones. Es socio de Rojas, Jim\u00e9nez &amp; Asociados, y ha sido decano en la Universidad Finis Terrae, adem\u00e1s de consultor de organismos multilaterales.<\/p>\n<h4 data-start=\"2466\" data-end=\"2724\"><strong data-start=\"2466\" data-end=\"2484\">Andr\u00e9s Velasco<\/strong><\/h4>\n<p class=\"\" data-start=\"2466\" data-end=\"2724\">Fue ministro de Hacienda y actualmente es decano de la Escuela de Pol\u00edticas P\u00fablicas de la London School of Economics (LSE). Ha sido acad\u00e9mico en Columbia, Harvard y NYU, y consultor para el FMI, Banco Mundial, BID y distintos gobiernos.<\/p>\n<h4 data-start=\"2726\" data-end=\"2990\"><strong data-start=\"2726\" data-end=\"2743\">Rodrigo Y\u00e1\u00f1ez<\/strong><\/h4>\n<p class=\"\" data-start=\"2726\" data-end=\"2990\">Fue el primer Subsecretario de Relaciones Econ\u00f3micas Internacionales y director general de DIRECON. Lider\u00f3 procesos de modernizaci\u00f3n de tratados comerciales y negociaciones bilaterales, consolidando el rol de Chile en la red global de acuerdos.<\/p>\n<h4 data-start=\"2992\" data-end=\"3214\"><strong data-start=\"2992\" data-end=\"3011\">Sebasti\u00e1n Claro<\/strong><\/h4>\n<p class=\"\" data-start=\"2992\" data-end=\"3214\">Exconsejero y vicepresidente del Banco Central de Chile, se desempe\u00f1a como acad\u00e9mico en la Universidad de los Andes. Es especialista en econom\u00eda internacional, con foco en China y mercados emergentes.<\/p>\n<h4 data-start=\"3216\" data-end=\"3473\"><strong data-start=\"3216\" data-end=\"3236\">Kathleen Barclay<\/strong><\/h4>\n<p class=\"\" data-start=\"3216\" data-end=\"3473\">Economista formada en Georgetown, fue ejecutiva por 23 a\u00f1os en J.P. Morgan Chase en Nueva York, Londres y Santiago. Es directora y expresidenta del directorio de AmCham Chile, adem\u00e1s de consejera del Centro de Estudios P\u00fablicos (CEP).<\/p>\n<h4 data-start=\"3475\" data-end=\"3797\"><strong data-start=\"3475\" data-end=\"3490\">Mario Matus<\/strong><\/h4>\n<p class=\"\" data-start=\"3475\" data-end=\"3797\">Diplom\u00e1tico y acad\u00e9mico del Heidelberg Center, fue director general adjunto de la Organizaci\u00f3n Mundial de la Propiedad Intelectual (OMPI) y embajador ante OMC, OMPI y UNCTAD. Particip\u00f3 activamente en negociaciones de tratados de libre comercio con Estados Unidos, China, Corea del Sur y la Uni\u00f3n Europea.<\/p>\n<h4 data-start=\"3799\" data-end=\"4094\"><strong data-start=\"3799\" data-end=\"3815\">Nicole Nehme<\/strong><\/h4>\n<p class=\"\" data-start=\"3799\" data-end=\"4094\">Abogada experta en derecho econ\u00f3mico, libre competencia y regulaci\u00f3n. Es socia fundadora del estudio Ferrada Nehme, acad\u00e9mica de la Universidad de Chile y asesora de organismos multilaterales y empresas multinacionales. Reconocida por su trayectoria y publicaciones jur\u00eddicas.<\/p>\n<h4 data-start=\"4096\" data-end=\"4451\"><strong data-start=\"4096\" data-end=\"4117\">Ra\u00fal Eduardo S\u00e1ez<\/strong><\/h4>\n<p class=\"\" data-start=\"4096\" data-end=\"4451\">Investigador senior de Cieplan y acad\u00e9mico en la Universidad de Talca, coordin\u00f3 el programa Cieplan-UTalca. Represent\u00f3 a Chile ante la OCDE entre 2011 y 2013 y fue director de Asuntos Internacionales del Ministerio de Hacienda entre 2000 y 2010, participando en la negociaci\u00f3n de todos los tratados de libre comercio de esa d\u00e9cada.<\/p>\n<h4 data-start=\"4453\" data-end=\"4720\"><strong data-start=\"4453\" data-end=\"4469\">Pablo Garc\u00eda<\/strong><\/h4>\n<p class=\"\" data-start=\"4453\" data-end=\"4720\">Fue vicepresidente y consejero del Banco Central de Chile. Se desempe\u00f1\u00f3 como director ejecutivo y alterno por el Cono Sur ante el FMI, donde adem\u00e1s presidi\u00f3 el Comit\u00e9 de \u00c9tica del Directorio. Actualmente es profesor en la Universidad Adolfo Ib\u00e1\u00f1ez.<\/p>\n<h4 data-start=\"4722\" data-end=\"5008\"><strong data-start=\"4722\" data-end=\"4740\">Vittorio Corbo<\/strong><\/h4>\n<p class=\"\" data-start=\"4722\" data-end=\"5008\">Economista de vasta trayectoria, fue presidente del Banco Central de Chile. Ha trabajado en el Fondo Monetario Internacional y el Banco Mundial. En la actualidad, es consultor, director de empresas y miembro del Centro de Estudios P\u00fablicos como investigador s\u00e9nior.<\/p>\n<h4 data-start=\"5010\" data-end=\"5312\"><strong data-start=\"5010\" data-end=\"5031\">Sebasti\u00e1n Edwards<\/strong><\/h4>\n<p class=\"\" data-start=\"5010\" data-end=\"5312\">Economista y acad\u00e9mico chileno, es profesor Henry Ford II en la Universidad de California en Los \u00c1ngeles (UCLA). Fue economista jefe para Am\u00e9rica Latina en el Banco Mundial y ha asesorado a m\u00faltiples gobiernos y empresas. Es autor de 15 libros y m\u00e1s de 200 art\u00edculos acad\u00e9micos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Consejo de Alto Nivel para la Respuesta Estrat\u00e9gica de Pol\u00edtica Econ\u00f3mica y Financiera Internacional&#8230;<\/p>\n","protected":false},"author":8,"featured_media":75225,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[126],"tags":[26386,26412,26411,516,10952,13376],"class_list":["post-75224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-aranceles","tag-consejo-de-alto-nivel-para-la-respuesta-estrategica-de-politica-economica-y-financiera-internacional","tag-cpefi","tag-estados-unidos","tag-gabriel-boric","tag-presidente-boric"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conozca a los expertos que asesorar\u00e1n al Gobierno ante aranceles de Trump - Mundoacuicola<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoacuicola.cl\/new\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conozca a los expertos que asesorar\u00e1n al Gobierno ante aranceles de Trump - Mundoacuicola\" \/>\n<meta property=\"og:description\" content=\"El Consejo de Alto Nivel para la Respuesta Estrat\u00e9gica de Pol\u00edtica Econ\u00f3mica y Financiera Internacional...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoacuicola.cl\/new\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoacuicola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.acuicola\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-23T08:28:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T16:15:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2025\/04\/aranceles.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ricardo Alvarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:site\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Alvarez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\\\/\"},\"author\":{\"name\":\"Ricardo Alvarez\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\"},\"headline\":\"Conozca a los expertos que asesorar\u00e1n al Gobierno ante aranceles de Trump\",\"datePublished\":\"2025-04-23T08:28:47+00:00\",\"dateModified\":\"2025-08-29T16:15:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\\\/\"},\"wordCount\":1175,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/aranceles.jpg\",\"keywords\":[\"Aranceles\",\"Consejo de Alto Nivel para la Respuesta Estrat\u00e9gica de Pol\u00edtica Econ\u00f3mica y Financiera Internacional\",\"CPEFI\",\"Estados Unidos\",\"Gabriel Boric\",\"Presidente Boric\"],\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\\\/\",\"name\":\"Conozca a los expertos que asesorar\u00e1n al Gobierno ante aranceles de Trump - Mundoacuicola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/aranceles.jpg\",\"datePublished\":\"2025-04-23T08:28:47+00:00\",\"dateModified\":\"2025-08-29T16:15:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/aranceles.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/aranceles.jpg\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conozca a los expertos que asesorar\u00e1n al Gobierno ante aranceles de Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"name\":\"Mundoacuicola\",\"description\":\"Revista de Acuicultura.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\",\"name\":\"Mundoacuicola\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"width\":1252,\"height\":296,\"caption\":\"Mundoacuicola\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.acuicola\\\/\",\"https:\\\/\\\/x.com\\\/mundoacuicola\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-acuicola\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\",\"name\":\"Ricardo Alvarez\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/author\\\/ricardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conozca a los expertos que asesorar\u00e1n al Gobierno ante aranceles de Trump - Mundoacuicola","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoacuicola.cl\/new\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\/","og_locale":"es_ES","og_type":"article","og_title":"Conozca a los expertos que asesorar\u00e1n al Gobierno ante aranceles de Trump - Mundoacuicola","og_description":"El Consejo de Alto Nivel para la Respuesta Estrat\u00e9gica de Pol\u00edtica Econ\u00f3mica y Financiera Internacional...","og_url":"https:\/\/www.mundoacuicola.cl\/new\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\/","og_site_name":"Mundoacuicola","article_publisher":"https:\/\/www.facebook.com\/mundo.acuicola\/","article_published_time":"2025-04-23T08:28:47+00:00","article_modified_time":"2025-08-29T16:15:30+00:00","og_image":[{"width":750,"height":400,"url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2025\/04\/aranceles.jpg","type":"image\/jpeg"}],"author":"Ricardo Alvarez","twitter_card":"summary_large_image","twitter_creator":"@mundoacuicola","twitter_site":"@mundoacuicola","twitter_misc":{"Escrito por":"Ricardo Alvarez","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoacuicola.cl\/new\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\/#article","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\/"},"author":{"name":"Ricardo Alvarez","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd"},"headline":"Conozca a los expertos que asesorar\u00e1n al Gobierno ante aranceles de Trump","datePublished":"2025-04-23T08:28:47+00:00","dateModified":"2025-08-29T16:15:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\/"},"wordCount":1175,"publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2025\/04\/aranceles.jpg","keywords":["Aranceles","Consejo de Alto Nivel para la Respuesta Estrat\u00e9gica de Pol\u00edtica Econ\u00f3mica y Financiera Internacional","CPEFI","Estados Unidos","Gabriel Boric","Presidente Boric"],"articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoacuicola.cl\/new\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\/","url":"https:\/\/www.mundoacuicola.cl\/new\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\/","name":"Conozca a los expertos que asesorar\u00e1n al Gobierno ante aranceles de Trump - Mundoacuicola","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2025\/04\/aranceles.jpg","datePublished":"2025-04-23T08:28:47+00:00","dateModified":"2025-08-29T16:15:30+00:00","breadcrumb":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoacuicola.cl\/new\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\/#primaryimage","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2025\/04\/aranceles.jpg","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2025\/04\/aranceles.jpg","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoacuicola.cl\/new\/conozca-a-los-expertos-que-asesoraran-al-gobierno-ante-aranceles-de-trump\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoacuicola.cl\/new\/"},{"@type":"ListItem","position":2,"name":"Conozca a los expertos que asesorar\u00e1n al Gobierno ante aranceles de Trump"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoacuicola.cl\/new\/#website","url":"https:\/\/www.mundoacuicola.cl\/new\/","name":"Mundoacuicola","description":"Revista de Acuicultura.","publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoacuicola.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization","name":"Mundoacuicola","url":"https:\/\/www.mundoacuicola.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","width":1252,"height":296,"caption":"Mundoacuicola"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.acuicola\/","https:\/\/x.com\/mundoacuicola","https:\/\/www.linkedin.com\/in\/mundo-acuicola"]},{"@type":"Person","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd","name":"Ricardo Alvarez","url":"https:\/\/www.mundoacuicola.cl\/new\/author\/ricardo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/75224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/comments?post=75224"}],"version-history":[{"count":0,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/75224\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media\/75225"}],"wp:attachment":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media?parent=75224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/categories?post=75224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/tags?post=75224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}