{"id":75990,"date":"2025-05-20T18:12:22","date_gmt":"2025-05-20T22:12:22","guid":{"rendered":"https:\/\/www.mundoacuicola.cl\/new\/?p=75990"},"modified":"2025-05-22T13:31:10","modified_gmt":"2025-05-22T17:31:10","slug":"salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad","status":"publish","type":"post","link":"https:\/\/www.mundoacuicola.cl\/new\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\/","title":{"rendered":"SalmonChile impulsa econom\u00eda azul desde Ays\u00e9n con foco en sostenibilidad"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">En el marco de Blue Week Los Lagos, plataforma colaborativa que busca articular una visi\u00f3n pa\u00eds sobre econom\u00eda azul, se llev\u00f3 a cabo Blue Day Ays\u00e9n, jornada que reuni\u00f3 a m\u00e1s de 80 personas entre autoridades, expertos nacionales e internacionales, representantes gremiales y actores locales vinculados al desarrollo costero, para conversar sobre turismo, pesca, acuicultura y desarrollo local en armon\u00eda con la protecci\u00f3n de los oc\u00e9anos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Esta iniciativa fue impulsada por SalmonChile, en alianza con el Gobierno Regional de Ays\u00e9n, Patagonia Ocean Hub, K\u00ebtrawa, el Centro de Investigaci\u00f3n en Ecosistemas de la Patagonia (CIEP), el Instituto Tecnol\u00f3gico del Salm\u00f3n (INTESAL), y con el apoyo de Salmones Austral e Innovasea.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Durante la semana, organizaciones como UNESCO, CEPAL, Naciones Unidas, Ocean Visions, AmiChile y SalmonChile, junto a l\u00edderes sindicales y autoridades regionales, dialogaron sobre la urgencia de repensar el desarrollo del litoral chileno. Se destac\u00f3 la necesidad de poner en el centro la conservaci\u00f3n, las personas, la equidad territorial y la sostenibilidad de las actividades econ\u00f3micas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Durante la jornada en Blue Day Ays\u00e9n, se realizaron presentaciones claves a cargo del Dr. Felipe Tucca, coordinador de investigaci\u00f3n de INTESAL, quien abord\u00f3 la relaci\u00f3n entre salmonicultura, ciencia y salud de los oc\u00e9anos; Gustavo Aedo Urrutia, bi\u00f3logo marino del CIEP, con una mirada sobre los ecosistemas patag\u00f3nicos y su v\u00ednculo con el desarrollo local; y Emmanuele di Lorenzo, presidente y cofundador de Ocean Visions, junto a Leonardo Valenzuela P\u00e9rez, director de alianzas internacionales de la misma organizaci\u00f3n, quienes compartieron experiencias internacionales sobre soluciones oce\u00e1nicas basadas en ciencia para enfrentar los impactos del cambio clim\u00e1tico.<\/span><\/p>\n<h3><strong>Econom\u00eda oce\u00e1nica<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Fernando Camiruaga, representante de SalmonChile en la regi\u00f3n de Ays\u00e9n, expres\u00f3 su satisfacci\u00f3n con la jornada, destacando: \u201cBlue Day se enmarc\u00f3 en una conversaci\u00f3n que desde SalmonChile venimos impulsando hace tiempo: c\u00f3mo construimos desde el sur una econom\u00eda oce\u00e1nica que aproveche nuestra ventaja comparativa, escale soluciones locales con impacto global y combine producci\u00f3n sostenible, soberan\u00eda territorial y visi\u00f3n de futuro. Fue una excelente jornada, y agradecemos a Salmones Austral e Innovasea, no solo por ser los partners oficiales, sino tambi\u00e9n por su permanente compromiso con esta agenda\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Felipe Lisboa, cofundador de K\u00ebtrawa, afirm\u00f3: \u201cEstamos muy contentos con el ecosistema que se est\u00e1 gestando aqu\u00ed: por las oportunidades, el di\u00e1logo entre los distintos actores y el ambiente de colaboraci\u00f3n. Vemos con optimismo esta semilla que se est\u00e1 plantando para concretar proyectos que articulen a la pol\u00edtica, el mundo productivo, las comunidades y la ciencia.\u201d<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por su parte, Humberto Mar\u00edn, director de Corfo Ays\u00e9n, valor\u00f3 el encuentro se\u00f1alando que \u201choy d\u00eda nos juntamos en el marco de Blue Day a conversar sobre el desarrollo de la industria en la regi\u00f3n de Ays\u00e9n, pero particularmente sobre el medio ambiente y el cuidado de los oc\u00e9anos. Es tremendamente relevante que todos los actores vinculados al litoral podamos construir juntos desde el di\u00e1logo\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Finalmente, Margit Veloso, directora de CorpAys\u00e9n, destac\u00f3 el valor de estos espacios de encuentro indicando que \u201cal formarse estos conversatorios, realmente uno adquiere una visi\u00f3n diferente. Los acuerdos son los que nos permiten avanzar, en la medida que estemos todos dispuestos a converger en beneficio com\u00fan\u201d.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Blue Day Ays\u00e9n, SalmonChile promovi\u00f3 la econom\u00eda azul con foco en sostenibilidad, ciencia y desarrollo local junto a actores regionales e internacionales.<\/p>\n","protected":false},"author":8,"featured_media":75992,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[112],"tags":[143,775,10967,3203,591,22601,206,434,170,3489,967],"class_list":["post-75990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos","tag-acuicultura","tag-amichile","tag-desarrollo-local","tag-economia-azul","tag-intesal","tag-ketrawa","tag-pesca","tag-region-de-aysen","tag-salmonchile","tag-turismo","tag-unesco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SalmonChile impulsa econom\u00eda azul desde Ays\u00e9n con foco en sostenibilidad - Mundoacuicola<\/title>\n<meta name=\"description\" content=\"SalmonChile promovi\u00f3 en Blue Day Ays\u00e9n la econom\u00eda azul con enfoque en sostenibilidad, ciencia y desarrollo costero local.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoacuicola.cl\/new\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SalmonChile impulsa econom\u00eda azul desde Ays\u00e9n con foco en sostenibilidad - Mundoacuicola\" \/>\n<meta property=\"og:description\" content=\"SalmonChile promovi\u00f3 en Blue Day Ays\u00e9n la econom\u00eda azul con enfoque en sostenibilidad, ciencia y desarrollo costero local.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoacuicola.cl\/new\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoacuicola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.acuicola\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-20T22:12:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-22T17:31:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2025\/05\/BlueDay.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ricardo Alvarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:site\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Alvarez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\\\/\"},\"author\":{\"name\":\"Ricardo Alvarez\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\"},\"headline\":\"SalmonChile impulsa econom\u00eda azul desde Ays\u00e9n con foco en sostenibilidad\",\"datePublished\":\"2025-05-20T22:12:22+00:00\",\"dateModified\":\"2025-05-22T17:31:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\\\/\"},\"wordCount\":581,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/BlueDay.jpg\",\"keywords\":[\"Acuicultura\",\"AmiChile\",\"desarrollo local\",\"econom\u00eda azul\",\"Intesal\",\"K\u00ebtrawa\",\"Pesca\",\"Regi\u00f3n de Ays\u00e9n\",\"Salmonchile\",\"turismo\",\"Unesco\"],\"articleSection\":[\"Eventos\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\\\/\",\"name\":\"SalmonChile impulsa econom\u00eda azul desde Ays\u00e9n con foco en sostenibilidad - Mundoacuicola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/BlueDay.jpg\",\"datePublished\":\"2025-05-20T22:12:22+00:00\",\"dateModified\":\"2025-05-22T17:31:10+00:00\",\"description\":\"SalmonChile promovi\u00f3 en Blue Day Ays\u00e9n la econom\u00eda azul con enfoque en sostenibilidad, ciencia y desarrollo costero local.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/BlueDay.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/BlueDay.jpg\",\"width\":750,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SalmonChile impulsa econom\u00eda azul desde Ays\u00e9n con foco en sostenibilidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"name\":\"Mundoacuicola\",\"description\":\"Revista de Acuicultura.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\",\"name\":\"Mundoacuicola\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"width\":1252,\"height\":296,\"caption\":\"Mundoacuicola\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.acuicola\\\/\",\"https:\\\/\\\/x.com\\\/mundoacuicola\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-acuicola\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\",\"name\":\"Ricardo Alvarez\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/author\\\/ricardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SalmonChile impulsa econom\u00eda azul desde Ays\u00e9n con foco en sostenibilidad - Mundoacuicola","description":"SalmonChile promovi\u00f3 en Blue Day Ays\u00e9n la econom\u00eda azul con enfoque en sostenibilidad, ciencia y desarrollo costero local.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoacuicola.cl\/new\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\/","og_locale":"es_ES","og_type":"article","og_title":"SalmonChile impulsa econom\u00eda azul desde Ays\u00e9n con foco en sostenibilidad - Mundoacuicola","og_description":"SalmonChile promovi\u00f3 en Blue Day Ays\u00e9n la econom\u00eda azul con enfoque en sostenibilidad, ciencia y desarrollo costero local.","og_url":"https:\/\/www.mundoacuicola.cl\/new\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\/","og_site_name":"Mundoacuicola","article_publisher":"https:\/\/www.facebook.com\/mundo.acuicola\/","article_published_time":"2025-05-20T22:12:22+00:00","article_modified_time":"2025-05-22T17:31:10+00:00","og_image":[{"width":750,"height":400,"url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2025\/05\/BlueDay.jpg","type":"image\/jpeg"}],"author":"Ricardo Alvarez","twitter_card":"summary_large_image","twitter_creator":"@mundoacuicola","twitter_site":"@mundoacuicola","twitter_misc":{"Escrito por":"Ricardo Alvarez","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoacuicola.cl\/new\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\/#article","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\/"},"author":{"name":"Ricardo Alvarez","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd"},"headline":"SalmonChile impulsa econom\u00eda azul desde Ays\u00e9n con foco en sostenibilidad","datePublished":"2025-05-20T22:12:22+00:00","dateModified":"2025-05-22T17:31:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\/"},"wordCount":581,"publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2025\/05\/BlueDay.jpg","keywords":["Acuicultura","AmiChile","desarrollo local","econom\u00eda azul","Intesal","K\u00ebtrawa","Pesca","Regi\u00f3n de Ays\u00e9n","Salmonchile","turismo","Unesco"],"articleSection":["Eventos"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoacuicola.cl\/new\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\/","url":"https:\/\/www.mundoacuicola.cl\/new\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\/","name":"SalmonChile impulsa econom\u00eda azul desde Ays\u00e9n con foco en sostenibilidad - Mundoacuicola","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2025\/05\/BlueDay.jpg","datePublished":"2025-05-20T22:12:22+00:00","dateModified":"2025-05-22T17:31:10+00:00","description":"SalmonChile promovi\u00f3 en Blue Day Ays\u00e9n la econom\u00eda azul con enfoque en sostenibilidad, ciencia y desarrollo costero local.","breadcrumb":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoacuicola.cl\/new\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\/#primaryimage","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2025\/05\/BlueDay.jpg","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2025\/05\/BlueDay.jpg","width":750,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoacuicola.cl\/new\/salmonchile-impulsa-economia-azul-desde-aysen-con-foco-en-sostenibilidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoacuicola.cl\/new\/"},{"@type":"ListItem","position":2,"name":"SalmonChile impulsa econom\u00eda azul desde Ays\u00e9n con foco en sostenibilidad"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoacuicola.cl\/new\/#website","url":"https:\/\/www.mundoacuicola.cl\/new\/","name":"Mundoacuicola","description":"Revista de Acuicultura.","publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoacuicola.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization","name":"Mundoacuicola","url":"https:\/\/www.mundoacuicola.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","width":1252,"height":296,"caption":"Mundoacuicola"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.acuicola\/","https:\/\/x.com\/mundoacuicola","https:\/\/www.linkedin.com\/in\/mundo-acuicola"]},{"@type":"Person","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd","name":"Ricardo Alvarez","url":"https:\/\/www.mundoacuicola.cl\/new\/author\/ricardo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/75990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/comments?post=75990"}],"version-history":[{"count":0,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/75990\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media\/75992"}],"wp:attachment":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media?parent=75990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/categories?post=75990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/tags?post=75990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}