{"id":87790,"date":"2026-04-14T11:05:15","date_gmt":"2026-04-14T15:05:15","guid":{"rendered":"https:\/\/www.mundoacuicola.cl\/new\/?p=87790"},"modified":"2026-04-15T17:09:47","modified_gmt":"2026-04-15T21:09:47","slug":"proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte","status":"publish","type":"post","link":"https:\/\/www.mundoacuicola.cl\/new\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\/","title":{"rendered":"Proyecto AcuyMinAgro de la UCN articula acuicultura, miner\u00eda y agricultura en el norte"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">El trabajo que la Universidad Cat\u00f3lica del Norte, a trav\u00e9s del proyecto AcuyMinAgro, realiza en las caletas del norte grande de Chile evidencia un aspecto central para el futuro de la acuicultura a peque\u00f1a escala: su desarrollo no depende \u00fanicamente de conocimientos t\u00e9cnicos, sino tambi\u00e9n de las din\u00e1micas sociales y culturales propias de cada territorio.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En este escenario, el proyecto aborda los desaf\u00edos en la diversificaci\u00f3n econ\u00f3mica y la producci\u00f3n sustentable de alimentos, promoviendo actividades como la acuicultura y la agricultura desde una perspectiva centrada en el territorio y sus comunidades, especialmente en zonas marcadas por la escasez de agua. Bajo esta premisa, la Universidad Cat\u00f3lica del Norte, a trav\u00e9s del proyecto AcuyMinAgro y con el respaldo de Minera BHP, ha llevado a cabo un intenso trabajo en diversas zonas del norte grande, orientado a fortalecer el v\u00ednculo con comunidades del borde costero y avanzar en soluciones productivas pertinentes a su realidad.<\/span><\/p>\n<h3><strong>Conocimiento ecol\u00f3gico local<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">En este contexto, el equipo realiz\u00f3 en distintas caletas de la regi\u00f3n nortina talleres participativos, centrados en el levantamiento del conocimiento ecol\u00f3gico local. Estas instancias permitieron que pescadores y pescadoras identificaran zonas con potencial para el cultivo de osti\u00f3n, as\u00ed como relevar los principales recursos presentes en su entorno, complementando su experiencia en el mar con herramientas t\u00e9cnicas que apoyan la toma de decisiones.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Constantino Villarroel R\u00edos, soci\u00f3logo del proyecto, enfatiz\u00f3 en que la acuicultura conlleva por s\u00ed misma un fuerte componente social, en donde \u2018\u2019la transferencia tecnol\u00f3gica en acuicultura a peque\u00f1a escala no es solo un desaf\u00edo t\u00e9cnico, sino que tiene un profundo arraigo social y cultural. Si no existen condiciones de organizaci\u00f3n, confianza y cohesi\u00f3n, lo cual llamamos capital social, estos procesos enfrentan dificultades para sostenerse en el tiempo. El desaf\u00edo es adaptar la transferencia tecnol\u00f3gica a las condiciones sociales y culturales de cada comunidad.\u201d<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En los talleres participaron el Sindicato de Buzos y Ramos Afines de Taltal, el Sindicato de Constituci\u00f3n y el Sindicato de Trabajadores Independientes de Buzos, Mariscadores y Ramos Afines de Caleta Cifuncho, con lo cual se generaron espacios de di\u00e1logo, donde el conocimiento del territorio se pone en valor como un componente fundamental en el desarrollo de nuevas actividades productivas.<\/span><\/p>\n<h3><strong>Desarrollo acu\u00edcola y agr\u00edcola<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">En paralelo, el equipo sostuvo una reuni\u00f3n con representantes del \u00e1rea de comunidades de Minera Las Cenizas, instancia en la que particip\u00f3 el Dr. Jes\u00fas L\u00f3pez Carvallo, director del proyecto, acompa\u00f1ado por la decana de la Facultad de Ciencias del Mar de la Universidad Cat\u00f3lica del Norte, Niris Cort\u00e9s Pizarro. Dicho encuentro permiti\u00f3 abordar oportunidades de colaboraci\u00f3n orientadas a fortalecer el trabajo con la comunidad de Caleta Cifuncho, especialmente en iniciativas vinculadas al desarrollo acu\u00edcola y agr\u00edcola en conjunto con el sindicato local.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Asimismo, se concret\u00f3 la entrega de semillas a distintas organizaciones, acci\u00f3n que busca potenciar sus capacidades productivas. En total, se distribuyeron <strong>57.000 semillas, considerando osti\u00f3n y ostra japonesa<\/strong>, beneficiando a comunidades de Caleta Cifuncho, Paposo y Constituci\u00f3n, transform\u00e1ndose en un avance concreto para la diversificaci\u00f3n de sus actividades econ\u00f3micas.<\/span><\/p>\n<h3><strong>Valor de la participaci\u00f3n femenina en la acuicultura nortina<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Uno de los aspectos que destaca en este trabajo en terreno es la activa participaci\u00f3n de mujeres en las distintas actividades desarrolladas, especialmente en Caleta Paposo. Su presencia no solo evidencia un proceso de incorporaci\u00f3n creciente al rubro acu\u00edcola, sino que tambi\u00e9n aporta nuevas din\u00e1micas al interior de las organizaciones.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u2019\u2019En nuestra experiencia hemos visto que las mujeres aportan valiosas capacidades para la consolidaci\u00f3n de iniciativas productivas sostenibles, tales como la organizaci\u00f3n comunitaria y la constancia en los procesos de cultivo y con una fuerte orientaci\u00f3n al trabajo colaborativo\u2019\u2019, se\u00f1al\u00f3 el Dr. L\u00f3pez.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La presencia activa de mujeres ha fortalecido el trabajo colectivo en las organizaciones, cre\u00e1ndose espacios m\u00e1s cohesionados y comprometidos con el desarrollo de iniciativas productivas.\u00a0 En este escenario, la decana de la Facultad de Ciencias del Mar destac\u00f3 la relevancia de la participaci\u00f3n femenina y se\u00f1al\u00f3 \u2018\u2019las mujeres est\u00e9n tomando roles activos en las caletas de pescadores es muy valioso, ellas han estado hist\u00f3ricamente en las actividades, pero invisibilizadas, entonces ese paso que han dado ellas hoy en estar siendo\u00a0<\/span><span style=\"font-weight: 400;\">visibles, valoradas por sus propios pares es muy importante y nosotros como facultad por supuesto apoyamos este tipo de iniciativas\u2019\u2019.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Con este trabajo, AcuyMinAgro sigue fortaleciendo su presencia en el territorio, apostando por una acuicultura que se construye desde el di\u00e1logo entre la ciencia y la experiencia de las comunidades. Un enfoque que hoy se vuelve fundamental para enfrentar desaf\u00edos como la escasez h\u00eddrica y avanzar en la diversificaci\u00f3n productiva en las zonas costeras del norte del pa\u00eds.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El proyecto AcuyMinAgro, liderado por la Universidad Cat\u00f3lica del Norte con apoyo de BHP, fortalece la acuicultura, agricultura y trabajo territorial con comunidades costeras de Antofagasta mediante transferencia tecnol\u00f3gica y desarrollo productivo local.<\/p>\n","protected":false},"author":10,"featured_media":87793,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[1261,143,1291,8404,122,29293,2972,785,144,702],"class_list":["post-87790","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acuicultura","tag-acuicola","tag-acuicultura","tag-acuicultura-a-pequena-escala","tag-acuyminagro","tag-industria-acuicola","tag-minera-bhp","tag-ostion","tag-ostra-japonesa","tag-ucn","tag-universidad-catolica-del-norte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proyecto AcuyMinAgro de la UCN articula acuicultura, miner\u00eda y agricultura en el norte - Mundoacuicola<\/title>\n<meta name=\"description\" content=\"El proyecto AcuyMinAgro, liderado por la UCN con apoyo de BHP, fortalece la acuicultura, agricultura y trabajo territorial.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoacuicola.cl\/new\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proyecto AcuyMinAgro de la UCN articula acuicultura, miner\u00eda y agricultura en el norte - Mundoacuicola\" \/>\n<meta property=\"og:description\" content=\"El proyecto AcuyMinAgro, liderado por la UCN con apoyo de BHP, fortalece la acuicultura, agricultura y trabajo territorial.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoacuicola.cl\/new\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoacuicola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.acuicola\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-14T15:05:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T21:09:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/04\/AcuyMinAgroUCN-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mbarrueto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:site\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mbarrueto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\\\/\"},\"author\":{\"name\":\"mbarrueto\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/c00ffe389abb88bd9254653add139315\"},\"headline\":\"Proyecto AcuyMinAgro de la UCN articula acuicultura, miner\u00eda y agricultura en el norte\",\"datePublished\":\"2026-04-14T15:05:15+00:00\",\"dateModified\":\"2026-04-15T21:09:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\\\/\"},\"wordCount\":840,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/AcuyMinAgroUCN-1.jpg\",\"keywords\":[\"Acu\u00edcola\",\"Acuicultura\",\"acuicultura a peque\u00f1a escala\",\"AcuyMinAgro\",\"Industria Acu\u00edcola\",\"Minera BHP\",\"osti\u00f3n\",\"ostra japonesa\",\"UCN\",\"Universidad Cat\u00f3lica del Norte\"],\"articleSection\":[\"Acuicultura\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\\\/\",\"name\":\"Proyecto AcuyMinAgro de la UCN articula acuicultura, miner\u00eda y agricultura en el norte - Mundoacuicola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/AcuyMinAgroUCN-1.jpg\",\"datePublished\":\"2026-04-14T15:05:15+00:00\",\"dateModified\":\"2026-04-15T21:09:47+00:00\",\"description\":\"El proyecto AcuyMinAgro, liderado por la UCN con apoyo de BHP, fortalece la acuicultura, agricultura y trabajo territorial.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/AcuyMinAgroUCN-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/AcuyMinAgroUCN-1.jpg\",\"width\":1200,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyecto AcuyMinAgro de la UCN articula acuicultura, miner\u00eda y agricultura en el norte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"name\":\"Mundoacuicola\",\"description\":\"Revista de Acuicultura.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\",\"name\":\"Mundoacuicola\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"width\":1252,\"height\":296,\"caption\":\"Mundoacuicola\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.acuicola\\\/\",\"https:\\\/\\\/x.com\\\/mundoacuicola\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-acuicola\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/c00ffe389abb88bd9254653add139315\",\"name\":\"mbarrueto\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/author\\\/mbarrueto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proyecto AcuyMinAgro de la UCN articula acuicultura, miner\u00eda y agricultura en el norte - Mundoacuicola","description":"El proyecto AcuyMinAgro, liderado por la UCN con apoyo de BHP, fortalece la acuicultura, agricultura y trabajo territorial.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoacuicola.cl\/new\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\/","og_locale":"es_ES","og_type":"article","og_title":"Proyecto AcuyMinAgro de la UCN articula acuicultura, miner\u00eda y agricultura en el norte - Mundoacuicola","og_description":"El proyecto AcuyMinAgro, liderado por la UCN con apoyo de BHP, fortalece la acuicultura, agricultura y trabajo territorial.","og_url":"https:\/\/www.mundoacuicola.cl\/new\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\/","og_site_name":"Mundoacuicola","article_publisher":"https:\/\/www.facebook.com\/mundo.acuicola\/","article_published_time":"2026-04-14T15:05:15+00:00","article_modified_time":"2026-04-15T21:09:47+00:00","og_image":[{"width":1200,"height":700,"url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/04\/AcuyMinAgroUCN-1.jpg","type":"image\/jpeg"}],"author":"mbarrueto","twitter_card":"summary_large_image","twitter_creator":"@mundoacuicola","twitter_site":"@mundoacuicola","twitter_misc":{"Escrito por":"mbarrueto","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoacuicola.cl\/new\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\/#article","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\/"},"author":{"name":"mbarrueto","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/c00ffe389abb88bd9254653add139315"},"headline":"Proyecto AcuyMinAgro de la UCN articula acuicultura, miner\u00eda y agricultura en el norte","datePublished":"2026-04-14T15:05:15+00:00","dateModified":"2026-04-15T21:09:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\/"},"wordCount":840,"publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/04\/AcuyMinAgroUCN-1.jpg","keywords":["Acu\u00edcola","Acuicultura","acuicultura a peque\u00f1a escala","AcuyMinAgro","Industria Acu\u00edcola","Minera BHP","osti\u00f3n","ostra japonesa","UCN","Universidad Cat\u00f3lica del Norte"],"articleSection":["Acuicultura"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoacuicola.cl\/new\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\/","url":"https:\/\/www.mundoacuicola.cl\/new\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\/","name":"Proyecto AcuyMinAgro de la UCN articula acuicultura, miner\u00eda y agricultura en el norte - Mundoacuicola","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/04\/AcuyMinAgroUCN-1.jpg","datePublished":"2026-04-14T15:05:15+00:00","dateModified":"2026-04-15T21:09:47+00:00","description":"El proyecto AcuyMinAgro, liderado por la UCN con apoyo de BHP, fortalece la acuicultura, agricultura y trabajo territorial.","breadcrumb":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoacuicola.cl\/new\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\/#primaryimage","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/04\/AcuyMinAgroUCN-1.jpg","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/04\/AcuyMinAgroUCN-1.jpg","width":1200,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoacuicola.cl\/new\/proyecto-acuyminagro-de-la-ucn-articula-acuicultura-mineria-y-agricultura-en-el-norte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoacuicola.cl\/new\/"},{"@type":"ListItem","position":2,"name":"Proyecto AcuyMinAgro de la UCN articula acuicultura, miner\u00eda y agricultura en el norte"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoacuicola.cl\/new\/#website","url":"https:\/\/www.mundoacuicola.cl\/new\/","name":"Mundoacuicola","description":"Revista de Acuicultura.","publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoacuicola.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization","name":"Mundoacuicola","url":"https:\/\/www.mundoacuicola.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","width":1252,"height":296,"caption":"Mundoacuicola"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.acuicola\/","https:\/\/x.com\/mundoacuicola","https:\/\/www.linkedin.com\/in\/mundo-acuicola"]},{"@type":"Person","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/c00ffe389abb88bd9254653add139315","name":"mbarrueto","url":"https:\/\/www.mundoacuicola.cl\/new\/author\/mbarrueto\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/87790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/comments?post=87790"}],"version-history":[{"count":1,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/87790\/revisions"}],"predecessor-version":[{"id":87792,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/87790\/revisions\/87792"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media\/87793"}],"wp:attachment":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media?parent=87790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/categories?post=87790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/tags?post=87790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}