{"id":89138,"date":"2026-05-26T05:45:22","date_gmt":"2026-05-26T09:45:22","guid":{"rendered":"https:\/\/www.mundoacuicola.cl\/new\/?p=89138"},"modified":"2026-05-26T18:55:34","modified_gmt":"2026-05-26T22:55:34","slug":"presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon","status":"publish","type":"post","link":"https:\/\/www.mundoacuicola.cl\/new\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\/","title":{"rendered":"Presidente Kast firma decreto que instituye el D\u00eda del Trabajador del Salm\u00f3n"},"content":{"rendered":"<p data-end=\"&quot;&quot;&quot;&quot;&quot;&quot;610&quot;&quot;&quot;&quot;&quot;&quot;\" data-start=\"&quot;&quot;&quot;&quot;&quot;&quot;194&quot;&quot;&quot;&quot;&quot;&quot;\">El Presidente de la Rep\u00fablica, Jos\u00e9 Antonio Kast, encabez\u00f3 este lunes en el Palacio de La Moneda la ceremonia de firma del decreto supremo que instituye oficialmente el\u00a0<strong data-end=\"&quot;&quot;&quot;&quot;&quot;&quot;417&quot;&quot;&quot;&quot;&quot;&quot;\" data-start=\"&quot;&quot;&quot;&quot;&quot;&quot;363&quot;&quot;&quot;&quot;&quot;&quot;\">26 de mayo como el \u201cD\u00eda del Trabajador del Salm\u00f3n\u201d<\/strong>, reconocimiento que busca relevar el aporte de miles de trabajadores y trabajadoras que sostienen una de las principales actividades productivas del pa\u00eds.<\/p>\n<p data-end=\"&quot;&quot;&quot;&quot;&quot;&quot;956&quot;&quot;&quot;&quot;&quot;&quot;\" data-start=\"&quot;&quot;&quot;&quot;&quot;&quot;612&quot;&quot;&quot;&quot;&quot;&quot;\">En la actividad participaron el biministro de Econom\u00eda y Miner\u00eda, Daniel Mas; el ministro del Trabajo y Previsi\u00f3n Social, Tom\u00e1s Rau; el subsecretario de Pesca y Acuicultura, Osvaldo Urrutia; representantes de SalmonChile, Consejo del Salm\u00f3n, Armasur, empresas del sector y dirigentes sindicales salmoneros.<\/p>\n<p data-end=\"&quot;&quot;&quot;&quot;&quot;&quot;1191&quot;&quot;&quot;&quot;&quot;&quot;\" data-start=\"&quot;&quot;&quot;&quot;&quot;&quot;958&quot;&quot;&quot;&quot;&quot;&quot;\">Durante la ceremonia, el Mandatario destac\u00f3 el rol estrat\u00e9gico de la salmonicultura para el desarrollo econ\u00f3mico y territorial del pa\u00eds, subrayando el trabajo realizado por miles de personas en las regiones del sur y la zona austral.<\/p>\n<p data-end=\"&quot;&quot;&quot;&quot;&quot;&quot;1425&quot;&quot;&quot;&quot;&quot;&quot;\" data-start=\"&quot;&quot;&quot;&quot;&quot;&quot;1193&quot;&quot;&quot;&quot;&quot;&quot;\">La industria salmonera genera actualmente m\u00e1s de\u00a0<strong data-end=\"&quot;&quot;&quot;&quot;&quot;&quot;1882&quot;&quot;&quot;&quot;&quot;&quot;\" data-start=\"&quot;&quot;&quot;&quot;&quot;&quot;1842&quot;&quot;&quot;&quot;&quot;&quot;\">70 mil empleos directos e indirectos<\/strong>, especialmente en las regiones del sur del pa\u00eds, y constituye una de las principales actividades productivas nacionales. Asimismo, la salmonicultura se consolid\u00f3 en 2025 como el\u00a0<strong data-end=\"&quot;&quot;&quot;&quot;&quot;&quot;2123&quot;&quot;&quot;&quot;&quot;&quot;\" data-start=\"&quot;&quot;&quot;&quot;&quot;&quot;2061&quot;&quot;&quot;&quot;&quot;&quot;\">segundo producto de exportaci\u00f3n de Chile despu\u00e9s del cobre<\/strong>, alcanzando env\u00edos por\u00a0<strong data-end=\"&quot;&quot;&quot;&quot;&quot;&quot;2169&quot;&quot;&quot;&quot;&quot;&quot;\" data-start=\"&quot;&quot;&quot;&quot;&quot;&quot;2147&quot;&quot;&quot;&quot;&quot;&quot;\">US$ 6.549 millones<\/strong>\u00a0y posicionando al pa\u00eds como el segundo productor mundial de salm\u00f3nidos.<\/p>\n<p data-end=\"&quot;&quot;&quot;&quot;&quot;&quot;2642&quot;&quot;&quot;&quot;&quot;&quot;\" data-is-last-node=\"&quot;&quot;&quot;&quot;&quot;&quot;&quot;&quot;&quot;&quot;&quot;&quot;\" data-is-only-node=\"&quot;&quot;&quot;&quot;&quot;&quot;&quot;&quot;&quot;&quot;&quot;&quot;\" data-start=\"&quot;&quot;&quot;&quot;&quot;&quot;2281&quot;&quot;&quot;&quot;&quot;&quot;\">Con la firma del decreto, el Gobierno establece una conmemoraci\u00f3n permanente destinada a reconocer el trabajo de quienes participan en las distintas etapas de producci\u00f3n, procesamiento, transporte y comercializaci\u00f3n de la industria salmonera, reforzando el compromiso con el empleo, el crecimiento y el desarrollo regional.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La medida da cumplimiento al anuncio realizado por el Jefe de Estado durante el SalmonChile Summit 2026, efectuado el pasado 6 de mayo en la Regi\u00f3n de Los Lagos, instancia donde comprometi\u00f3 avanzar en una conmemoraci\u00f3n oficial para reconocer a los trabajadores del sector y su aporte a la defensa de las fuentes laborales.<\/p>\n","protected":false},"author":10,"featured_media":89139,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[26061,2907,26876,184,2273,197],"class_list":["post-89138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salmonicultura","tag-dia-del-trabajador-del-salmon","tag-industria-salmonera","tag-jose-antonio-kast","tag-salmon","tag-salmon-chileno","tag-salmonicultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presidente Kast firma decreto que instituye el D\u00eda del Trabajador del Salm\u00f3n - Mundoacuicola<\/title>\n<meta name=\"description\" content=\"La conmemoraci\u00f3n oficial reconoce a los trabajadores del sector y su aporte a la defensa de las fuentes laborales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoacuicola.cl\/new\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presidente Kast firma decreto que instituye el D\u00eda del Trabajador del Salm\u00f3n - Mundoacuicola\" \/>\n<meta property=\"og:description\" content=\"La conmemoraci\u00f3n oficial reconoce a los trabajadores del sector y su aporte a la defensa de las fuentes laborales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoacuicola.cl\/new\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoacuicola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.acuicola\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-26T09:45:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-26T22:55:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/05\/PresidenteKastDiaTrabajadorSalmonero.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mbarrueto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:site\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mbarrueto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\\\/\"},\"author\":{\"name\":\"mbarrueto\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/c00ffe389abb88bd9254653add139315\"},\"headline\":\"Presidente Kast firma decreto que instituye el D\u00eda del Trabajador del Salm\u00f3n\",\"datePublished\":\"2026-05-26T09:45:22+00:00\",\"dateModified\":\"2026-05-26T22:55:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\\\/\"},\"wordCount\":282,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/PresidenteKastDiaTrabajadorSalmonero.jpg\",\"keywords\":[\"D\u00eda del Trabajador del Salm\u00f3n\",\"Industria salmonera\",\"Jos\u00e9 Antonio Kast\",\"Salm\u00f3n\",\"Salm\u00f3n chileno\",\"salmonicultura\"],\"articleSection\":[\"Salmonicultura\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\\\/\",\"name\":\"Presidente Kast firma decreto que instituye el D\u00eda del Trabajador del Salm\u00f3n - Mundoacuicola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/PresidenteKastDiaTrabajadorSalmonero.jpg\",\"datePublished\":\"2026-05-26T09:45:22+00:00\",\"dateModified\":\"2026-05-26T22:55:34+00:00\",\"description\":\"La conmemoraci\u00f3n oficial reconoce a los trabajadores del sector y su aporte a la defensa de las fuentes laborales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/PresidenteKastDiaTrabajadorSalmonero.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/PresidenteKastDiaTrabajadorSalmonero.jpg\",\"width\":1200,\"height\":700},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presidente Kast firma decreto que instituye el D\u00eda del Trabajador del Salm\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"name\":\"Mundoacuicola\",\"description\":\"Revista de Acuicultura.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\",\"name\":\"Mundoacuicola\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"width\":1252,\"height\":296,\"caption\":\"Mundoacuicola\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.acuicola\\\/\",\"https:\\\/\\\/x.com\\\/mundoacuicola\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-acuicola\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/c00ffe389abb88bd9254653add139315\",\"name\":\"mbarrueto\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/author\\\/mbarrueto\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presidente Kast firma decreto que instituye el D\u00eda del Trabajador del Salm\u00f3n - Mundoacuicola","description":"La conmemoraci\u00f3n oficial reconoce a los trabajadores del sector y su aporte a la defensa de las fuentes laborales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoacuicola.cl\/new\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\/","og_locale":"es_ES","og_type":"article","og_title":"Presidente Kast firma decreto que instituye el D\u00eda del Trabajador del Salm\u00f3n - Mundoacuicola","og_description":"La conmemoraci\u00f3n oficial reconoce a los trabajadores del sector y su aporte a la defensa de las fuentes laborales.","og_url":"https:\/\/www.mundoacuicola.cl\/new\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\/","og_site_name":"Mundoacuicola","article_publisher":"https:\/\/www.facebook.com\/mundo.acuicola\/","article_published_time":"2026-05-26T09:45:22+00:00","article_modified_time":"2026-05-26T22:55:34+00:00","og_image":[{"width":1200,"height":700,"url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/05\/PresidenteKastDiaTrabajadorSalmonero.jpg","type":"image\/jpeg"}],"author":"mbarrueto","twitter_card":"summary_large_image","twitter_creator":"@mundoacuicola","twitter_site":"@mundoacuicola","twitter_misc":{"Escrito por":"mbarrueto","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoacuicola.cl\/new\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\/#article","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\/"},"author":{"name":"mbarrueto","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/c00ffe389abb88bd9254653add139315"},"headline":"Presidente Kast firma decreto que instituye el D\u00eda del Trabajador del Salm\u00f3n","datePublished":"2026-05-26T09:45:22+00:00","dateModified":"2026-05-26T22:55:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\/"},"wordCount":282,"publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/05\/PresidenteKastDiaTrabajadorSalmonero.jpg","keywords":["D\u00eda del Trabajador del Salm\u00f3n","Industria salmonera","Jos\u00e9 Antonio Kast","Salm\u00f3n","Salm\u00f3n chileno","salmonicultura"],"articleSection":["Salmonicultura"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoacuicola.cl\/new\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\/","url":"https:\/\/www.mundoacuicola.cl\/new\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\/","name":"Presidente Kast firma decreto que instituye el D\u00eda del Trabajador del Salm\u00f3n - Mundoacuicola","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/05\/PresidenteKastDiaTrabajadorSalmonero.jpg","datePublished":"2026-05-26T09:45:22+00:00","dateModified":"2026-05-26T22:55:34+00:00","description":"La conmemoraci\u00f3n oficial reconoce a los trabajadores del sector y su aporte a la defensa de las fuentes laborales.","breadcrumb":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoacuicola.cl\/new\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\/#primaryimage","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/05\/PresidenteKastDiaTrabajadorSalmonero.jpg","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/05\/PresidenteKastDiaTrabajadorSalmonero.jpg","width":1200,"height":700},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoacuicola.cl\/new\/presidente-kast-firma-decreto-que-instituye-el-dia-del-trabajador-del-salmon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoacuicola.cl\/new\/"},{"@type":"ListItem","position":2,"name":"Presidente Kast firma decreto que instituye el D\u00eda del Trabajador del Salm\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoacuicola.cl\/new\/#website","url":"https:\/\/www.mundoacuicola.cl\/new\/","name":"Mundoacuicola","description":"Revista de Acuicultura.","publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoacuicola.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization","name":"Mundoacuicola","url":"https:\/\/www.mundoacuicola.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","width":1252,"height":296,"caption":"Mundoacuicola"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.acuicola\/","https:\/\/x.com\/mundoacuicola","https:\/\/www.linkedin.com\/in\/mundo-acuicola"]},{"@type":"Person","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/c00ffe389abb88bd9254653add139315","name":"mbarrueto","url":"https:\/\/www.mundoacuicola.cl\/new\/author\/mbarrueto\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/89138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/comments?post=89138"}],"version-history":[{"count":1,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/89138\/revisions"}],"predecessor-version":[{"id":89140,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/89138\/revisions\/89140"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media\/89139"}],"wp:attachment":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media?parent=89138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/categories?post=89138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/tags?post=89138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}