{"id":89361,"date":"2026-06-01T17:36:08","date_gmt":"2026-06-01T21:36:08","guid":{"rendered":"https:\/\/www.mundoacuicola.cl\/new\/?p=89361"},"modified":"2026-06-02T18:31:33","modified_gmt":"2026-06-02T22:31:33","slug":"subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos","status":"publish","type":"post","link":"https:\/\/www.mundoacuicola.cl\/new\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\/","title":{"rendered":"Subsecretario Urrutia compromete certezas para la acuicultura y llama a acercar el salm\u00f3n a los hogares chilenos"},"content":{"rendered":"<p class=\"isSelectedEnd\">La necesidad de fortalecer las condiciones que permitan proyectar el desarrollo de la pesca y la acuicultura en Chile, junto con promover un mayor consumo de productos del mar entre la poblaci\u00f3n, fueron algunos de los principales mensajes planteados por el subsecretario de Pesca y Acuicultura, Osvaldo Urrutia, durante su participaci\u00f3n en la conmemoraci\u00f3n de los 50 a\u00f1os de la salmonicultura chilena, realizada en Puerto Montt y organizada por Mundo Acu\u00edcola.<\/p>\n<p class=\"isSelectedEnd\">La autoridad particip\u00f3 en el panel \u201cPasado, presente y futuro de la salmonicultura\u201d, instancia en la que abord\u00f3 la evoluci\u00f3n del rol p\u00fablico durante las \u00faltimas cinco d\u00e9cadas, los desaf\u00edos regulatorios que enfrenta la actividad y la importancia de fortalecer la colaboraci\u00f3n entre el Estado y el sector productivo para impulsar el desarrollo de la acuicultura nacional.<\/p>\n<h2>El desaf\u00edo de modernizar la regulaci\u00f3n<\/h2>\n<p class=\"isSelectedEnd\">Consultado respecto a la evoluci\u00f3n que ha tenido el rol del Estado durante los \u00faltimos 50 a\u00f1os de salmonicultura, Urrutia sostuvo que la regulaci\u00f3n suele avanzar a un ritmo distinto al de las actividades productivas, debido a la complejidad de los marcos normativos y administrativos que rigen al aparato p\u00fablico.<\/p>\n<p class=\"isSelectedEnd\">En ese contexto, explic\u00f3 que uno de los principales desaf\u00edos es generar condiciones que permitan mejorar la eficiencia regulatoria sin descuidar los est\u00e1ndares sanitarios y ambientales que exige la actividad. \u201cEste gobierno, con las herramientas que tenemos, quiere avanzar decisivamente para facilitar que estos sectores productivos puedan producir m\u00e1s y mejor\u201d, se\u00f1al\u00f3.<\/p>\n<p class=\"isSelectedEnd\">La autoridad agreg\u00f3 que actualmente Subpesca trabaja tanto en optimizar procedimientos existentes como en impulsar cambios regulatorios orientados a mejorar el funcionamiento del sector. \u201cQueremos trabajar en esos dos niveles: mejorar el marco regulatorio, pero adem\u00e1s optimizarlo de manera ojal\u00e1 lo m\u00e1s eficiente posible\u201d, indic\u00f3.<\/p>\n<p class=\"isSelectedEnd\">Si bien durante su intervenci\u00f3n no abord\u00f3 espec\u00edficamente la Ley Lafkenche, sus planteamientos se produjeron en un contexto donde diversos actores de la industria han relevado la necesidad de avanzar en mecanismos que entreguen mayor certeza para el desarrollo de actividades productivas en el borde costero, particularmente en materias vinculadas a planificaci\u00f3n territorial, relocalizaciones y uso de espacios mar\u00edtimos.<\/p>\n<h2>El rol de Subpesca y la articulaci\u00f3n p\u00fablico-privada<\/h2>\n<p class=\"isSelectedEnd\">Durante el panel, Urrutia destac\u00f3 que uno de los principales desaf\u00edos de la Subsecretar\u00eda de Pesca y Acuicultura es coordinar la acci\u00f3n de m\u00faltiples organismos p\u00fablicos vinculados a la regulaci\u00f3n de la actividad, resguardando al mismo tiempo el patrimonio sanitario y ambiental. \u201cCon la Subsecretar\u00eda de Pesca y Acuicultura, el Estado tiene el rol de garantizar el patrimonio sanitario y ambiental con el que trabajamos\u201d, se\u00f1al\u00f3.<\/p>\n<p class=\"isSelectedEnd\">Asimismo, enfatiz\u00f3 la importancia de mantener una relaci\u00f3n permanente con los distintos actores del sector para recoger inquietudes, identificar oportunidades de mejora y promover soluciones que permitan avanzar hacia una acuicultura m\u00e1s eficiente y sostenible. \u201cTenemos una pol\u00edtica de puertas abiertas. Nos reunimos constantemente con todos los grupos, con industrias, con empresas y con privados para conocer sus inquietudes y generar mejoras tanto regulatorias como en el uso de nuevas tecnolog\u00edas\u201d, afirm\u00f3.<\/p>\n<p class=\"isSelectedEnd\">En esa l\u00ednea, destac\u00f3 iniciativas desarrolladas junto al sector productivo para fortalecer el monitoreo sanitario, disminuir el uso de antibi\u00f3ticos e incorporar nuevas herramientas tecnol\u00f3gicas orientadas a mejorar el desempe\u00f1o ambiental y productivo de los centros de cultivo.<\/p>\n<h2>Certezas para el futuro y m\u00e1s salm\u00f3n en la mesa de los chilenos<\/h2>\n<p class=\"isSelectedEnd\">Uno de los momentos m\u00e1s destacados de la conversaci\u00f3n se produjo durante la din\u00e1mica de cierre del panel, cuando los participantes fueron invitados a completar la frase: \u201cPara que la salmonicultura siga siendo un motor de orgullo y desarrollo para Chile en los pr\u00f3ximos 50 a\u00f1os, el compromiso que asumimos es&#8230;\u201d.<\/p>\n<p class=\"isSelectedEnd\">En su respuesta, Urrutia identific\u00f3 dos compromisos que, a su juicio, resultan fundamentales para el futuro del sector.<\/p>\n<p class=\"isSelectedEnd\">El primero dice relaci\u00f3n con la necesidad de entregar estabilidad y confianza a la actividad mediante condiciones regulatorias claras y predecibles. \u201cEl compromiso de Subpesca y de acuicultura es decididamente otorgar todas las certezas necesarias, jur\u00eddicas, legales y pol\u00edticas, para que este sector se pueda proyectar de manera estable y con confianza en los pr\u00f3ximos 50 a\u00f1os, de manera que contribuya a la productividad, al empleo y al desarrollo econ\u00f3mico y social de Chile\u201d, sostuvo.<\/p>\n<p class=\"isSelectedEnd\">El segundo compromiso estuvo vinculado a un desaf\u00edo que trasciende a la propia industria y que apunta a fortalecer el v\u00ednculo entre los chilenos y los productos del mar. \u201cOjal\u00e1 todos podamos seguir incentivando el consumo de salm\u00f3n chileno, de manera de acercar el salm\u00f3n a todos los hogares y que todos los chilenos se sientan parte\u201d, afirm\u00f3.<\/p>\n<p class=\"isSelectedEnd\">Para el subsecretario, una mayor presencia de estos alimentos en la dieta nacional no solo contribuir\u00eda a fortalecer la identidad mar\u00edtima del pa\u00eds, sino tambi\u00e9n a mejorar la calidad de vida de las personas. \u201cAs\u00ed tambi\u00e9n contribuir a una mejor nutrici\u00f3n, a una mejor salud, a una dieta equilibrada y en general a la salud de Chile\u201d, concluy\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante la conmemoraci\u00f3n de los 50 a\u00f1os de la salmonicultura chilena organizada por Mundo Acu\u00edcola en Puerto Montt, el subsecretario de Pesca y Acuicultura, Osvaldo Urrutia, destac\u00f3 la necesidad de modernizar la regulaci\u00f3n, fortalecer las certezas para la inversi\u00f3n y proyectar el desarrollo de la acuicultura nacional. La autoridad tambi\u00e9n llam\u00f3 a promover un mayor consumo de salm\u00f3n y productos del mar en Chile, relevando su aporte a la nutrici\u00f3n, el empleo y el desarrollo econ\u00f3mico y social del pa\u00eds.<\/p>\n","protected":false},"author":8,"featured_media":89369,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[29312,6936,17386,5953,7877,8357,9444,28871,772,18270,197,3477,307],"class_list":["post-89361","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salmonicultura","tag-50-anos-de-la-salmonicultura","tag-acuicultura-chilena","tag-certeza-juridica","tag-consumo-de-salmon","tag-desarrollo-productivo","tag-empleo","tag-innovacion-acuicola","tag-osvaldo-urrutia","tag-puerto-montt","tag-regulacion-acuicola","tag-salmonicultura","tag-sostenibilidad","tag-subpesca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Subsecretario Urrutia compromete certezas para la acuicultura y llama a acercar el salm\u00f3n a los hogares chilenos - Mundoacuicola<\/title>\n<meta name=\"description\" content=\"La autoridad estuvo en el panel \u201cPasado, presente y futuro de la salmonicultura\u201d, durante la Conmemoraci\u00f3n de los 50 a\u00f1os de la salmonicultura\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mundoacuicola.cl\/new\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Subsecretario Urrutia compromete certezas para la acuicultura y llama a acercar el salm\u00f3n a los hogares chilenos - Mundoacuicola\" \/>\n<meta property=\"og:description\" content=\"La autoridad estuvo en el panel \u201cPasado, presente y futuro de la salmonicultura\u201d, durante la Conmemoraci\u00f3n de los 50 a\u00f1os de la salmonicultura\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mundoacuicola.cl\/new\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\/\" \/>\n<meta property=\"og:site_name\" content=\"Mundoacuicola\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mundo.acuicola\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-01T21:36:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-02T22:31:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/06\/Subsecretario50anos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"732\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ricardo Alvarez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:site\" content=\"@mundoacuicola\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ricardo Alvarez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\\\/\"},\"author\":{\"name\":\"Ricardo Alvarez\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\"},\"headline\":\"Subsecretario Urrutia compromete certezas para la acuicultura y llama a acercar el salm\u00f3n a los hogares chilenos\",\"datePublished\":\"2026-06-01T21:36:08+00:00\",\"dateModified\":\"2026-06-02T22:31:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\\\/\"},\"wordCount\":878,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Subsecretario50anos.jpg\",\"keywords\":[\"50 a\u00f1os de la salmonicultura\",\"Acuicultura chilena\",\"certeza jur\u00eddica\",\"consumo de salm\u00f3n\",\"desarrollo productivo\",\"empleo\",\"innovaci\u00f3n acu\u00edcola\",\"Osvaldo Urrutia\",\"Puerto Montt\",\"regulaci\u00f3n acu\u00edcola\",\"salmonicultura\",\"sostenibilidad\",\"subpesca\"],\"articleSection\":[\"Salmonicultura\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\\\/\",\"name\":\"Subsecretario Urrutia compromete certezas para la acuicultura y llama a acercar el salm\u00f3n a los hogares chilenos - Mundoacuicola\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Subsecretario50anos.jpg\",\"datePublished\":\"2026-06-01T21:36:08+00:00\",\"dateModified\":\"2026-06-02T22:31:33+00:00\",\"description\":\"La autoridad estuvo en el panel \u201cPasado, presente y futuro de la salmonicultura\u201d, durante la Conmemoraci\u00f3n de los 50 a\u00f1os de la salmonicultura\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Subsecretario50anos.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/06\\\/Subsecretario50anos.jpg\",\"width\":1200,\"height\":732},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Subsecretario Urrutia compromete certezas para la acuicultura y llama a acercar el salm\u00f3n a los hogares chilenos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#website\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"name\":\"Mundoacuicola\",\"description\":\"Revista de Acuicultura.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#organization\",\"name\":\"Mundoacuicola\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"contentUrl\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-LOGO-Mundo-Acuicola-2026.png\",\"width\":1252,\"height\":296,\"caption\":\"Mundoacuicola\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mundo.acuicola\\\/\",\"https:\\\/\\\/x.com\\\/mundoacuicola\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/mundo-acuicola\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/#\\\/schema\\\/person\\\/52cfe7e461eb2d30484965350ee34bdd\",\"name\":\"Ricardo Alvarez\",\"url\":\"https:\\\/\\\/www.mundoacuicola.cl\\\/new\\\/author\\\/ricardo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Subsecretario Urrutia compromete certezas para la acuicultura y llama a acercar el salm\u00f3n a los hogares chilenos - Mundoacuicola","description":"La autoridad estuvo en el panel \u201cPasado, presente y futuro de la salmonicultura\u201d, durante la Conmemoraci\u00f3n de los 50 a\u00f1os de la salmonicultura","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mundoacuicola.cl\/new\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\/","og_locale":"es_ES","og_type":"article","og_title":"Subsecretario Urrutia compromete certezas para la acuicultura y llama a acercar el salm\u00f3n a los hogares chilenos - Mundoacuicola","og_description":"La autoridad estuvo en el panel \u201cPasado, presente y futuro de la salmonicultura\u201d, durante la Conmemoraci\u00f3n de los 50 a\u00f1os de la salmonicultura","og_url":"https:\/\/www.mundoacuicola.cl\/new\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\/","og_site_name":"Mundoacuicola","article_publisher":"https:\/\/www.facebook.com\/mundo.acuicola\/","article_published_time":"2026-06-01T21:36:08+00:00","article_modified_time":"2026-06-02T22:31:33+00:00","og_image":[{"width":1200,"height":732,"url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/06\/Subsecretario50anos.jpg","type":"image\/jpeg"}],"author":"Ricardo Alvarez","twitter_card":"summary_large_image","twitter_creator":"@mundoacuicola","twitter_site":"@mundoacuicola","twitter_misc":{"Escrito por":"Ricardo Alvarez","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mundoacuicola.cl\/new\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\/#article","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\/"},"author":{"name":"Ricardo Alvarez","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd"},"headline":"Subsecretario Urrutia compromete certezas para la acuicultura y llama a acercar el salm\u00f3n a los hogares chilenos","datePublished":"2026-06-01T21:36:08+00:00","dateModified":"2026-06-02T22:31:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\/"},"wordCount":878,"publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/06\/Subsecretario50anos.jpg","keywords":["50 a\u00f1os de la salmonicultura","Acuicultura chilena","certeza jur\u00eddica","consumo de salm\u00f3n","desarrollo productivo","empleo","innovaci\u00f3n acu\u00edcola","Osvaldo Urrutia","Puerto Montt","regulaci\u00f3n acu\u00edcola","salmonicultura","sostenibilidad","subpesca"],"articleSection":["Salmonicultura"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mundoacuicola.cl\/new\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\/","url":"https:\/\/www.mundoacuicola.cl\/new\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\/","name":"Subsecretario Urrutia compromete certezas para la acuicultura y llama a acercar el salm\u00f3n a los hogares chilenos - Mundoacuicola","isPartOf":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\/#primaryimage"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/06\/Subsecretario50anos.jpg","datePublished":"2026-06-01T21:36:08+00:00","dateModified":"2026-06-02T22:31:33+00:00","description":"La autoridad estuvo en el panel \u201cPasado, presente y futuro de la salmonicultura\u201d, durante la Conmemoraci\u00f3n de los 50 a\u00f1os de la salmonicultura","breadcrumb":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mundoacuicola.cl\/new\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\/#primaryimage","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/06\/Subsecretario50anos.jpg","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/06\/Subsecretario50anos.jpg","width":1200,"height":732},{"@type":"BreadcrumbList","@id":"https:\/\/www.mundoacuicola.cl\/new\/subsecretario-urrutia-compromete-certezas-para-la-acuicultura-y-llama-a-acercar-el-salmon-a-los-hogares-chilenos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.mundoacuicola.cl\/new\/"},{"@type":"ListItem","position":2,"name":"Subsecretario Urrutia compromete certezas para la acuicultura y llama a acercar el salm\u00f3n a los hogares chilenos"}]},{"@type":"WebSite","@id":"https:\/\/www.mundoacuicola.cl\/new\/#website","url":"https:\/\/www.mundoacuicola.cl\/new\/","name":"Mundoacuicola","description":"Revista de Acuicultura.","publisher":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mundoacuicola.cl\/new\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mundoacuicola.cl\/new\/#organization","name":"Mundoacuicola","url":"https:\/\/www.mundoacuicola.cl\/new\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/","url":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","contentUrl":"https:\/\/www.mundoacuicola.cl\/new\/wp-content\/uploads\/2026\/01\/cropped-LOGO-Mundo-Acuicola-2026.png","width":1252,"height":296,"caption":"Mundoacuicola"},"image":{"@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mundo.acuicola\/","https:\/\/x.com\/mundoacuicola","https:\/\/www.linkedin.com\/in\/mundo-acuicola"]},{"@type":"Person","@id":"https:\/\/www.mundoacuicola.cl\/new\/#\/schema\/person\/52cfe7e461eb2d30484965350ee34bdd","name":"Ricardo Alvarez","url":"https:\/\/www.mundoacuicola.cl\/new\/author\/ricardo\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/89361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/comments?post=89361"}],"version-history":[{"count":1,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/89361\/revisions"}],"predecessor-version":[{"id":89370,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/posts\/89361\/revisions\/89370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media\/89369"}],"wp:attachment":[{"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/media?parent=89361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/categories?post=89361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mundoacuicola.cl\/new\/wp-json\/wp\/v2\/tags?post=89361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}